{"id":249849,"date":"2025-01-23T17:15:18","date_gmt":"2025-01-23T16:15:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249849"},"modified":"2025-01-23T16:44:41","modified_gmt":"2025-01-23T15:44:41","slug":"sofia-a-casa-viene-accolta-dal-sindaco-greco-benvenuta-nuova-cittadina-di-castrolibero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sofia-a-casa-viene-accolta-dal-sindaco-greco-benvenuta-nuova-cittadina-di-castrolibero\/","title":{"rendered":"Sofia a casa viene accolta dal sindaco Greco: &#8220;Benvenuta nuova cittadina di Castrolibero&#8221;"},"content":{"rendered":"<div dir=\"auto\">CASTROLIBERO &#8211; La piccola Sofia questa mattina, dopo essere <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/neonata-rapita-cosenza-valeria-dimessa-dal-sacro-cuore-tra-sorrisi-e-voglia-di-serenita\" target=\"_blank\" rel=\"noopener\">uscita dalla clinica Sacro Cuore <\/a><\/strong>di Cosenza, \u00e8 stata accolta a<strong> casa Cavoto, a Castrolibero,<\/strong> tra palloncini, dolci e aria di festa. Sembra ormai lontano quell&#8217;incubo che l&#8217;ha vista lontana dai propri genitori per diverse ore dal momento in cui Rosa Vespa e Acqua Moses, entrando nella clinica Sacro Cuore di Cosenza, <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/neonata-rapita-la-polizia-sofia-vittima-casuale-in-casa-della-coppia-una-festa-castello-di-carta-crollato-subito\" target=\"_blank\" rel=\"noopener\">l&#8217;hanno rapita<\/a><\/strong> portandola a casa loro. Una folle vicenda che ha lasciato un trauma indelebile nella <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/la-mamma-di-sofia-sui-social-ringrazia-la-nostra-famiglia-ieri-si-stava-sgretolando-in-mille-pezzi\" target=\"_blank\" rel=\"noopener\">mamma Valeria<\/a><\/strong>, che ora si appella alla giustizia chiedendo che i due rapitori non escano pi\u00f9 dal carcere: &#8220;Non voglio p\u00f9 vedermeli davanti&#8221;. Intanto la piccola, di appena qualche giorno, ha ricevuto anche la visita del <strong>sindaco Orlandino Greco<\/strong> che ha immortalato il momento con una foto sui social: &#8220;La Famiglia Cavoto al completo. Benvenuta Sofia. Nuova Cittadina di Castrolibero&#8221;.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">I due coniugi indagati per il rapimento della neonata, Rosa e Acqua, si trovano al momento in carcere, lei a Castrovillari e lui a Cosenza. Si attende per domani l&#8217;esito dell&#8217;<strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/rosa-vespa-e-acqua-moses-domani-linterrogatorio-in-carcere-per-i-rapitori-di-sofia\" target=\"_blank\" rel=\"noopener\">interrogatorio in carcere<\/a><\/strong> per la coppia che dovr\u00e0 chiarire diversi aspetti di una vicenda che ha tenuto con il fiato sospeso non solo un&#8217;intera citt\u00e0 ma un intero Paese.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CASTROLIBERO &#8211; La piccola Sofia questa mattina, dopo essere uscita dalla clinica Sacro Cuore di Cosenza, \u00e8 stata accolta a casa Cavoto, a Castrolibero, tra palloncini, dolci e aria di festa. Sembra ormai lontano quell&#8217;incubo che l&#8217;ha vista lontana dai propri genitori per diverse ore dal momento in cui Rosa Vespa e Acqua Moses, entrando [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":249851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,564],"tags":[19],"class_list":["post-249849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-castrolibero","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249849"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/249851"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}