{"id":249969,"date":"2025-01-25T08:08:31","date_gmt":"2025-01-25T07:08:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249969"},"modified":"2025-01-25T12:02:40","modified_gmt":"2025-01-25T11:02:40","slug":"tenta-di-evitare-il-controllo-dei-carabinieri-arrestato-per-possesso-di-marijuana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tenta-di-evitare-il-controllo-dei-carabinieri-arrestato-per-possesso-di-marijuana\/","title":{"rendered":"Tenta di evitare il controllo dei carabinieri, arrestato per possesso di marijuana"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; I carabinieri hanno arrestato un giovane trovato in possesso di marijuana, gi\u00e0 suddivisa in dosi pronte per essere vendute, e di un bilancino di precisione. I militari entre percorrevano le strade del quartiere Arghill\u00e0 di Reggio Calabria, hanno notato un <strong>gruppo di giovani con comportamenti sospetti<\/strong> <strong>nei pressi del polo sanitario della zona.<\/strong> La loro presenza in un punto strategico e frequentato della citt\u00e0 ha insospettito i militari, che hanno deciso di intervenire e procedere a un controllo. Alla vista dell\u2019auto dell\u2019Arma, per\u00f2, <strong>il gruppo ha tentato di disperdersi, cercando di eludere il controllo<\/strong>. La prontezza e la tempestivit\u00e0 dei Carabinieri hanno per\u00f2 <strong>fatto s\u00ec che uno dei giovani venisse fermato in pochi istanti.<\/strong><\/p>\n<p>Sottoposto a perquisizione, il giovane \u00e8 stato trovato in possesso di quasi <strong>20 grammi di marijuana,<\/strong> gi\u00e0 suddivisa in dosi, pronte per essere immesse sul mercato dello spaccio. Durante il controllo, \u00e8 stato rinvenuto anche un bilancino di precisione, strumento che conferma la sua intenzione di vendere le sostanze stupefacenti. La situazione ha immediatamente sollecitato l\u2019intervento dei Carabinieri, che hanno proceduto all\u2019arresto del giovane e al sequestro della droga.<\/p>\n<p>Il giovane arrestato, con precedenti per reati legati alla droga, \u00e8 stato portato in caserma per le formalit\u00e0 di rito e successivamente trasferito presso il carcere di Reggio Calabria, dove \u00e8 a disposizione dell\u2019autorit\u00e0 giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; I carabinieri hanno arrestato un giovane trovato in possesso di marijuana, gi\u00e0 suddivisa in dosi pronte per essere vendute, e di un bilancino di precisione. I militari entre percorrevano le strade del quartiere Arghill\u00e0 di Reggio Calabria, hanno notato un gruppo di giovani con comportamenti sospetti nei pressi del polo sanitario della [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":248851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-249969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249969"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248851"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}