{"id":250103,"date":"2025-01-27T14:22:00","date_gmt":"2025-01-27T13:22:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=250103"},"modified":"2025-01-27T14:25:24","modified_gmt":"2025-01-27T13:25:24","slug":"rosacs-dopo-il-ritardo-si-era-convinta-di-essere-incinta-il-legale-mamma-e-sorella-distrutte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rosacs-dopo-il-ritardo-si-era-convinta-di-essere-incinta-il-legale-mamma-e-sorella-distrutte\/","title":{"rendered":"Rosa dopo il ritardo si era convinta di essere incinta. Il legale: &#8220;mamma e sorella distrutte&#8221;"},"content":{"rendered":"<p>(ANSA) &#8211; COSENZA, 27 GEN &#8211; &#8220;<strong>Nel mese di maggio 2024, a fronte dell&#8217;assenza di ciclo mestruale che si prolungava da due mesi, l&#8217;indagata si convinceva di essere rimasta incinta e di ci\u00f2 informava il marito<\/strong>, che era in procinto di partire per la Nigeria, a seguito della morte della madre; da questo momento la Vespa non cercava riscontri clinici a tale &#8216;autodiagnosi&#8217;, non recandosi da un ginecologo, ne sottoponendosi ad esami di routine (se non fittiziamente)&#8221;. \u00c8 quanto si riporta nell&#8217;ordinanza di convalida di <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/neonata-rapita-rosa-vespa-resta-in-carcere-e-scagiona-il-marito-ho-fatto-tutto-da-sola\" target=\"_blank\" rel=\"noopener\">arresto di Rosa Vespa<\/a><\/strong>, la donna di 51 anni, di Cosenza, che nel pomeriggio del 21 gennaio scorso ha rapito una neonata introducendosi all&#8217;interno della clinica Sacro Cuore di Cosenza.<\/p>\n<p>Con la donna c&#8217;era anche il <strong>marito Moses Omogo<\/strong> Chidiebere, il 43enne, dapprima arrestato e poi <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/neonata-rapita-scarcerato-il-marito-di-rosa-vespa-la-difesa-di-moses-mi-ha-mostrato-i-certificati-medici\" target=\"_blank\" rel=\"noopener\">rilasciato<\/a><\/strong> perch\u00e9 \u00e8 scritto nell&#8217;ordinanza: &#8220;A specifica domanda l&#8217;Omogo dichiarava che, sia in occasione delle visite durante la gravidanza che durante il parto, l<strong>a moglie aveva sempre detto che avrebbe dovuto aspettare fuori perch\u00e9 non era consentito l&#8217;accesso ad altre persone.<\/strong> Dopo il parto, inoltre, Omogo si preoccupava di chiedere alla moglie come avrebbe dovuto procedere per la registrazione della nascita del bambino, ottenendo in merito una serie di rassicurazioni da parte della Vespa che verosimilmente, approfittando della non perfetta conoscenza delle procedure burocratiche italiane da parte del marito, gli diceva che tale adempimento si sarebbe dovuto effettuare dopo le dimissioni del bambino, recandosi in Comune, affermando altres\u00ec che le aveva gi\u00e0 provveduto a firmare qualcosa subito dopo la nascita&#8221;.<\/p>\n<p>Attualmente Rosa Vespa resta in carcere a Castrovillari, dove nei prossimi giorni sar\u00e0 sottoposta ad una visita da parte di un medico nominato dall&#8217;avvocata della donna, Teresa Gallucci per valutarne<strong> lo stato mentale<\/strong>. &#8220;La<strong> famiglia Vespa<\/strong> &#8211; ha detto all&#8217;Ansa l&#8217;avvocata Gallucci &#8211; sta vivendo un doppio trauma, <strong>la sorella Marina e la madre sono distrutte,<\/strong> non solo dal punto di vista giudiziario, ma anche umano, perch\u00e9 tutti aspettavano l&#8217;arrivo di un bimbo in famiglia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ANSA) &#8211; COSENZA, 27 GEN &#8211; &#8220;Nel mese di maggio 2024, a fronte dell&#8217;assenza di ciclo mestruale che si prolungava da due mesi, l&#8217;indagata si convinceva di essere rimasta incinta e di ci\u00f2 informava il marito, che era in procinto di partire per la Nigeria, a seguito della morte della madre; da questo momento la [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":250043,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-250103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=250103"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/250043"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=250103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=250103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=250103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}