{"id":250163,"date":"2025-01-28T13:54:07","date_gmt":"2025-01-28T12:54:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=250163"},"modified":"2025-01-28T14:43:25","modified_gmt":"2025-01-28T13:43:25","slug":"la-mamma-della-piccola-sofia-si-affida-ad-un-legale-possibile-un-atto-integrativo-di-querela","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/la-mamma-della-piccola-sofia-si-affida-ad-un-legale-possibile-un-atto-integrativo-di-querela\/","title":{"rendered":"La mamma della piccola Sofia si affida ad un legale &#8220;possibile un atto integrativo di querela&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; Ancora scossa e sotto shock per quanto accaduto<a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/neonata-rapita-cosenza-valeria-dimessa-dal-sacro-cuore-tra-sorrisi-e-voglia-di-serenita\" target=\"_blank\" rel=\"noopener\"> Valeria<\/a>,<strong>\u00a0la mamma della piccola Sofia<\/strong>, rapita dalla clinica sacro Cuore di Cosenza da Rosa Vespa e ritrovata dalla polizia nel giro di poche ore, ha dato mandato ad un legale. Sar\u00e0 <strong>l&#8217;avvocato Chiara Penna<\/strong> a supportare la donna che \u00abha deciso, come \u00e8 suo diritto, <strong>di avvalersi di una difesa tecnica e di propri consulenti<\/strong>\u00bb.<\/p>\n<p>\u00ab<strong>La fiducia negli inquirenti \u00e8 massima<\/strong> &#8211; ha spiegato l&#8217;avvocato Penna evidenziando che &#8211; la nostra attivit\u00e0 \u00e8 di supporto e affiancamento rispetto a quella svolta dal pubblico ministero ed eventualmente di integrazione ad essa. \u00c8 anche possibile &#8211; conclude il legale della donna &#8211; che<strong> la signora Chiappetta proponga a breve un atto integrativo di querela<\/strong>, per portare a conoscenza dell&#8217;Autorit\u00e0 giudiziaria <strong>nuove circostanze meritevoli di indagine approfondita anche nei confronti di altri soggetti<\/strong>\u00bb. La famiglia vuole capire <strong>se davvero Rosa Vespa abbia fatto tutta da sola<\/strong> o sia<strong> stata aiutata da altre persone, magari in clinica<\/strong>. Il Gip di Cosenza, lo ricordiamo, ha confermato la custodia cautelare in carcere per il sequestro avvenuto marted\u00ec scorso della neonata, <strong>solo per la 51enne<\/strong>, disponendo invece la scarcerazione immediata per il <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/bambina-rapita-da-vespa-la-verita-di-moses-ha-ingannato-tutti-la-sorella-la-mamma-e-me\" target=\"_blank\" rel=\"noopener\">marito<\/a>, Moses Omogo Chidiebere che ha sempre dichiarato di essere allo scuro di tutto cos\u00ec come l&#8217;intera famiglia.<\/p>\n<p>Nell&#8217;ordinanza che ha portato alla scarcerazione, il gip Pingitore scrive: \u00abemerge un asimmetrico rapporto di coppia nel quale <strong>l\u2019Omogo si pone in una posizione di piena accondiscendenza e cieca fiducia nei confronti della Vespa<\/strong>, molto probabilmente anche perch\u00e8 rappresenta il <strong>suo unico punto di riferimento familiare e affettivo in Italia<\/strong>. Non irragionevole quindi il suo completo affidarsi alle parole della moglie la quale, consapevole della influenza esercitata sul compagno, ne approfittava, imbastendo, mese dopo mese, quella folle sceneggiata\u00bb. Ed ancora, si legge nell&#8217;ordinanza che \u00abSi potrebbe obiettare che a<strong>ppare impossibile che l\u2019Omogo non si sia mai avveduto del finto stato di\u00a0gravidanza\u00a0della moglie<\/strong> convivendo nella stessa abitazione e condividendo lo stesso letto. Ci\u00f2, tuttavia, era possibile in ragione della\u00a0<strong>effettiva trasformazione fisica<\/strong> subita dalla Vespa durante quei mesi, del tutto analoga a quella delle donne incinta\u00bb.<\/p>\n<p>\u00abL\u2019indagata era precipitata in quella che lei stessa descrive una <strong>situazione di forte disagio psicologico<\/strong> in cui, a 52 anni, si sentiva una <strong>donna a met\u00e0 perch\u00e9 non era riuscita a realizzare il suo sogno di avere una bella famiglia e dei figli\u00bb<\/strong>. Per Rosa Vespa, che si trova nel carcere di Castrovillari, il proprio legale <strong>ha chiesto una perizia psichiatrica <\/strong>per valutare lo stato mentale della donna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Ancora scossa e sotto shock per quanto accaduto Valeria,\u00a0la mamma della piccola Sofia, rapita dalla clinica sacro Cuore di Cosenza da Rosa Vespa e ritrovata dalla polizia nel giro di poche ore, ha dato mandato ad un legale. Sar\u00e0 l&#8217;avvocato Chiara Penna a supportare la donna che \u00abha deciso, come \u00e8 suo diritto, [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":250164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-250163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=250163"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/250164"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=250163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=250163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=250163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}