{"id":250417,"date":"2025-01-31T14:50:38","date_gmt":"2025-01-31T13:50:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=250417"},"modified":"2025-01-31T14:50:38","modified_gmt":"2025-01-31T13:50:38","slug":"lo-beccano-con-armi-clandestine-e-126mila-euro-in-casa-arrestato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lo-beccano-con-armi-clandestine-e-126mila-euro-in-casa-arrestato\/","title":{"rendered":"Lo beccano con armi clandestine e 126mila euro in casa: arrestato"},"content":{"rendered":"<p>VIBO VALENTIA- I finanzieri del Comando provinciale di Vibo Valentia, con il supporto di unit\u00e0 cinofila del Gruppo di Lamezia Terme, hanno effettuato una perquisizione domiciliare a Tropea, culminata con l&#8217;arresto di un soggetto per<strong> detenzione illegale di armi da fuoco<\/strong>, di cui una con matricola abrasa, e di munizioni. Nel corso delle operazioni, eseguite dal Nucleo di polizia economico finanziaria di Vibo, \u00e8 stata individuata, nascosta all&#8217;interno di un deposito adibito a ricovero attrezzi agricoli, <strong>una pistola calibro 7,65 con due caricatori e 10 munizion<\/strong>i. I militari hanno anche ritirato in via cautelare, una pistola a salve, una carabina ed un fucile da caccia cal. 16 e 71 cartucce. Nel corso della perquisizione sono state trovate e sequestrate banconote da 50 e 100 euro,<strong> per un totale di 126.000 euro<\/strong>. L&#8217;operazione si \u00e8 svolta sotto la guida del procuratore della Repubblica Camillo Falvo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA- I finanzieri del Comando provinciale di Vibo Valentia, con il supporto di unit\u00e0 cinofila del Gruppo di Lamezia Terme, hanno effettuato una perquisizione domiciliare a Tropea, culminata con l&#8217;arresto di un soggetto per detenzione illegale di armi da fuoco, di cui una con matricola abrasa, e di munizioni. Nel corso delle operazioni, eseguite [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":250418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-250417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=250417"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/250418"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=250417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=250417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=250417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}