{"id":250678,"date":"2025-02-04T17:30:39","date_gmt":"2025-02-04T16:30:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=250678"},"modified":"2025-02-04T15:28:52","modified_gmt":"2025-02-04T14:28:52","slug":"schiavonea-senza-acqua-e-riscaldamento-intervento-urgente-per-la-scuola-di-via-nizza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/schiavonea-senza-acqua-e-riscaldamento-intervento-urgente-per-la-scuola-di-via-nizza\/","title":{"rendered":"Schiavonea: senza acqua e riscaldamento, intervento urgente per la scuola di via Nizza"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; Situazione critica per la scuola elementare di via Nizza a Schiavonea, dove i <strong>bambini<\/strong> si trovano a <strong>fronteggiare gravi disagi a causa della mancanza di acqua e riscaldamento<\/strong>. Negli ultimi giorni, i <strong>genitori<\/strong> sono stati costretti a <strong>ritirare i figli prima del termine delle lezioni<\/strong>, poich\u00e9 l\u2019istituto non garantisce le condizioni minime per la frequenza. Il gruppo consiliare di Fratelli d\u2019Italia, su iniziativa della Consigliera comunale <strong>Daniela Romano<\/strong>, ha preso una posizione netta sulla vicenda, evidenziando la necessit\u00e0 di un intervento immediato da parte dell\u2019Amministrazione comunale. <strong>\u00abNon possiamo permettere che i bambini perdano ulteriori giorni di scuola<\/strong> \u2013 afferma Daniela Romano \u2013. Nei giorni scorsi sono stata personalmente presso la scuola per verificare la situazione e, gi\u00e0 a gennaio, grazie anche al mio intervento, una ditta inviata dal Comune era intervenuta per risolvere il problema ai termosifoni e alla rete idrica. Purtroppo, i disagi si sono ripresentati, a dimostrazione che servono soluzioni definitive e non interventi provvisori\u00bb.<\/p>\n<h4>Disagi e proteste dei genitori<\/h4>\n<p>Le segnalazioni dei genitori raccontano una situazione drammatica: <strong>bagni inaccessibili, cisterne vuote, aule fredde e stufette che causano continui blackout.<\/strong> Sebbene la scuola non sia stata ufficialmente chiusa, le maestre stanno contattando i genitori per far ritirare i bambini, non essendoci le condizioni per proseguire le attivit\u00e0 didattiche. \u00abLe famiglie sono esasperate e non possiamo restare indifferenti \u2013 sottolinea Romano \u2013. Bisogna intervenire subito per garantire il <strong>diritto allo studio<\/strong> e la <strong>sicurezza dei bambini<\/strong>. \u00c8 impensabile che nel 2025 ci siano ancora scuole in queste condizioni, simili a quelle del terzo mondo\u00bb.<\/p>\n<h4>Progetti in corso e soluzioni temporanee<\/h4>\n<p>La Consigliera Romano ha spiegato che per la scuola \u00e8 gi\u00e0 stato finanziato un progetto PINQUA, con lavori di riqualificazione iniziati nell\u2019estate 2024. Tuttavia, al momento gli <strong>interventi hanno riguardato solo l\u2019esterno, mentre all\u2019interno continuano a persistere gravi criticit\u00e0.<\/strong> \u00abNei mesi scorsi \u2013 aggiunge \u2013 non \u00e8 stato possibile trovare un immobile alternativo per ospitare i bambini durante i lavori. Questa difficolt\u00e0 ha rallentato le operazioni, ma non pu\u00f2 giustificare il mancato intervento su problemi cos\u00ec urgenti. Mi sono interfacciata con il vice sindaco Pistoia, che mi ha assicurato che la situazione \u00e8 sotto controllo, ma al momento i fatti dimostrano il contrario. Servono azioni concrete e tempestive\u00bb.<\/p>\n<h4>La posizione del gruppo consiliare FDI<\/h4>\n<p>Fratelli d\u2019Italia ribadisce l\u2019importanza di un impegno immediato da parte dell\u2019Amministrazione comunale per risolvere i problemi strutturali della scuola di via Nizza. \u00ab<strong>Non \u00e8 accettabile<\/strong> \u2013 conclude Romano \u2013 <strong>che<\/strong>, dopo sei anni di amministrazione e un\u2019ingente disponibilit\u00e0 di fondi, le<strong> scuole del territorio siano ancora impraticabili<\/strong>. \u00c8 ora di dare risposte ai cittadini e garantire ai bambini un\u2019istruzione in ambienti sicuri e dignitosi\u00bb.Il gruppo consiliare di Fratelli d\u2019Italia continuer\u00e0 a monitorare la situazione e a sollecitare interventi adeguati per rispondere alle esigenze della comunit\u00e0 scolastica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; Situazione critica per la scuola elementare di via Nizza a Schiavonea, dove i bambini si trovano a fronteggiare gravi disagi a causa della mancanza di acqua e riscaldamento. Negli ultimi giorni, i genitori sono stati costretti a ritirare i figli prima del termine delle lezioni, poich\u00e9 l\u2019istituto non garantisce le condizioni [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":250679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-250678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=250678"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/250679"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=250678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=250678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=250678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}