{"id":250852,"date":"2025-02-06T16:30:02","date_gmt":"2025-02-06T15:30:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=250852"},"modified":"2025-02-06T14:53:48","modified_gmt":"2025-02-06T13:53:48","slug":"san-giovanni-in-fiore-intesa-per-lutilizzo-dello-stadio-per-latterraggio-notturno-dellelisoccorso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/san-giovanni-in-fiore-intesa-per-lutilizzo-dello-stadio-per-latterraggio-notturno-dellelisoccorso\/","title":{"rendered":"San Giovanni in Fiore: intesa per l&#8217;utilizzo dello stadio per l&#8217;atterraggio notturno dell&#8217;Elisoccorso"},"content":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211; E&#8217; stato firmato il Protocollo d\u2019intesa con l&#8217;Azienda sanitaria provinciale di Cosenza, per l&#8217;utilizzo dello stadio comunale quale luogo per l&#8217;atterraggio dell&#8217;Elisoccorso, anche nelle ore notturne. \u00abCon il direttore generale dell&#8217;Asp di Cosenza abbiamo firmato l&#8217;intesa &#8211; spiega il sindaco Rosaria Succurro &#8211; per l&#8217;utilizzo dello stadio comunale per l&#8217;elisoccorso da parte di Elitaliana, il gestore degli elicotteri che ha sottoscritto l&#8217;Accordo. \u00c8 il primo passo per assicurare il servizio anche nelle ore notturne. Ma bisogna essere uniti per potenziare tutto l&#8217;ospedale\u00bb. \u00abQuesto voglio fare insieme alle associazioni, ai sindacati, a tutti i rappresentanti politici e ai cittadini\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-250855 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Firma-Protocollo-elisoccorso-san-giovanni-fiore.jpg\" alt=\"\" width=\"468\" height=\"290\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Firma-Protocollo-elisoccorso-san-giovanni-fiore.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Firma-Protocollo-elisoccorso-san-giovanni-fiore-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Firma-Protocollo-elisoccorso-san-giovanni-fiore-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Firma-Protocollo-elisoccorso-san-giovanni-fiore-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Firma-Protocollo-elisoccorso-san-giovanni-fiore-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Firma-Protocollo-elisoccorso-san-giovanni-fiore-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Firma-Protocollo-elisoccorso-san-giovanni-fiore-356x220.jpg 356w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211; E&#8217; stato firmato il Protocollo d\u2019intesa con l&#8217;Azienda sanitaria provinciale di Cosenza, per l&#8217;utilizzo dello stadio comunale quale luogo per l&#8217;atterraggio dell&#8217;Elisoccorso, anche nelle ore notturne. \u00abCon il direttore generale dell&#8217;Asp di Cosenza abbiamo firmato l&#8217;intesa &#8211; spiega il sindaco Rosaria Succurro &#8211; per l&#8217;utilizzo dello stadio comunale per [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":250854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-250852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=250852"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/250852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/250854"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=250852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=250852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=250852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}