{"id":251125,"date":"2025-02-08T20:23:29","date_gmt":"2025-02-08T19:23:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=251125"},"modified":"2025-02-08T20:30:40","modified_gmt":"2025-02-08T19:30:40","slug":"sospiro-di-sollievo-a-san-giovanni-in-fiore-luciano-marra-e-tornato-a-casa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sospiro-di-sollievo-a-san-giovanni-in-fiore-luciano-marra-e-tornato-a-casa\/","title":{"rendered":"Sospiro di sollievo a San Giovanni in Fiore. Luciano Marra \u00e8 tornato a casa"},"content":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211; Sono state<strong> ore di ansia e apprensione,<\/strong> ma per fortuna tutto si \u00e8 risolto per il meglio. <strong>Luciano Marra, il dipendente comunale<\/strong> <a href=\"https:\/\/quicosenza.it\/news\/provincia\/preoccupazione-a-san-giovanni-in-fiore-per-la-scomparsa-di-luciano-marra-ricerche-in-corso\" target=\"_blank\" rel=\"noopener\">scomparso ieri<\/a> a San Giovanni in Fiore \u00e8 tornato a casa sano e salvo. L&#8217;uomo, 56 anni, <strong>era stato visto l&#8217;ultima volta ieri mattina presto<\/strong> quando era uscito di casa ma senza fare pi\u00f9 ritorno.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FAccademiaKronosSgf%2Fposts%2Fpfbid0RxsReJ9jadZrgEhqhTtZ6Tf3qbb8WjmZ78ksm3KfNJALNS1frohBMDsP6ejX94kSl&amp;show_text=true&amp;width=500\" width=\"500\" height=\"485\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Dopo gli appelli da parte dei familiari, preoccupati a fornire qualsiasi informazione utile o segnalazioni (che avevano anche allertato i carabinieri che avevano avviato le ricerche insieme alla Protezione civile), la<strong> notizia pi\u00f9 bella \u00e8 stata data questo pomeriggio della nipote<\/strong> dell&#8217;uomo con un messaggio sui social, in cui avvisava tutti <strong>del rientro a casa dell&#8217;uomo in buone condizioni fisiche <\/strong>con un ringraziamento a quanti si sono spesi per le sue ricerche: \u00ab<em>volevamo informarvi che<strong> zio \u00e8 rientrato a casa<\/strong>.\u00a0Grazie di cuore a tutti per la vicinanza, l&#8217;affetto e il supporto dimostrato in questi due giorni \u00e9 stato davvero importante per noi<\/em><em>\u00bb.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211; Sono state ore di ansia e apprensione, ma per fortuna tutto si \u00e8 risolto per il meglio. Luciano Marra, il dipendente comunale scomparso ieri a San Giovanni in Fiore \u00e8 tornato a casa sano e salvo. L&#8217;uomo, 56 anni, era stato visto l&#8217;ultima volta ieri mattina presto quando era [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":251054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-251125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/251125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=251125"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/251125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/251054"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=251125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=251125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=251125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}