{"id":25141,"date":"2013-08-09T08:08:04","date_gmt":"2013-08-09T06:08:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=25141"},"modified":"2023-01-17T13:22:39","modified_gmt":"2023-01-17T12:22:39","slug":"10193-motopesca-affondato-naufraghi-soccorsi-da-un-altro-peschereccio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10193-motopesca-affondato-naufraghi-soccorsi-da-un-altro-peschereccio\/","title":{"rendered":"Motopesca affonda, naufraghi soccorsi da un altro peschereccio"},"content":{"rendered":"<p style=\"text-align: justify;\">BELMONTE CALABRO &#8211; Nel mare Tirreno, al largo di Belmonte Calabro e&#8217; <strong>affondato un motopesca<\/strong>, per cause in corso d&#8217;accertamento.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Le tre persone a bordo, il proprietario dell&#8217;imbarcazione e due marittimi, che erano finiti in mare, sono stati soccorsi da un altro motopesca di passaggio nella zona e condotti a riva. Le loro condizioni sono buone. L&#8217;Ufficio marittimo di Paola ha aperto un&#8217;inchiesta amministrativa per accertare le cause dell&#8217;affondamento del motopesca. E\u2019 giunta direttamente intorno alle 10.30 dal padre del Comandante del Motopesca Odissea, della Marineria di Vibo Valentia, la notizia che il figlio stava affondando con la propria unit\u00e0 da pesca a largo di Belmonte Calabro. Immediata l\u2019assunzione del coordinamento delle attivit\u00e0 di ricerca assunte dalla Sala Operativa della Guardia Costiera di Vibo Valentia Marina, che faceva convergere in zona tutte le unit\u00e0 impegnate in attivit\u00e0 di controllo in mare nell\u2019ambito dell\u2019Operazione Mare Sicuro, nonch\u00e9, oltre ad allertare il 5\u00b0M.R.S.C. della Direzione Marittima di Reggio Calabria e la Centrale Operativa del Comando Generale, predisponeva l\u2019uscita di una terza Motovedetta di soccorso di stanza nel Porto di Cetraro. Dopo circa 10 minuti, dall\u2019inizio delle ricerche, il Comandante del Motopesca informava telefonicamente la moglie di essere giunto a riva sulla spiaggia di Longobardi con gli altri due marittimi imbarcati sull\u2019Odissea. Tutti e tre erano stati avvistati in mare dal Motopesca \u201cSan Francesco di Paola\u201d, che li recuperava e li faceva sbarcare sulla spiaggia. Accertata la notizia, e presi diretti contatti con il Comandante del Motopesca, la Sala Operativa della Capitaneria di Porto di Vibo, faceva convergere sulla spiaggia di Longobardi le due pattuglie terrestri dell\u2019Ufficio Locale Marittimo di Paola e della Delegazione di Spiaggia di Amantea, che raggiungevano i naufraghi e verificato che gli stessi non avevano necessit\u00e0 di assistenza sanitaria, li conducevano presso gli uffici della Guardia Costiera di Amantea ove sarebbero stati raggiunti dai familiari. Da una prima ricostruzione sommaria, il motopesca, per cause ancora in fase di accertamento, \u00e8 affondato in pochissimi minuti mentre si trovava a circa sette km dalla costa a nord ovest della Zona di Tutela Biologica di Amantea, su un fondale di circa 400 metri. E\u2019 stata aperta un\u2019inchiesta amministrativa da parte dell\u2019Ufficio Locale Marittimo di Paola per accertare le cause dell\u2019affondamento del Motopesca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BELMONTE CALABRO &#8211; Nel mare Tirreno, al largo di Belmonte Calabro e&#8217; affondato un motopesca, per cause in corso d&#8217;accertamento.<\/p>\n","protected":false},"author":22,"featured_media":25142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-25141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=25141"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/25142"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=25141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=25141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=25141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}