{"id":251532,"date":"2025-02-13T08:58:05","date_gmt":"2025-02-13T07:58:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=251532"},"modified":"2025-02-13T10:00:30","modified_gmt":"2025-02-13T09:00:30","slug":"estorsioni-a-commercianti-e-imprenditori-tre-misure-cautelari-tra-castrovillari-e-cassano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/estorsioni-a-commercianti-e-imprenditori-tre-misure-cautelari-tra-castrovillari-e-cassano\/","title":{"rendered":"Estorsioni a commercianti e imprenditori, tre misure cautelari tra Castrovillari e Cassano"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211;\u00a0 La Squadra mobile di Cosenza e la Squadra di polizia giudiziaria del Commissariato di Castrovillari, dalle prime ore di oggi sono impegnate nell&#8217;esecuzione di tre misure cautelari nei confronti di <strong>altrettanti indagati accusati di estorsione<\/strong>, in alcuni casi rimasta allo stato di tentativo, aggravata dalle modalit\u00e0 mafiose. Le indagini si sono avvalse delle dichiarazioni delle <strong>vittime che hanno sporto denuncia<\/strong> e riconosciuto gli aguzzini segnalandoli alla Polizia.<\/p>\n<p>I tre soggetti sono stati <strong>portati in carcere<\/strong> e sono accusati di numerosi episodi di estorsione aggravati dalle modalit\u00e0 mafiose ai danni di titolari di esercizi commerciali e attivit\u00e0 imprenditoriali del settore agricolo e dell&#8217;assistenza medica dell&#8217;area della Sibaritide e del Pollino. I tre, sono <strong>soggetti noti alle forze dell&#8217;ordine<\/strong> e le investigazioni si sono sviluppate grazie anche ad attivit\u00e0 tecniche, servizi sul territorio e riscontri sul campo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211;\u00a0 La Squadra mobile di Cosenza e la Squadra di polizia giudiziaria del Commissariato di Castrovillari, dalle prime ore di oggi sono impegnate nell&#8217;esecuzione di tre misure cautelari nei confronti di altrettanti indagati accusati di estorsione, in alcuni casi rimasta allo stato di tentativo, aggravata dalle modalit\u00e0 mafiose. Le indagini si sono avvalse [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":251533,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-251532","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-provincia","tag-copertina","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/251532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=251532"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/251532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/251533"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=251532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=251532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=251532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}