{"id":251968,"date":"2025-02-19T12:30:36","date_gmt":"2025-02-19T11:30:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=251968"},"modified":"2026-07-09T16:12:26","modified_gmt":"2026-07-09T14:12:26","slug":"offese-jole-santelli-dopo-la-morte-condannata-la-docente-che-scrisse-evvai-una-mafiosa-in-meno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/offese-jole-santelli-dopo-la-morte-condannata-la-docente-che-scrisse-evvai-una-mafiosa-in-meno\/","title":{"rendered":"Offese Jole Santelli dopo la morte. Condannata la docente che scrisse \u00abevvai una mafiosa in meno\u00bb"},"content":{"rendered":"<p>GENOVA &#8211; Il Tribunale di Genova ha condannato per <strong>diffamazione aggravata tramite social network, <\/strong>la professoressa <strong>P. C.<\/strong>\u00a0<strong>a svolgere 12 ore settimanali<\/strong> presso un Associazione della citt\u00e0 ligure <strong>per la durata di 4 mesi.<\/strong> Questo il verdetto che mette fine al processo <strong>contro la docente del Liceo statale Pertini di Genova, che aveva offeso la memoria dell&#8217;ex Presidente<\/strong> della Regione Calabria Jole Santelli pubblicando a ottobre del 2021 un<strong><a href=\"https:\/\/quicosenza.it\/news\/calabria\/448710-rinviata-a-giudizio-la-prof-che-esulto-su-facebook-per-la-morte-della-santelli\" target=\"_blank\" rel=\"noopener\"> post offensivo<\/a> alla notizia della morte<\/strong>.<\/p>\n<p>La docente, con alle spalle anche una candidatura come consigliera comunale M5S alle amministrative 2017, aveva scritto su Facebook: \u00ab<strong><em>Evvai! Una mafiosa di meno\u00bb<\/em><\/strong>. Il post, dopo aver ricevuto decine di critiche anche da parte di genitori degli alunni, era stato in seguito rimosso. La docente, presente in udienza, ha rinnovato le scuse alle sorelle della Santelli<strong> riservandosi di scrivere una lettera a loro per le scuse formali<\/strong>.\u00a0Il Tribunale di Genova, Giudice monocratico Lovesio, <strong>ha fissato l\u2019udienza per il 15 ottobre 2025<\/strong> per verificare che la Castellaro abbia svolte le ore stabilite per la messa alla prova e valutare le <strong>richieste della parte civile da parte delle sorelle dell&#8217;ex Presidente Paola e Roberta<\/strong>, assistite dall&#8217;avvocato Sabrina Rondinelli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GENOVA &#8211; Il Tribunale di Genova ha condannato per diffamazione aggravata tramite social network, la professoressa P. C.\u00a0a svolgere 12 ore settimanali presso un Associazione della citt\u00e0 ligure per la durata di 4 mesi. Questo il verdetto che mette fine al processo contro la docente del Liceo statale Pertini di Genova, che aveva offeso la [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":149189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-251968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/251968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=251968"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/251968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/149189"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=251968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=251968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=251968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}