{"id":251974,"date":"2025-02-19T13:28:20","date_gmt":"2025-02-19T12:28:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=251974"},"modified":"2025-02-19T13:29:42","modified_gmt":"2025-02-19T12:29:42","slug":"la-proposta-una-metropolitana-leggera-per-unire-i-comuni-del-tirreno-e-collegarli-a-cosenza-e-allunical","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/la-proposta-una-metropolitana-leggera-per-unire-i-comuni-del-tirreno-e-collegarli-a-cosenza-e-allunical\/","title":{"rendered":"La proposta &#8211; Una metropolitana leggera per unire i comuni del Tirreno e collegarli a Cosenza e all&#8217;Unical"},"content":{"rendered":"<div dir=\"auto\">SAN LUCIDO (CS) &#8211; \u00abUna <strong>metropolitana leggera<\/strong> in grado di <strong>unire davvero i paesi del litorale tirrenico<\/strong>, e di unire<strong> il Tirreno Cosentino all&#8217;universit\u00e0 di Arcavacata e al capoluogo Cosentino<\/strong>, <strong>implementando anche il trasporto per e dall&#8217;aeroporto di Lamezia Terme<\/strong>. Un progetto ormai improrogabile e mai concretizzatosi negli anni\u00bb. A rilanciare l&#8217;idea di un mezzo di trasporto veloce di massa, anche in chiave turistica \u00e8 il sindaco di San Lucido Cosimo De Tommaso.<\/div>\n<h3 dir=\"auto\">\u00a0\u00abL&#8217;opera \u00e8 perfettamente realizzabile e sostenibile\u00bb<\/h3>\n<div dir=\"auto\">\u00abPu\u00f2 esser <strong>gratuita per i fruitori perch\u00e9 utilizzer\u00e0 le linee e l&#8217;impiantistica gi\u00e0 present<\/strong>e, serve &#8211; prosegue il primo cittadino &#8211; ad <strong>unire i territori, evitando in realt\u00e0 di isolare delle zone<\/strong>, anche dell&#8217;entroterra nepetino e della Riviera dei Cedri, che hanno difficolt\u00e0 ad usufruire del diritto alla mobilit\u00e0.\u00a0\u00a0Finora, alcuni fattori e delle diversit\u00e0 di veduta hanno rallentato l&#8217;iter, ma <strong>l&#8217;opera \u00e8 perfettamente realizzabile, risulta sostenibile dal punto di vista ambientale<\/strong>\u00a0e pu\u00f2 definitivamente rilanciare la costa tirrenica, il capoluogo bruzio e la Calabria tutta\u00bb.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Cosimo-De-Tommaso-Sindaco-San-Lucido.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-251975 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Cosimo-De-Tommaso-Sindaco-San-Lucido.jpg\" alt=\"Cosimo De Tommaso Sindaco San Lucido\" width=\"530\" height=\"353\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Cosimo-De-Tommaso-Sindaco-San-Lucido.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Cosimo-De-Tommaso-Sindaco-San-Lucido-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Cosimo-De-Tommaso-Sindaco-San-Lucido-768x511.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Cosimo-De-Tommaso-Sindaco-San-Lucido-631x420.jpg 631w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Cosimo-De-Tommaso-Sindaco-San-Lucido-150x100.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/02\/Cosimo-De-Tommaso-Sindaco-San-Lucido-696x464.jpg 696w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/a><\/div>\n<h3 dir=\"auto\">Sostegno di molti sindaci del territorio<\/h3>\n<div dir=\"auto\">De Tommaso prosegue: \u00abQuesta idea, <strong>gode gi\u00e0 del sostegno di molti sindaci del territorio<\/strong>, \u00e8 aperta a quanti vorranno sostenerla in un tavolo istituzionale con la Regione Calabria e la Provincia di Cosenza in prima battuta, ed \u00e8 priva di colori politici e di primogeniture. La realizzazione di una metropolitana leggera &#8211; sottolinea il sindaco di San Lucido &#8211;<strong> consentirebbe anche a tantissimi abitanti della provincia di Cosenza di recarsi nelle localit\u00e0 del Tirreno Cosentino con facilit\u00e0 e per tutto l&#8217;anno<\/strong>, incrementando le presenze nei nostri comuni. Darebbe la possibilit\u00e0 a lavoratori, studenti, e cittadini di<strong> recarsi a Cosenza, all&#8217;universit\u00e0 della Calabria, nell&#8217;hinterland, con facilit\u00e0<\/strong>. Inoltre &#8211; grazie a questa opera &#8211; si devono realizzare collegamenti, anche con bus e navette, verso l&#8217;aeroporto di Lamezia Terme. Anche l&#8217;aspetto legato alla sicurezza\u00a0 \u00e8 nevralgico. Le arterie stradali non sono pi\u00f9 adatte e sicure per un&#8217;alta percorribilit\u00e0, soprattutto nei mesi estivi. <strong>Una metropolitana leggera serve a decongestionare il traffico e se attiva anche di notte, specialmente in estate, si eviterebbero molti incidenti stradali, e sarebbe un mezzo utilizzato dai giovani per spostarsi in sicurezza\u00bb<\/strong>.<\/div>\n<div dir=\"auto\"><\/div>\n<h3 dir=\"auto\">\u00abServe un&#8217;idea radicale per i trasporti e per il turistico\u00bb<\/h3>\n<div dir=\"auto\">\u00abDalla SS18, alla Statale 107, fino ai collegamenti ferroviari, <strong>\u00e8 evidente che persistono delle carenze strutturali e logistiche che incidono negativamente, \u00e8 innegabile<\/strong>. Non dobbiamo puntare il dito alimentando inutili polemiche n\u00e8 possiamo aspettare la manna dal cielo\u00bb. De Tommaso conclude: \u00ab<strong>Serve un&#8217;idea radicale sia nel settore dei trasporti che in quello turistico,<\/strong> che sia fattibile e che non resti nel cassetto dei sogni. Auspico il coinvolgimento dei sindaci e degli amministratori di tutto il litorale al fine di realizzare quest&#8217;opera di elevata capacit\u00e0 molto simile alla classica metropolitana, di cui conserva le caratteristiche di totale separazione o assenza di interferenza con altri sistemi di trasporto\u00bb.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SAN LUCIDO (CS) &#8211; \u00abUna metropolitana leggera in grado di unire davvero i paesi del litorale tirrenico, e di unire il Tirreno Cosentino all&#8217;universit\u00e0 di Arcavacata e al capoluogo Cosentino, implementando anche il trasporto per e dall&#8217;aeroporto di Lamezia Terme. Un progetto ormai improrogabile e mai concretizzatosi negli anni\u00bb. A rilanciare l&#8217;idea di un mezzo [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":251976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-251974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/251974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=251974"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/251974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/251976"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=251974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=251974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=251974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}