{"id":252091,"date":"2025-02-20T20:00:00","date_gmt":"2025-02-20T19:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=252091"},"modified":"2025-02-20T19:38:38","modified_gmt":"2025-02-20T18:38:38","slug":"salvini-il-ponte-sullo-stretto-e-lopera-piu-monitorata-al-mondo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/salvini-il-ponte-sullo-stretto-e-lopera-piu-monitorata-al-mondo\/","title":{"rendered":"Salvini: \u00abIl ponte sullo Stretto \u00e8 l&#8217;opera pi\u00f9 monitorata al Mondo\u00bb"},"content":{"rendered":"<p>ROMA &#8211; &#8220;Nelle prossime settimane contiamo di concludere le interlocuzioni con la commissione Via e procedere tempestivamente con gli ulteriori adempimenti previsti dalla direttiva Habitat&#8221;. Cos\u00ec <strong>Matteo Salvini<\/strong> rispondendo al question time in Senato a un&#8217;interrogazione sul Ponte sullo Stretto. &#8220;Questo &#8211; ha proseguito &#8211; ci consentir\u00e0 di arrivare all&#8217;approvazione del progetto definitivo da parte del Cipes e quindi finalmente partire con la cantierizzazione. <strong>Il Ponte sullo stretto \u00e8 una delle strutture pi\u00f9 studiate e monitorate a livello mondiale<\/strong>&#8221; ha concluso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; &#8220;Nelle prossime settimane contiamo di concludere le interlocuzioni con la commissione Via e procedere tempestivamente con gli ulteriori adempimenti previsti dalla direttiva Habitat&#8221;. Cos\u00ec Matteo Salvini rispondendo al question time in Senato a un&#8217;interrogazione sul Ponte sullo Stretto. &#8220;Questo &#8211; ha proseguito &#8211; ci consentir\u00e0 di arrivare all&#8217;approvazione del progetto definitivo da parte [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":244430,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-252091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=252091"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/244430"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=252091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=252091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=252091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}