{"id":252113,"date":"2025-02-22T17:46:07","date_gmt":"2025-02-22T16:46:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=252113"},"modified":"2025-02-22T17:50:41","modified_gmt":"2025-02-22T16:50:41","slug":"restyling-al-comune-di-cassano-oltre-3-milioni-per-ristrutturare-ledificio-che-risale-agli-anni-70","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/restyling-al-comune-di-cassano-oltre-3-milioni-per-ristrutturare-ledificio-che-risale-agli-anni-70\/","title":{"rendered":"Restyling al Comune di Cassano: oltre 3 milioni per ristrutturare l&#8217;edificio che risale agli anni &#8217;70"},"content":{"rendered":"<p class=\"v1MsoNormal\">CASSANO ALLO IONIO (CS) &#8211; Si \u00e8 tenuta qualche giorno fa nella sala del consiglio comunale della Citt\u00e0 di <strong>Cassano All&#8217;Ionio<\/strong> la formale consegna dei lavori che porteranno alla <strong>ristrutturazione, all&#8217;adeguamento sismico e all&#8217;efficientamento energetico del Municipio cassanese<\/strong>. Ad eseguire i lavori sar\u00e0 l&#8217;impresa <strong>Giafra Srl di Cosenza,<\/strong> esperta del settore. A firmare la documentazione il rup geometra Diego Falcone, responsabile del settore Urbanistica del Comune sibarita, il responsabile dell&#8217;area Tecnica dell&#8217;Ente, ingegnere Luigi Serra Cassano. l&#8217;architetto Pasquale Barone, progettista e direttore dei lavori e l&#8217;ingegnere Francesco Mollo, referente della Giafra Srl.<\/p>\n<p class=\"v1MsoNormal\">Presenti per l&#8217;amministrazione comunale il sindaco Giovanni Papasso, il vicesindaco Antonino Mungo, le assessore Sara Russo ed Elisa Fasanella, la consigliera con delega Carmen Gaudiano e Veronica Petrosino, delegata dell&#8217;amministrazione comunale nel consiglio di amministrazione di AssoLaghi, dirigenti e dipendenti comunali e accorsi per conoscere il progetto che cambier\u00e0 la casa dei cassanesi dopo oltre cinquant&#8217;anni.<\/p>\n<p class=\"v1MsoNormal\">In aula anche, in qualit\u00e0 di cronisti d&#8217;eccezione, anche alcuni corsisti dell&#8217;istituto di istruzione secondaria superiore &#8220;Erodoto d Thurii&#8221;, accompagnati dai docenti Cecilia Casella e Domenico Marino, per scoprire e conoscere tecniche e segreti della comunicazione istituzionale.<\/p>\n<h3><strong>Papasso: \u00abEnnesimo intervento di portata storica\u00bb<\/strong><\/h3>\n<p class=\"v1MsoNormal\">\u00abC&#8217;era la necessit\u00e0 \u2013 ha raccontato ai presenti il<strong> sindaco Giovanni Papasso<\/strong> \u2013 di eseguire i lavori di adeguamento sismico ma anche quella di rifare gli<strong> impianti ormai obsoleti<\/strong> motivo per cui abbiamo deciso di intervenire in tal senso. Mettiamo mano, nei fatti, alla casa dei cassanesi (costruita oltre cinquant&#8217;anni fa) e diamo il via a questo <strong>ennesimo intervento di portata storica<\/strong> visto che non \u00e8 mai stato n\u00e9 pensato e n\u00e9 fatto prima delle mie amministrazioni ed \u00e8 un momento importante anche per tutto l&#8217;Alto Ionio perch\u00e9 il nostro Comune \u00e8 s\u00ec la casa dei cassanesi ma anche un punto di riferimento dell&#8217;intera zona visto che \u00e8 anche sede territoriale COC con funzione strategica per il coordinamento degli interventi dell&#8217;area in caso di gravi eventi avversi: un vanto e un onore per tutti noi ma che comporta anche degli oneri motivo per cui <strong>l&#8217;intervento non era pi\u00f9 procrastinabile<\/strong>. Con questa iniziativa \u2013 ha concluso il sindaco Papasso \u2013 dimostriamo ancora una volta il nostro impegno per un Comune pi\u00f9 sostenibile e innovativo. I lavori che oggi partono segneranno una svolta importante per la nostra amministrazione e per i cittadini, che potranno godere di un ambiente pi\u00f9 efficiente e in linea con le sfide ambientali\u00a0del\u00a0futuro e con le ultime normative in vigore\u00bb.<\/p>\n<p class=\"v1MsoNormal\"><strong>L&#8217;intervento che comincer\u00e0 nei prossimi giorni sar\u00e0 &#8220;a strati&#8221;<\/strong>: il piano seminterrato e il piano terra sono gi\u00e0 disponibili, mentre gli altri piani dell&#8217;edificio sono ancora interessati dall&#8217;attivit\u00e0 ordinaria. Completati questa parte, poi si passer\u00e0 ai piani superiori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; Si \u00e8 tenuta qualche giorno fa nella sala del consiglio comunale della Citt\u00e0 di Cassano All&#8217;Ionio la formale consegna dei lavori che porteranno alla ristrutturazione, all&#8217;adeguamento sismico e all&#8217;efficientamento energetico del Municipio cassanese. Ad eseguire i lavori sar\u00e0 l&#8217;impresa Giafra Srl di Cosenza, esperta del settore. A firmare la documentazione [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":252114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[],"class_list":["post-252113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=252113"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/252114"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=252113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=252113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=252113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}