{"id":252450,"date":"2025-02-26T07:19:11","date_gmt":"2025-02-26T06:19:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=252450"},"modified":"2025-02-26T07:20:46","modified_gmt":"2025-02-26T06:20:46","slug":"tentato-omicidio-di-un-35enne-armi-da-guerra-tritolo-e-droga-arrestate-cinque-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tentato-omicidio-di-un-35enne-armi-da-guerra-tritolo-e-droga-arrestate-cinque-persone\/","title":{"rendered":"Tentato omicidio di un 35enne, armi da guerra, tritolo e droga: arrestate cinque persone"},"content":{"rendered":"<p>MONTEBELLO JONICO (RC) &#8211; Un\u2019operazione complessa quella condotta dai carabinieri di Melito Porto Salvo con il supporto dello Squadrone Eliportato Cacciatori &#8220;Calabria&#8221;, del Nucleo Cinofili di Vibo Valentia e dei militari di Desio (MB). <strong>Cinque persone<\/strong>, legate da <strong>vincoli di parentela<\/strong>, sono state arrestate con accuse gravissime: <strong>tentato omicidio, detenzione e porto di armi da guerra, detenzione e traffico di stupefacenti e ricettazione<\/strong>.<\/p>\n<h4><strong>Il delitto che ha fatto scattare l\u2019indagine<\/strong><\/h4>\n<p>I fatti risalgono al 9 ottobre del 2024, quando un uomo residente a Montebello Jonico \u00e8 <strong>arrivato all\u2019ospedale di Melito Porto Salvo<\/strong> con una <strong>ferita d\u2019arma da fuoco al collo<\/strong>. La gravit\u00e0 della lesione ha richiesto il trasferimento immediato nel reparto di Rianimazione del Gom di Reggio Calabria, dove l\u2019uomo \u00e8 stato ricoverato. L\u2019allarme lanciato dall\u2019ospedale ha subito attivato i carabinieri, che hanno avviato le prime indagini per ricostruire la dinamica dell\u2019accaduto. Le prime evidenze sul luogo del delitto hanno permesso di stabilire che<strong> l\u2019arma usata fosse una pistola a tamburo del tipo &#8216;rivoltella&#8217;;<\/strong> un dettaglio suggerito dall\u2019assenza di bossoli e dalla tipologia dell\u2019ogiva estratta dal corpo della vittima. Gli investigatori hanno quindi iniziato a scandagliare ogni dettaglio della vita della vittima e dei suoi contatti per risalire al responsabile dell\u2019attentato.<\/p>\n<h4><strong>Le indagini<\/strong><\/h4>\n<p>Durate diversi mesi, sono state eseguite con metodi tradizionali e avanzate tecniche investigative. Gli inquirenti hanno <strong>raccolto testimonianze cruciali<\/strong>, ma \u00e8 stata soprattutto l\u2019attivit\u00e0 tecnica a rivelarsi determinante: intercettazioni telefoniche e ambientali hanno permesso di delineare il quadro criminale e identificare i soggetti coinvolti. I carabinieri hanno poi effettuato una serie di <strong>perquisizioni<\/strong> mirate nelle abitazioni e nei terreni degli indagati, con particolare attenzione ad un <strong>giardino di propriet\u00e0 della madre del presunto autore del tentato omicidio<\/strong>. Ed \u00e8 proprio l\u00ec che sono emersi importanti elementi indiziari.<\/p>\n<h4><strong>L\u2019arsenale nascosto e la droga<\/strong><\/h4>\n<p>Le perquisizioni hanno infatti portato alla scoperta di un <strong>vero e proprio arsenale da guerra, nascosto con meticolosa attenzione<\/strong>. Tra le armi sequestrate figurano pistole e fucili, tra cui una pistola tipo Rivoltella di colore nero contenente nel tamburo a 6 colpi, 5 colpi cal. 7.65, verosimilmente utilizzata per commettere il delitto, ma anche un fucile automatico AK-47 Kalashnikov con matricola abrasa. Oltre a ci\u00f2, i Carabinieri hanno rinvenuto ingenti <strong>quantit\u00e0 di munizioni, esplosivi e droga:<\/strong> circa <strong>mezzo chilo di cocaina,<\/strong> dal valore di mercato di 150mila euro, 200 grammi di <strong>tritolo<\/strong> occultati in un barattolo di vetro e una micidiale bomba carta del peso di circa 1,2 kg, dotata di miccia.<\/p>\n<h4><strong>Un fortino del crimine: traffico, armi e omert\u00e0<\/strong><\/h4>\n<p>L\u2019attivit\u00e0 d\u2019intercettazione ha consentito di mettere in luce come tutti i partecipanti alle condotte delittuose, legati fra loro da intensissimi legami familiari, agissero all\u2019unisono, con fortissima <strong>solidariet\u00e0 reciproca<\/strong> e come <strong>un vero e proprio corpo unico<\/strong>, nonch\u00e9 la detenzione di una mole impressionante di armi anche micidiali e da guerra con correlato munizionamento oltrech\u00e8 esplosivo di notoria elevata potenzialit\u00e0 offensiva. Il tutto era disseminato tra le pertinenze delle abitazioni e i terreni limitrofi, pronto per essere utilizzato.<\/p>\n<h4><strong>Il presunto movente del tentato omicidio<\/strong><\/h4>\n<p>Sarebbe invece da ricondurre a un <strong>debito contratto dalla vittima per l\u2019acquisto di droga<\/strong>. I preesistenti contatti tra la vittima e gli indagati erano stati frequenti e erano avvenuti spesso tramite messaggi in codice, con espressioni come \u201cun bacino\u201d o \u201cdue bacini\u201d per riferirsi alle dosi di stupefacente richieste. Secondo le dichiarazioni raccolte, la vittima si recava spesso presso <strong>l\u2019abitazione del presunto autore<\/strong> del <strong>tentato omicidio<\/strong> per acquistare droga e in almeno un\u2019occasione avrebbe consegnato denaro contante direttamente a uno degli arrestati. Nonostante gli elementi raccolti, <strong>gli indagati hanno tentato pi\u00f9 volte di eludere le investigazioni<\/strong> cercando di spostare le armi e imponendo il silenzio ai propri familiari. Durante le intercettazioni, sono stati <strong>documentati ordini espliciti impartiti da uno degli arrestati alla figlia e al cognato<\/strong> affinch\u00e9 non rivelassero nulla agli inquirenti, nonch\u00e9 la volont\u00e0 di occultare ulteriori armi da guerra, al momento non ancora rinvenute dai militari dell\u2019Arma.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTEBELLO JONICO (RC) &#8211; Un\u2019operazione complessa quella condotta dai carabinieri di Melito Porto Salvo con il supporto dello Squadrone Eliportato Cacciatori &#8220;Calabria&#8221;, del Nucleo Cinofili di Vibo Valentia e dei militari di Desio (MB). Cinque persone, legate da vincoli di parentela, sono state arrestate con accuse gravissime: tentato omicidio, detenzione e porto di armi da [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":252451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-252450","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=252450"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/252451"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=252450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=252450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=252450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}