{"id":252499,"date":"2025-03-01T21:00:44","date_gmt":"2025-03-01T20:00:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=252499"},"modified":"2025-03-01T21:07:15","modified_gmt":"2025-03-01T20:07:15","slug":"san-giovanni-in-fiorecs-in-campo-9-professioniste-per-sostenere-famiglie-e-minori-in-difficolta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/san-giovanni-in-fiorecs-in-campo-9-professioniste-per-sostenere-famiglie-e-minori-in-difficolta\/","title":{"rendered":"San Giovanni in Fiore, in campo 9 professioniste per sostenere famiglie e minori in difficolt\u00e0"},"content":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211;<strong> A San Giovanni in Fiore e\u0300 partito il Programma P.I.P.P.I., finanziato con fondi PNRR per 211.500 euro<\/strong>. \u00abE\u0300 un intervento \u2013 spiega la sindaca <strong>Rosaria Succurro<\/strong> \u2013 che mira a rafforzare la capacita\u0300 dei genitori di prendersi cura dei propri figli, in modo da prevenire <strong>situazioni di disagio e ridurre il rischio di allontanamento dei minori dalla famiglia d\u2019origine.<\/strong> Si tratta in sostanza di un progetto di cura, attenzione e vicinanza alle famiglie in difficolt\u00e0, attraverso l\u2019attivazione di educatori e psicologi che lavorano direttamente nel territorio, nelle scuole e nelle case, per costruire risposte concrete ai bisogni educativi e sociali dei bambini\u00bb.<\/p>\n<p>\u00abOltretutto, ben 9 professioniste, tra educatrici e psicologhe, sono impegnate in questo lavoro. La loro competenza \u2013 sottolinea la Sindaca \u2013 e il loro radicamento nella comunita\u0300 locale rappresentano senz\u2019altro un valore aggiunto. La nostra amministrazione ha sempre messo le persone al centro dell\u2019azione politica. Il nostro obiettivo e\u0300 costruire una solida rete di sostegno, affinch\u00e9 nessuno rimanga indietro. La famiglia, pensiamo, e\u0300 il primo luogo di crescita e protezione per ogni bambino, e con questo Programma \u2013 evidenzia Succurro \u2013 vogliamo dare strumenti e risorse per rafforzarla, garantendo ai piu\u0300 piccoli un presente sereno e un futuro migliore\u00bb. \u00abIl Comune di San Giovanni in Fiore \u2013 conclude la Sindaca \u2013 continua a investire nel sociale, ogni giorno con impegno e responsabilit\u00e0. Le politiche sociali sono il primo indicatore della capacita\u0300 e della visione amministrativa. Minori e famiglie sono la nostra priorit\u00e0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211; A San Giovanni in Fiore e\u0300 partito il Programma P.I.P.P.I., finanziato con fondi PNRR per 211.500 euro. \u00abE\u0300 un intervento \u2013 spiega la sindaca Rosaria Succurro \u2013 che mira a rafforzare la capacita\u0300 dei genitori di prendersi cura dei propri figli, in modo da prevenire situazioni di disagio e [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":252774,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-252499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=252499"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/252774"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=252499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=252499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=252499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}