{"id":252533,"date":"2025-02-26T19:14:37","date_gmt":"2025-02-26T18:14:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=252533"},"modified":"2025-02-26T19:14:37","modified_gmt":"2025-02-26T18:14:37","slug":"davide-ferrerio-ridotto-in-coma-dopo-il-pestaggio-definitiva-la-pena-per-laggressore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/davide-ferrerio-ridotto-in-coma-dopo-il-pestaggio-definitiva-la-pena-per-laggressore\/","title":{"rendered":"Davide Ferrerio ridotto in coma dopo il pestaggio, definitiva la pena per l&#8217;aggressore"},"content":{"rendered":"<p>CATANZARO &#8211; La Corte di Cassazione ha rigettato il ricorso della difesa di<strong> Nicol\u00f2 Passalacqua<\/strong>, 25enne accusato di essere stato il responsabile dell&#8217;aggressione ai danni di <strong><a href=\"https:\/\/quicosenza.it\/news\/italia\/484283-brutale-pestaggio-a-davide-ferrerio-intercettazioni-agghiacciati-e-caduto-come-un-salame\" target=\"_blank\" rel=\"noopener\">Davide Ferrerio<\/a><\/strong>, il giovane di Bologna ridotto in fin di vita l&#8217;11 agosto del 2022 nel centro di Crotone. Ferrerio, dal giorno dell&#8217;aggressione, \u00e9 <strong>in coma irreversibile<\/strong>. La condanna a <strong>12 anni e otto mesi per tentato omicidio<\/strong> \u00e8 dunque definitiva. &#8220;E&#8217; la minima risposta che la giustizia italiana doveva dare necessariamente alla famiglia di Davide&#8221;, dice l&#8217;avvocato Gabriele Bordoni, difensore della madre del ragazzo.<\/p>\n<h3><strong>Uno scambio di persona all&#8217;origine dell&#8217;aggressione<\/strong><\/h3>\n<p>All&#8217;origine dell&#8217;aggressione del bolognese, uno scambio di persona causato da una serie di coincidenze. Tutto sarebbe scaturito da una relazione social tra una ragazza, <strong>Martina Perugino, alla quale era interessato Passalacqua,<\/strong> ed un uomo, Alessandro Curto, che si nascondeva sotto un profilo falso con il nome di un ex fidanzato della ragazza. Per questo la <strong>madre della giovane, Anna Perugino<\/strong>, aveva organizzato un appuntamento per smascherare chi c&#8217;era dietro quel profilo. Insieme al compagno Andrej Gaju ad alcuni parenti e a Nicol\u00f2 Passalacqua, la giovane era andata davanti al Tribunale, dove avevano incrociato proprio Curto che si era defilato e, dopo avere raggiunto l&#8217;auto, aveva inviato un messaggio alla ragazza nel quale diceva di avere &#8220;una camicia bianca&#8221;. Dopo quel messaggio si \u00e8 verificata l&#8217;aggressione ai danni di Ferrerio.<\/p>\n<p><strong><a href=\"https:\/\/quicosenza.it\/news\/calabria\/aggressione-davide-ferrerio-condannata-a-8-anni-anna-perugino-assolto-il-compagno\" target=\"_blank\" rel=\"noopener\">Anna Perugino<\/a> \u00e8 stata condannata a otto anni in primo grado<\/strong> e l&#8217;11 marzo \u00e8 previsto l&#8217;appello insieme a Gaju, assolto per non aver commesso il fatto. Il tribunale di Crotone riqualific\u00f2 il reato da concorso anomalo in tentato omicidio a concorso anomalo in lesioni gravissime. Ha fatto appello la parte civile e la Procura generale ha chiesto rispettivamente 12 anni e quattro anni. <strong>Anche Curto \u00e8 in attesa della Cassazione<\/strong> dopo che \u00e8 stato impugnata la sentenza di proscioglimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; La Corte di Cassazione ha rigettato il ricorso della difesa di Nicol\u00f2 Passalacqua, 25enne accusato di essere stato il responsabile dell&#8217;aggressione ai danni di Davide Ferrerio, il giovane di Bologna ridotto in fin di vita l&#8217;11 agosto del 2022 nel centro di Crotone. Ferrerio, dal giorno dell&#8217;aggressione, \u00e9 in coma irreversibile. La condanna [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":183279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-252533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=252533"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183279"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=252533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=252533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=252533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}