{"id":252606,"date":"2025-02-27T14:30:30","date_gmt":"2025-02-27T13:30:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=252606"},"modified":"2025-02-27T14:51:17","modified_gmt":"2025-02-27T13:51:17","slug":"bastoni-e-passamontagna-per-aggredire-i-tifosi-avversari-daspo-per-cinque-ultras","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/bastoni-e-passamontagna-per-aggredire-i-tifosi-avversari-daspo-per-cinque-ultras\/","title":{"rendered":"Bastoni e passamontagna per aggredire i tifosi avversari, Daspo per cinque ultras"},"content":{"rendered":"<p>CROTONE &#8211; Il questore di Crotone Renato Panvino ha emesso cinque provvedimenti di Daspo a carico di <strong>altrettanti tifosi calabresi<\/strong>, in relazione all&#8217;incontro di calcio di Lega Pro <strong>Crotone-Benevento<\/strong> disputato il <strong>31 ottobre 2024 nello stadio Ezio Scida<\/strong>. I cinque erano stati fermati dai carabinieri di Cir\u00f2 Marina dopo che avevano <strong>tentato di aggredire tifosi del Benevento<\/strong> che transitavano sulla statale 106 all&#8217;altezza della frazione Torre di Melissa a bordo di <strong>un minivan in direzione Taranto<\/strong>.<\/p>\n<p>Nel corso della successiva perquisizione, sull&#8217;auto erano stati trovati due passamontagna, una mazza da baseball, un bastone di plastica, una sciarpa del Crotone calcio, una maschera da travestimento. Il materiale era stato sequestrato ed i cinque denunciati per violazione della normativa in tema di manifestazioni sportive e porto di armi od oggetti atti ad offendere.<\/p>\n<p>Dopo il procedimento amministrativo avviato dalla Divisione Polizia Anticrimine a seguito di quell&#8217;episodio, il questore ha emesso i Daspo la cui <strong>durata varia da uno a 8 anni<\/strong>. Per tre persone \u00e8 stata prevista l&#8217;ulteriore prescrizione dell&#8217;obbligo di presentazione in Questura durante lo svolgimento delle competizioni sportive. I <strong>tre<\/strong>, infatti, risultavano <strong>gi\u00e0 colpiti da provvedimento di Daspo<\/strong> e pertanto \u00e8 stata aggravata la misura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Il questore di Crotone Renato Panvino ha emesso cinque provvedimenti di Daspo a carico di altrettanti tifosi calabresi, in relazione all&#8217;incontro di calcio di Lega Pro Crotone-Benevento disputato il 31 ottobre 2024 nello stadio Ezio Scida. I cinque erano stati fermati dai carabinieri di Cir\u00f2 Marina dopo che avevano tentato di aggredire tifosi [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":252611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-252606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=252606"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/252611"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=252606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=252606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=252606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}