{"id":252949,"date":"2025-03-04T18:09:56","date_gmt":"2025-03-04T17:09:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=252949"},"modified":"2025-03-04T18:09:56","modified_gmt":"2025-03-04T17:09:56","slug":"ombre-e-misteri-sulla-morte-di-salvatore-cosenza-scende-in-piazza-per-uccello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ombre-e-misteri-sulla-morte-di-salvatore-cosenza-scende-in-piazza-per-uccello\/","title":{"rendered":"&#8220;Ombre e misteri sulla morte di Salvatore&#8221;: Cosenza scende in piazza per &#8216;Uccello&#8217;"},"content":{"rendered":"<p>COSENZA &#8211; <strong>&#8220;Giustizia e verit\u00e0 per Salvatore<\/strong>&#8220;. E&#8217; lo slogan della manifestazione indetta per <strong>luned\u00ec 10 marzo alle ore 17,00 davanti al Tribunale di Cosenza<\/strong> per chiedere alle autorit\u00e0 chiarezza sulla <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/la-morte-di-salvatore-iaccino-la-procura-ha-aperto-uninchiesta-per-omicidio-colposo-4-indagati\" target=\"_blank\" rel=\"noopener\">morte di Salvatore Iaccino<\/a><\/strong> che &#8220;ha scosso tutta la citt\u00e0, in un sentimento collettivo di tristezza, sgomento e rabbia&#8221;, scrivono i cittadini in una nota. La Procura di Cosenza\u00a0<strong>ha aperto un\u2019inchiesta sulla\u00a0<a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/uccello-adesso-e-libero-di-volare-cosenza-e-i-suoi-tifosi-piangono-la-morte-di-salvatore-iaccino\" target=\"_blank\" rel=\"noopener\">morte<\/a> del 48enne<\/strong> ultr\u00e0 del Cosenza conosciuto da tutti con il soprannome di \u201cUccello\u201d<\/p>\n<p>&#8220;Le circostanze della sua morte sono ancora<strong> avvolte da ombre e misteri<\/strong>, che la versione ufficiale fornita dalla clinica Villa degli Oleandri non ha saputo spiegare. A 20 giorni dalla tragedia, luned\u00ec 17 marzo, scenderemo in piazza per pretendiamo giustizia e verit\u00e0 per Salvatore e che le vere cause della sua morte non finiscano insabbiate nelle stanze del Tribunale di Cosenza&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-252951 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1.jpg\" alt=\"\" width=\"435\" height=\"544\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1.jpg 1080w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1-240x300.jpg 240w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1-819x1024.jpg 819w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1-768x960.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1-336x420.jpg 336w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1-150x188.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1-300x375.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1-696x870.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/f22ebe41-7290-41d1-8793-e1a6cf86f1fd-1-1068x1335.jpg 1068w\" sizes=\"auto, (max-width: 435px) 100vw, 435px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Giustizia e verit\u00e0 per Salvatore&#8220;. E&#8217; lo slogan della manifestazione indetta per luned\u00ec 10 marzo alle ore 17,00 davanti al Tribunale di Cosenza per chiedere alle autorit\u00e0 chiarezza sulla morte di Salvatore Iaccino che &#8220;ha scosso tutta la citt\u00e0, in un sentimento collettivo di tristezza, sgomento e rabbia&#8221;, scrivono i cittadini in una [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":252950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-252949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=252949"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/252949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/252950"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=252949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=252949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=252949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}