{"id":253486,"date":"2025-03-12T11:00:22","date_gmt":"2025-03-12T10:00:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=253486"},"modified":"2025-03-12T10:03:04","modified_gmt":"2025-03-12T09:03:04","slug":"efficientamento-delle-reti-idriche-mendicino-nel-processo-di-ingegnerizzazione-di-serbatoi-e-reti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/efficientamento-delle-reti-idriche-mendicino-nel-processo-di-ingegnerizzazione-di-serbatoi-e-reti\/","title":{"rendered":"Efficientamento delle reti idriche, Mendicino nel processo di ingegnerizzazione di serbatoi e reti"},"content":{"rendered":"<p>MENDICINO (CS) &#8211; Accompagnata dal responsabile dell\u2019Ufficio tecnico Ing. Roberto Greco, il sindaco Irma Bucarelli ha visitato le aree interessate dai lavori, sottolineando l&#8217;importanza di questo progetto per la comunit\u00e0: \u00ab<strong>L\u2019avvio concreto dei cantieri<\/strong> segna un passo significativo verso il <strong>miglioramento dei nostri servizi idrici<\/strong>. Ringrazio di cuore la <strong>Regione Calabria per aver scelto Mendicino<\/strong> come uno dei comuni pionieri in questo percorso di efficientamento. Questo progetto non solo ci permetter\u00e0 di modernizzare i nostri impianti, ma garantir\u00e0 anche una gestione pi\u00f9 sostenibile delle risorse idriche, a beneficio di tutti i cittadini\u00bb.<\/p>\n<p>Il sindaco ha poi aggiunto: \u00abSiamo <strong>consapevoli dell\u2019importanza di una rete idrica efficiente<\/strong> e <strong>all\u2019avanguardia<\/strong>, in grado di ridurre gli sprechi e garantire un servizio di qualit\u00e0. Con questo intervento, Mendicino si avvia verso un futuro pi\u00f9 sostenibile e responsabile\u00bb.<\/p>\n<h4><strong>I lavori<\/strong><\/h4>\n<p>Includono <strong>l\u2019ingegnerizzazione dei serbatoi<\/strong> e <strong>l\u2019ottimizzazione delle reti idriche<\/strong>, rappresentano un investimento significativo per il comune, volto a garantire un servizio idrico pi\u00f9 efficiente e a migliorare la qualit\u00e0 della vita dei cittadini. Il <strong>primo obiettivo<\/strong> del progetto \u00e8 comunque quello di \u201c<strong>ingegnerizzare le reti<\/strong>\u201d, realizzando un dettagliato stato di fatto sia fisico che idraulico che costituisce il punto di partenza corretto per la definizione del piano di infrastrutturazione, necessario a guidare nel tempo il risanamento delle reti di distribuzione.<\/p>\n<p>Altro obiettivo fondamentale \u00e8 quello di <strong>recuperare volumi idrici<\/strong> riducendo le perdite sia amministrative \u2013 mediante sostituzione di contatori &#8211; che di rete \u2013 attraverso la prima campagna sistematica di ricerca perdite e sostituzione mirata di alcuni tratti di condotta.<br \/>\nCon la ricerca perdite in rete si avr\u00e0 sia il recupero di risorsa, sia il conseguente alleggerimento dell\u2019attivit\u00e0 di manutenzione ordinaria; come noto per\u00f2, questo tipo di risanamento tende ad annullarsi nel tempo ed \u00e8 quindi necessario implementare un processo ciclico di ricerca perdite, che potr\u00e0 essere eseguito dai tecnici stessi della gestione, opportunamente formati.<\/p>\n<p>Con la <strong>sostituzione mirata delle reti si ridurranno le perdite<\/strong> di sottofondo nei tronchi di rete pi\u00f9 deteriorati, producendo un effetto continuato nel tempo col beneficio a lungo termine del rinnovamento della rete stessa. In termini generali, sia le attivit\u00e0 relative ai lavori di ricerca e riparazione delle perdite, sia quelle dei lavori di sostituzione mirata delle condotte, consentiranno una migliore gestione dell&#8217;esercizio delle reti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MENDICINO (CS) &#8211; Accompagnata dal responsabile dell\u2019Ufficio tecnico Ing. Roberto Greco, il sindaco Irma Bucarelli ha visitato le aree interessate dai lavori, sottolineando l&#8217;importanza di questo progetto per la comunit\u00e0: \u00abL\u2019avvio concreto dei cantieri segna un passo significativo verso il miglioramento dei nostri servizi idrici. Ringrazio di cuore la Regione Calabria per aver scelto Mendicino [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":253491,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-253486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/253486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=253486"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/253486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/253491"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=253486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=253486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=253486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}