{"id":253552,"date":"2025-03-12T20:04:00","date_gmt":"2025-03-12T19:04:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=253552"},"modified":"2025-03-12T20:06:43","modified_gmt":"2025-03-12T19:06:43","slug":"scavi-di-laino-borgo-il-tesoro-archeologico-diventa-un-modello-di-ricerca-per-le-universita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/scavi-di-laino-borgo-il-tesoro-archeologico-diventa-un-modello-di-ricerca-per-le-universita\/","title":{"rendered":"Scavi di Laino Borgo: il tesoro archeologico diventa un modello di ricerca per le universit\u00e0"},"content":{"rendered":"<p>MESSINA &#8211; &#8220;Non solo un <strong>cantiere di scavi ricco di ritrovamenti unici nel loro genere<\/strong>, ma anche <strong>un vero modello di integrato di ricerca e collaborazione interistituzionale da portare all&#8217;attenzione degli studenti e delle facolt\u00e0 universitarie<\/strong>. La campagna di scavi archeologici sul colle di <strong>Santa Gada nel comune di Laino Borgo<\/strong> <strong>oltre ad essere ormai un caso di studio internazionale<\/strong> sta diventando una buona pratica di dialogo tra enti territoriale e di ricerca. Cosi stamane presso l&#8217;Aula Magna dell&#8217;Universit\u00e0 di Messina la <strong>giunta comunale di Laino Borgo<\/strong> con il <strong>sindaco Mariangelina Russo<\/strong>, il suo vice Innocenzo Donato, e l&#8217;assessore alla cultura Giuseppina Calvosa, sono stati presenti ad un importante convegno che mette in evidenza l&#8217;interesse e l&#8217;importanza che gli scavi di Santa Gada hanno raggiunto nel mondo accademico e della ricerca.<\/p>\n<p>Nel corso dell&#8217;evento al quale hanno preso parte anche Luigi Bloise del Parco nazionale del Pollino, P. Aurino Soprintendente Sabap Cosenza, il professor Mollo a capo delle campagna di scavi condotte nel territorio di Laino Borgo, e altri illustri relatori, ha portato i suoi saluti (attraverso un messaggio scritto) anche il neo commissario dell&#8217;Ente Parco del Pollino, Luigi Lirangi, ai quali sono giunti gli auguri di un proficuo lavoro da parte dell&#8217;amministrazione comunale guidata dal sindaco Russo.<\/p>\n<p>La ricerca di Laino Borgo sar\u00e0 attenzionata dall&#8217;Universit\u00e0 di Messina in quanto modello di sinergia sul territorio tra Comune, Ente Parco, sovrintendenza Sabap di Cosenza e la stessa Universit\u00e0 &#8211; \u00e8 stato affermato nel corso dell&#8217;incontro &#8211; e sar\u00e0 presentata come una delle migliori ricerche dell&#8217;Universit\u00e0 di Messina per l&#8217;impatto sulle comunit\u00e0 locali, sulla comunit\u00e0 scientifica e nei processi di valorizzazione dei beni culturali.<\/p>\n<p>\u00abNon ci stancheremo mai di ringraziare il professor Mollo, i suoi collaboratori, i ragazzi che hanno partecipato alle campagne scavi &#8211; ha ribadito il sindaco di Laino Borgo, Mariangelina Russo &#8211; per averci riscoperto le nostre antichissime e importanti origini dando un risalto alla nostra comunit\u00e0 non soltanto per il territorio Lao-Mercure ma per l&#8217;intero mondo scientifico, culturale e accademico nazionale ed internazionale\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MESSINA &#8211; &#8220;Non solo un cantiere di scavi ricco di ritrovamenti unici nel loro genere, ma anche un vero modello di integrato di ricerca e collaborazione interistituzionale da portare all&#8217;attenzione degli studenti e delle facolt\u00e0 universitarie. La campagna di scavi archeologici sul colle di Santa Gada nel comune di Laino Borgo oltre ad essere ormai [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":211048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-253552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/253552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=253552"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/253552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/211048"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=253552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=253552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=253552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}