{"id":25377,"date":"2013-08-21T06:46:20","date_gmt":"2013-08-21T04:46:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=25377"},"modified":"2023-01-17T13:22:57","modified_gmt":"2023-01-17T12:22:57","slug":"10313-transumanze-sila-festival-i-prossimi-eventi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10313-transumanze-sila-festival-i-prossimi-eventi\/","title":{"rendered":"Transumanze Sila Festival: i prossimi eventi"},"content":{"rendered":"<p style=\"text-align: justify;\">LORICA &#8211; Parte oggi l&#8217;edizione 2013 di &#8220;Slow Festival elogio alla lentezza&#8221;, evento all&#8217;interno dell&#8217;articolato programma di <a href=\"http:\/\/transumanze.provincia.cs.it\/sites\/\" target=\"_blank\" rel=\"noopener\">Transumanze Sila Festival<\/a> organizzato dalla Provincia di Cosenza e caratterizzato da un ricco cartellone di appuntamenti che vanno dal 2 agosto al 15 settembre.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Lo Slow Festival ideato e organizzato da L&#8217;Officina delle Idee con la collaborazione della condotta <a href=\"http:\/\/www.slowfood.it\" target=\"_blank\" rel=\"noopener\">Slow Food<\/a> Cosenza e Sila e di Slow Food Calabria, quest&#8217;anno ha come filo conduttore il tema &#8220;<strong>Viaggi e paesaggi<\/strong>&#8221; e propone a riguardo diversi spunti di riflessione attraverso tematiche che toccano vari settori: dalla cultura al turismo, dalla medicina al benessere, dalla scrittura alla lettura, dalla fotografia al video. Tutti appuntamenti che, chiaramente, hanno come protagonista la lentezza in quanto approccio comportamentale che consente di avere maggiore consapevolezza delle proprie azioni e quindi dell&#8217;esistenza stessa. Il Festival, sotto la direzione artistica di Antonio Blandi, Fausta Comite e Raffaele Riga, si snoda lungo una serie di interessanti appuntamenti che vanno dal 21 al 31 agosto. Sono previsti: mostre fotografiche, presentazioni di libri, tavole rotonde, degustazioni guidate, attivita&#8217; esperienziali di trekking yoga, sciamanesimo, meditazione camminata, chi kung, incontri di approfondimento su scrittura, fotografia, video e carnet di viaggio. I vari ospiti del Festival accompagneranno il pubblico in un percorso intellettuale, culturale e sensoriale teso a promuovere approcci comportamentali consapevoli: buoni, giusti e puliti. Tra le novita&#8217; di quest&#8217;anno sono da segnalare alcune importanti ed interessanti iniziative, a partire dalla Gran Festa dei Formaggi che si svolgera&#8217; il 30 e 31 agosto con un&#8217;attenzione particolare per la produzione di formaggi ovi-caprini ed un focus con esperti del settore sulla razza rustica calabrese. Un altro evento catalizzatore di questa edizione e&#8217; il &#8220;<strong>Cammino di Gioacchino da Fiore<\/strong>&#8221; nell&#8217;ambito della sezione &#8220;<strong>Officina degli scrittori? Scuola del Racconto di Viaggio<\/strong>&#8221; che si propone come un percorso esperenziale attraverso i luoghi che hanno caratterizzato la vita del &#8220;calavrese abate Giovacchino di spirito profetico dotato&#8221;. Altra rilevante iniziativa e&#8217; la giornata dedicata a &#8220;LaborApp verso gli stati generali delle comunita&#8217; appenniniche&#8221;, che prevede, oltre all&#8217;incontro dei delegati Slow Food delle regioni appenniniche, anche un forum\/laboratorio per la costruzione di un manifesto per la salvaguardia e la valorizzazione del patrimonio culturale e identitario della montagna appenninica. <br \/>Il programma entra subito nel vivo con le attivita&#8217; esperenziali proposte nell&#8217;ambito della sezione &#8220;<strong>Sila Naturalmente Benessere<\/strong>&#8220;, un contenitore di attivita&#8217; sia fisiche che meditative che hanno nella natura e nel suo rispetto il comune denominatore e che percio&#8217; si svolgeranno nell&#8217;incantevole scenario naturalistico dell&#8217;altipiano silano. Le date previste sono: mercoledi&#8217; 21 agosto e giovedi&#8217; 22 agosto con il maestro Paolo Ricci ideatore del Trekking Yoga, nato dalla sua pratica yoga e da un imprescindibile amore per la natura e la montagna. Il maestro proporra&#8217;, inoltre, degli esercizi di chi kung la &#8216;ginnastica interna&#8217; cinese che sta alla base delle arti marziali orientali (Tai Chi Chuan, Kung Fu, ecc.). A seguire il venerdi&#8217; 23 agosto ci saranno gli incontri pratici esperienziali tenuti da Marcello Aragona, oncologo e psicoterapeuta ad indirizzo transpersonale e da Stefania Panetta, biologa ed operatrice ayurveda che riguardano le antiche tradizioni sciamaniche, la dendroterapia energetica e la meditazione camminata. Sempre nella stessa giornata del 23 agosto, a Lorica, ci sara&#8217; l&#8217;inaugurazione della mostra fotografica di Enzo Barone, dal titolo &#8220;Viaggi e paesaggi dal mondo&#8221; e della mostra &#8220;<strong>Paesaggi della provincia cosentina<\/strong>&#8221; che raccoglie le opere di diversi fotografi dell&#8217;Associazione &#8220;<strong>Ladri di luce<\/strong>&#8220;. Anche in questa edizione dello Slow Festival si manifesta l&#8217;intenzione di raccontare la realta&#8217; non soltanto attraverso le conferenze, ma anche attraverso la forza evocativa delle immagini. A tal proposito e&#8217; bene ricordare come la FIAF (Federazione Italiana Associazioni Fotografiche) ha voluto accordare, per il terzo anno consecutivo, il suo riconoscimento ufficiale alla manifestazione. Un&#8217;altra interessante iniziativa, che si propone anche in questa terza edizione dello &#8220;Slow Festival&#8221;, riguarda la presentazione di alcuni libri di autori calabresi, sempre nell&#8217;ottica di valorizzare e di far conoscere la ricchezza del nostro territorio anche in termini di cultura. Gli appuntamenti in programma, ai quali saranno presenti ovviamente gli autori, sono tre. Si parte il 22 agosto a Silvana Mansio con Daniel Cundari, giovane e promettente poeta e scrittore, che presenta il suo ultimo lavoro &#8220;<strong>Istruzioni per distruggere il vento<\/strong>&#8220;. Si prosegue il 23 agosto, a Lorica, con <a href=\"http:\/\/www.ecologiaconsapevole.it\" target=\"_blank\" rel=\"noopener\"><strong>Francesco Tassone ed il suo libro &#8220;Ecologia consapevole&#8221;<\/strong><\/a> e si conclude il 30 agosto, sempre a Lorica, con Nicola Fiorita che illustra il libro &#8220;Blocco 52&#8221; e Anna Lauria con il libro d&#8217;arte: VISIONI PO.ETICHE calligrammi digitali e poesie visive. Il percorso di un poeta visivo negli anni, attraverso la contaminazione dei linguaggi: poesia, pittura, fotografia, digital art.<br \/>La giornata del 24 agosto e&#8217; caratterizzata da due tavole rotonde in cui si affrontano tematiche di considerevole importanza relativamente alla qualita&#8217; delle nostre vite in termini di salute e benessere. Nella mattinata, a Molarotta presso il centro visite A.R.S.A.C., si parlera&#8217; di &#8220;Turismo accessibile nella provincia di Cosenza ? work in progress ? Incontri per una provincia diversamente visitAbile&#8221;. Nello specifico si tratta di un momento di confronto su una tematica gia&#8217; affrontata nella scorsa edizione dello Slow Festival che dara&#8217; la possibilita&#8217; di fare un resoconto delle attivita&#8217; gia&#8217; avviate, ma anche di accogliere nuovi spunti di riflessione, puntando l&#8217;interesse sul rapporto &#8220;<strong>Sport e disabilita&#8217; nella qualita&#8217; dell&#8217;offerta turistica<\/strong>&#8220;. Nell&#8217;occasione s&#8217;incontreranno rappresentanti istituzionali di Enti e di Parchi, associazioni del settore, professori universitari e soggetti appartenenti a varie associazioni del mondo del volontariato che hanno gia&#8217; aderito all&#8217;iniziativa. A questo momento fara&#8217; seguito, sempre nella stessa giornata, alle ore 18.00 a Lorica, la tavola rotonda dal titolo &#8220;<strong>La Medicina Narrativa<\/strong>&#8221; un tema interessante e di attualita&#8217; che sara&#8217; affrontato da un nutrito tavolo di medici ed esperti del settore tra i quali segnaliamo il prof. Antonio Virzi&#8217; Presidente della Societa&#8217; Italiana di Medicina Narrativa. L&#8217;intento e&#8217; quello di portare l&#8217;attenzione del pubblico a questo nuovo approccio alla medicina che si va affermando e punta alla costruzione di un percorso di cura condiviso tra medici, operatori e pazienti per favorire lo sviluppo di una pratica clinica in cui i dati puramente scientifici siano integrati dalle narrazioni dei malati. Il 26 agosto comincia un&#8217;altra delle iniziative in programma nell&#8217;ambito della sezione del festival dal titolo &#8220;<strong>Officina degli Scrittori, Scuola del Racconto di Viaggio<\/strong>&#8220;. In continuita&#8217; con l&#8217;esperienza delle scorse edizioni, anche quest&#8217;anno si e&#8217; voluto fortemente riproporre questo appuntamento culturale unico nel panorama calabrese teso a diventare punto di riferimento per l&#8217;incontro, il confronto e l&#8217;approfondimento delle attivita&#8217; espressive quali la fotografia, la scrittura, il carnet di viaggio e il video intese non solo come forme artistiche, ma anche come mezzi per incentivare la promozione del territorio. Quest&#8217;anno, in particolare, i lavori saranno finalizzati alla realizzazione del progetto &#8220;Il cammino di Gioacchino da Fiore&#8221; con la partecipazione di alcuni componenti della Scuola del Viaggio di Milano che si affiancheranno ai partecipanti lungo un percorso esperenziale attraverso i principali luoghi che hanno segnato la vita e le opere dell&#8217;abate.<br \/>L&#8217;iniziativa continuera&#8217; poi nei giorni 27 e 28 agosto. Nelle giornate del 30 e 31 agosto si svolgera&#8217; la &#8220;<strong>Gran Festa Nazionale dei Formaggi<\/strong>&#8221; che si apre alle 10,30 a Lorica, con la tavola rotonda dal tema &#8220;I formaggi ovi-caprini, peculiarita&#8217; nutrizionali e alimentari&#8221;. Saranno presenti esperti del settore oltre che una nutrita rappresentanza di allevatori della capra rustica calabrese. Sempre nella stessa giornata del 30 agosto alle ore 20,00 e&#8217; il momento di soddisfare anche il palato con il &#8220;Simposio del gusto&#8221; dove naturalmente saranno protagonisti i formaggi ovi-caprini calabresi accompagnati da buon pane ed ottimo vino. Il &#8220;<strong>Simposio del gusto<\/strong>&#8221; sara&#8217; ripetuto anche il giorno successivo alle ore 19.30. Le degustazioni saranno abilmente guidate da Mario Reda (assaggiatore ONAF Organizzazione Nazionale Assaggiatori di Formaggi) e da Walter Cricri&#8217; (Direttore INAP Istituto Nazionale Assaggiatori Pane). Il 31 agosto e&#8217; la volta di &#8220;<strong>LaborApp verso gli stati generali delle comunita&#8217; appenniniche<\/strong>&#8221; meeting dei delegati Slow Food delle regioni appenniniche che vedra&#8217; la presenza anche di Silvio Barbero vicepresidente nazionale di Slow Food ospite, tra l&#8217;altro, della tavola rotonda che si svolgera&#8217; successivamente, alle ore 16,00, con la partecipazione di: Istituzioni, Enti Locali, Universita&#8217;, Associazioni di Categoria, Ordini Professionali, Associazioni ambientaliste, culturali e sociali che si incontrano per prendere parte alla costruzione di un &#8220;<strong>Manifesto per la salvaguardia e la valorizzazione del patrimonio culturale e identitario della montagna appenninica<\/strong>&#8220;. Questa terza edizione dello Slow Festival si chiude il 31 agosto con l&#8217;evento &#8220;U munnu sona, u munnu abballa &#8221; incontro di danza popolare. Gli incontri in programma sono tutti gratuiti, tuttavia e&#8217; opportuno ricordare a quanti vogliano partecipare alle iniziative inserite nelle sezioni &#8220;Sila Naturalmente Benessere&#8221; e &#8220;<strong>Officina degli Scrittori. Scuola del Racconto di Viaggio<\/strong>&#8221; che e&#8217; indispensabile, per ovvie esigenze organizzative, inviare una mail al seguente indirizzo <a href=\"mailto:info@slowfestival.it\">info@slowfestival.it<\/a> nel piu&#8217; breve tempo possibile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LORICA &#8211; Parte oggi l&#8217;edizione 2013 di &#8220;Slow Festival elogio alla lentezza&#8221;, evento all&#8217;interno dell&#8217;articolato programma di Transumanze Sila Festival organizzato dalla Provincia di Cosenza e caratterizzato da un ricco cartellone di appuntamenti che vanno dal 2 agosto al 15 settembre.<\/p>\n","protected":false},"author":22,"featured_media":25378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[19],"class_list":["post-25377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=25377"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/25378"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=25377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=25377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=25377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}