{"id":253842,"date":"2025-03-15T17:30:48","date_gmt":"2025-03-15T16:30:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=253842"},"modified":"2025-03-15T17:48:46","modified_gmt":"2025-03-15T16:48:46","slug":"algieri-riconfermato-nellassemblea-nazionale-di-confcommercio-premiato-limpegno-sin-qui-svolto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/algieri-riconfermato-nellassemblea-nazionale-di-confcommercio-premiato-limpegno-sin-qui-svolto\/","title":{"rendered":"Algieri riconfermato nell\u2019Assemblea Nazionale di Confcommercio: \u00abpremiato l\u2019impegno sin qui svolto\u00bb"},"content":{"rendered":"<p>COSENZA \u2013 La riconferma di <strong>Klaus Algieri<\/strong> nell\u2019<strong>Assemblea Nazionale di Confcommercio<\/strong> che ha visto anche la rielezione per acclamazione di <strong>Carlo Sangalli<\/strong> alla presidenza nazionale, conferma il lavoro positivo sin qui svolto sul territorio.<\/p>\n<p>Ma c\u2019\u00e8 di pi\u00f9, come ha sottolineato orgoglioso lo stesso Algieri, \u201cl\u2019intera regione sar\u00e0 ben rappresentata nell\u2019<strong>Assemblea Nazionale<\/strong>, grazie all\u2019ingresso del rappresentante della Calabria centrale e di Reggio Calabria. Un risultato &#8211; prosegue Algieri \u2013 che ci consente di fare rete e lavorare sinergicamente per le imprese calabresi \u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 La riconferma di Klaus Algieri nell\u2019Assemblea Nazionale di Confcommercio che ha visto anche la rielezione per acclamazione di Carlo Sangalli alla presidenza nazionale, conferma il lavoro positivo sin qui svolto sul territorio. Ma c\u2019\u00e8 di pi\u00f9, come ha sottolineato orgoglioso lo stesso Algieri, \u201cl\u2019intera regione sar\u00e0 ben rappresentata nell\u2019Assemblea Nazionale, grazie all\u2019ingresso del [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":253843,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19,135],"class_list":["post-253842","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/253842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=253842"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/253842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/253843"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=253842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=253842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=253842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}