{"id":254069,"date":"2025-03-17T20:26:21","date_gmt":"2025-03-17T19:26:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=254069"},"modified":"2025-03-17T20:26:21","modified_gmt":"2025-03-17T19:26:21","slug":"maxi-sequestrato-di-bianchetto-lungo-la-statale-106-quasi-200-chili-pescati-illegalmente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/maxi-sequestrato-di-bianchetto-lungo-la-statale-106-quasi-200-chili-pescati-illegalmente\/","title":{"rendered":"Maxi sequestrato di &#8220;bianchetto&#8221; lungo la Statale 106: quasi 200 chili pescati illegalmente"},"content":{"rendered":"<p>CRUCOLI (KR) &#8211; Nel corso di un\u2019attivit\u00e0 di controllo lungo la Statale 106, nella frazione Torretta del Comune di Crucoli,<strong> i militari della Capitaneria di Porto hanno fermato un autoveicolo refrigerato<\/strong> diretto a Sud. All\u2019interno del mezzo, accuratamente nascosti in cassette di polistirolo, sono stati <strong>rinvenuti ben 190 chilogrammi di novellame di sardina, pescato illegalmente<\/strong>.\u00a0Immediato \u00e8 s<strong>cattato il sequestro del prodotto ittico, nonch\u00e9 una sanzione amministrativa di 10.000 euro inflitta al conducente del veicolo<\/strong> per trasporto di esemplari ittici sotto la taglia minima consentita, in violazione della normativa vigente sulla pesca.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/Bovellama-di-Sarda.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-254071 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/Bovellama-di-Sarda.jpg\" alt=\"Novellama di Sarda bianchetto sequestrato\" width=\"505\" height=\"342\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/Bovellama-di-Sarda.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/Bovellama-di-Sarda-300x203.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/Bovellama-di-Sarda-768x519.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/Bovellama-di-Sarda-621x420.jpg 621w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/Bovellama-di-Sarda-150x101.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/Bovellama-di-Sarda-696x471.jpg 696w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/a><\/p>\n<p>Il prodotto sequestrato, sottoposto ai controlli del Servizio Veterinario dell\u2019ASP di Crotone, \u00e8 stato <strong>dichiarato non idoneo al consumo umano per l\u2019impossibilit\u00e0 di tracciarne la provenienza<\/strong> e, pertanto, distrutto secondo le procedure di legge.\u00a0Si tratta di un altro importante risultato nell\u2019ambito delle attivit\u00e0 di polizia marittima della Guardia Costiera crotonese, che<strong> dall\u2019inizio dell\u2019anno ha gi\u00e0 sequestrato circa 600 kg di novellame di sardina,<\/strong> a conferma dell\u2019intensificarsi dei controlli contro un fenomeno che rappresenta una minaccia concreta per l\u2019ecosistema marino e per l\u2019equilibrio della fauna ittica.<\/p>\n<p>La Guardia Costiera ricorda che la pesca e la vendita del novellame rappresentano non solo un illecito, ma <strong>un danno gravissimo alla biodiversit\u00e0 marina<\/strong>, minacciando la riproduzione delle specie e l\u2019intero comparto della pesca regolare. I controlli continueranno con la massima attenzione su tutto il territorio, anche per tutelare la salute pubblica e il rispetto della legalit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CRUCOLI (KR) &#8211; Nel corso di un\u2019attivit\u00e0 di controllo lungo la Statale 106, nella frazione Torretta del Comune di Crucoli, i militari della Capitaneria di Porto hanno fermato un autoveicolo refrigerato diretto a Sud. All\u2019interno del mezzo, accuratamente nascosti in cassette di polistirolo, sono stati rinvenuti ben 190 chilogrammi di novellame di sardina, pescato illegalmente.\u00a0Immediato [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":254070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-254069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/254069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=254069"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/254069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/254070"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=254069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=254069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=254069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}