{"id":254260,"date":"2025-03-19T17:27:10","date_gmt":"2025-03-19T16:27:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=254260"},"modified":"2025-03-19T17:27:10","modified_gmt":"2025-03-19T16:27:10","slug":"falconara-albanese-usb-muraca-srl-inadempiente-operai-senza-stipendio-da-4-mesi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/falconara-albanese-usb-muraca-srl-inadempiente-operai-senza-stipendio-da-4-mesi\/","title":{"rendered":"Falconara Albanese, USB \u00abMuraca Srl inadempiente, operai senza stipendio da 4 mesi\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Il sindacato USB Lavoro Privato Cosenza denuncia pubblicamente la <strong>grave inadempienza della ditta Muraca Srl, che da quattro mesi non eroga gli stipendi ai propri lavoratori<\/strong>, lasciandoli in una condizione di estrema difficolt\u00e0 economica e sociale. La Muraca Srl svolge in diversi comuni in Calabria i servizi di gestione dei rifiuti e di igiene urbana. &#8220;Questa situazione \u00e8 <strong>inaccettabile<\/strong> e rappresenta una <strong>palese violazione degli obblighi contrattuali previsti dal CCNL Igiene Ambientale<\/strong>, che stabilisce chiaramente il diritto dei lavoratori a ricevere la retribuzione nei tempi e nei modi concordati&#8221;.<\/p>\n<h4><strong>&#8220;L&#8217;azienda si rifugia dietro ai ritardi del Comune&#8221;<\/strong><\/h4>\n<p>&#8220;Ma il problema non \u00e8 solo della Muraca Srl. Il <strong>Comune di Falconara Albanese<\/strong> ha il <strong>dovere<\/strong> di <strong>vigilare sugli appalti pubblici<\/strong> e garantire che i lavoratori impiegati nei servizi essenziali vengano retribuiti regolarmente. Invece, assistiamo a uno scontro tra amministrazione comunale e azienda, di cui stanno pagando il prezzo gli operai, abbandonati senza stipendio e senza certezze. Inoltre, <strong>l\u2019azienda non pu\u00f2 rifugiarsi dietro ai ritardi di pagamento del Comune per giustificare il mancato pagamento degli stipendi<\/strong>. Il rapporto di lavoro tra Muraca Srl e i propri operai esiste e sussiste indipendentemente dalle vicende legate all\u2019appalto. \u00c8 un preciso dovere del datore di lavoro garantire il salario ai dipendenti, senza scaricare su di loro le proprie difficolt\u00e0 economiche o gestionali.<\/p>\n<p>&#8220;Ricordiamo all\u2019amministrazione comunale &#8211; prosegue il sindacato &#8211; che <strong>questi lavoratori sono cittadini di Falconara Albanese<\/strong>, persone che garantiscono ogni giorno la pulizia e il decoro del paese, e che meritano rispetto. Il Comune deve schierarsi senza ambiguit\u00e0 dalla parte di chi lavora, assumendosi le proprie responsabilit\u00e0 e intervenendo per risolvere la situazione. Abbiamo gi\u00e0 segnalato questa vergognosa condotta all\u2019Ispettorato Territoriale del Lavoro (ITL) e, se entro questa settimana non arriveranno risposte e soluzioni concrete, USB <strong>proclamer\u00e0 lo stato di agitazione fino ad arrivare allo sciopero&#8221;.<\/strong><\/p>\n<p>&#8220;I lavoratori non sono pi\u00f9 disponibili a garantire il servizio per il bene della cittadinanza senza essere retribuiti. Non si pu\u00f2 pretendere che chi lavora per garantire l&#8217;igiene pubblica e la sicurezza della comunit\u00e0 debba continuare a subire in silenzio il mancato pagamento del proprio salario. USB chiede l\u2019immediato pagamento degli stipendi arretrati e annuncia che, in assenza di risposte, <strong>saranno messe in atto tutte le iniziative sindacali e legali necessarie per tutelare i lavoratori e i loro diritti<\/strong>. Non resteremo in silenzio davanti a questa ennesima ingiustizia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il sindacato USB Lavoro Privato Cosenza denuncia pubblicamente la grave inadempienza della ditta Muraca Srl, che da quattro mesi non eroga gli stipendi ai propri lavoratori, lasciandoli in una condizione di estrema difficolt\u00e0 economica e sociale. La Muraca Srl svolge in diversi comuni in Calabria i servizi di gestione dei rifiuti e di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":254263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-254260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/254260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=254260"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/254260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/254263"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=254260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=254260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=254260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}