{"id":254377,"date":"2025-03-20T21:00:52","date_gmt":"2025-03-20T20:00:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=254377"},"modified":"2025-03-20T20:24:39","modified_gmt":"2025-03-20T19:24:39","slug":"ahmed-grave-malato-di-tumore-dimenticato-nel-carcere-di-reggio-cucchi-interroga-il-governo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ahmed-grave-malato-di-tumore-dimenticato-nel-carcere-di-reggio-cucchi-interroga-il-governo\/","title":{"rendered":"Ahmed, grave malato di tumore dimenticato nel carcere di Reggio. Cucchi interroga il governo"},"content":{"rendered":"<p>ROMA\u00a0 &#8211; &#8220;In Italia i migranti detenuti sono gli ultimi tra gli ultimi, privati delle cure essenziali e abbandonati nell&#8217;indifferenza. La vicenda di Habashy Rashed Hassan Arafa, detto Ahmed, ne \u00e8 una tragica conferma. <strong>Gravemente malato di tumore, \u00e8 rimasto per ben cinque anni dietro le sbarre del carcere di Reggio Calabria,<\/strong> invisibile, senza visite specialistiche, n\u00e9 assistenza adeguata, ostacolato da barriere linguistiche e dall&#8217;incapacit\u00e0 del sistema penitenziario di tutelare i pi\u00f9 vulnerabili. <strong>Solo quando era ormai troppo tardi \u00e8 stato visitato e grazie<\/strong> <strong><a href=\"https:\/\/quicosenza.it\/news\/calabria\/detenuto-malato-terminale-ignorato-fino-allultimo-giorno-di-pena-lucano-chiede-giustizia-in-europa\" target=\"_blank\" rel=\"noopener\">all&#8217;intervento di Mimmo Lucano<\/a><\/strong>, Ahmed ora potr\u00e0 trascorrere gli ultimi giorni della sua vita con dignit\u00e0 nel Villaggio Globale di Riace. Su questa storia di violazione dei diritti umani esigiamo una spiegazione dal governo Meloni. Per questo abbiamo presentato un&#8217;interrogazione ai ministri della Giustizia e della Salute, Carlo Nordio e Orazio Schillaci, per fare piena luce e chiedere misure concrete affinch\u00e9 simili tragedie non si ripetano mai pi\u00f9&#8221;. Lo afferma la senatrice dell&#8217;Alleanza Verdi e Sinistra Ilaria Cucchi, che sul caso ha presentato un&#8217;interrogazione ai ministri Nordio e Schillaci.<\/p>\n<p>&#8220;\u00c8 indispensabile<strong> garantire mediatori culturali in ogni carcere, rafforzare il diritto all&#8217;assistenza sanitaria per tutti i detenuti e investire nella sanit\u00e0 pubblica<\/strong>, soprattutto nel Mezzogiorno, dove le criticit\u00e0 sono pi\u00f9 gravi, prosegue Cucchi. Inoltre, va riconosciuto e sostenuto il lavoro delle realt\u00e0 del terzo settore, come il Villaggio Globale di Riace, che suppliscono alle gravi carenze dello Stato. Ignorare la sofferenza di chi \u00e8 gi\u00e0 ai margini \u00e8 inaccettabile. La giustizia non pu\u00f2 e non deve essere disumana, il diritto alla salute deve valere per tutti, senza eccezioni&#8221; conclude Cucchi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA\u00a0 &#8211; &#8220;In Italia i migranti detenuti sono gli ultimi tra gli ultimi, privati delle cure essenziali e abbandonati nell&#8217;indifferenza. La vicenda di Habashy Rashed Hassan Arafa, detto Ahmed, ne \u00e8 una tragica conferma. Gravemente malato di tumore, \u00e8 rimasto per ben cinque anni dietro le sbarre del carcere di Reggio Calabria, invisibile, senza visite [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":254378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-254377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/254377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=254377"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/254377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/254378"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=254377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=254377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=254377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}