{"id":255241,"date":"2025-03-30T10:02:33","date_gmt":"2025-03-30T08:02:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=255241"},"modified":"2025-03-30T10:02:33","modified_gmt":"2025-03-30T08:02:33","slug":"denunciato-dalla-figlia-per-maltrattamenti-padre-assolto-dal-tribunale-di-castrovillari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/denunciato-dalla-figlia-per-maltrattamenti-padre-assolto-dal-tribunale-di-castrovillari\/","title":{"rendered":"Denunciato dalla figlia per maltrattamenti, padre assolto dal tribunale di Castrovillari"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Si conclude la vicenda che riguarda <strong>un 60enne rossanese e la propria compagna,<\/strong> difesi dagli <strong>avvocati Francesco Nicoletti e Giusy Acri,<\/strong> processati dinanzi al Tribunale di Castrovillari per i<strong> gravissimi reati di maltrattamenti e lesioni aggravate ai danni della figlia dell\u2019uomo<\/strong>,<strong> abitante nella stessa casa dopo la separazione dei genitori.<\/strong><\/p>\n<p>A dare origine al processo la<strong> denuncia presentata dalla ragazza contro il padre e la sua convivente<\/strong> che, in concorso tra loro, con reiterate condotte vessatorie, violente e minacciose, si sarebbero resi autori di maltrattamenti e, in alcune occasioni, anche di aggressioni fisiche a seguito delle quali avrebbe riportato lesioni refertate dal Pronto Soccorso dell\u2019Ospedale di Rossano.<\/p>\n<p>Costituitasi parte civile, al fine di insistere nella condanna penale del padre e della compagna e ottenere un congruo risarcimento dei danni da parte di entrambi, la ragazza \u00e8 stata escussa nel corso del dibattimento in aula, dove ha confermato tutte le accuse precedentemente denunciate. In qualit\u00e0 di testi indicati dalla pubblica accusa sono state sentite dal Tribunale pure la sorella della ragazza, anche lei figlia dell\u2019imputato, e la ex moglie. Entrambe hanno dato manforte alla versione accusatoria rendendo dichiarazioni contro entrambi gli imputati. Nel corso del processo sono stati poi escussi anche i testi indicati dalla difesa, che ha altres\u00ec prodotto una relazione tecnica, corredata da foto, redatta da un ingegnere, con cui veniva rappresentato l\u2019esatto stato dei luoghi.<\/p>\n<p>Al termine dell\u2019istruttoria dibattimentale il Pubblico Ministero ha chiesto la condanna per entrambi gli imputati alla pena di anni 2 di reclusione. Richiesta a cui si \u00e8 associata la parte civile, chiedendo anche la condanna dei due al risarcimento dei danni e al pagamento delle spese legali sostenute dalla ragazza.<\/p>\n<p>Il Tribunale di Castrovillari, all\u2019esito della camera di consiglio, in totale accoglimento delle richieste avanzate dagli avvocati Francesco Nicoletti e Giusy Acri, ha emesso sentenza di assoluzione nei confronti degli imputati con la formula pi\u00f9 ampia: perch\u00e9 il fatto non sussiste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Si conclude la vicenda che riguarda un 60enne rossanese e la propria compagna, difesi dagli avvocati Francesco Nicoletti e Giusy Acri, processati dinanzi al Tribunale di Castrovillari per i gravissimi reati di maltrattamenti e lesioni aggravate ai danni della figlia dell\u2019uomo, abitante nella stessa casa dopo la separazione dei genitori. A dare [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":181955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-255241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/255241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=255241"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/255241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/181955"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=255241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=255241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=255241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}