{"id":255384,"date":"2025-04-01T10:00:12","date_gmt":"2025-04-01T08:00:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=255384"},"modified":"2025-04-01T09:38:52","modified_gmt":"2025-04-01T07:38:52","slug":"cosenza-nella-sede-di-confcommercio-presentata-la-giornata-della-ristorazione-2025","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-nella-sede-di-confcommercio-presentata-la-giornata-della-ristorazione-2025\/","title":{"rendered":"Cosenza, nella sede di Confcommercio presentata la &#8216;Giornata della Ristorazione 2025&#8217;"},"content":{"rendered":"<p>COSENZA \u2013 E\u2019 stata presentata presso la sede di Confcommercio Cosenza la Giornata della Ristorazione edizione 2025, che il\u00a0<strong>17 maggio<\/strong>\u00a0vedr\u00e0 ristoranti e locali di tutta Italia celebrare la cultura dell\u2019ospitalit\u00e0 e della condivisione attraverso il cibo. l\u2019iniziativa nazionale promossa da\u00a0Fipe-Confcommercio, ha visto la partecipazione di Davide Rampello direttore creativo della <strong>Rampello &amp; Partners<\/strong> e che da diversi anni cura per Striscia la Notizia la rubrica: \u201cPaesi, Paesaggi\u201d<\/p>\n<p>La\u00a0<strong>Giornata della Ristorazione 2025<\/strong>\u00a0ha l\u2019obiettivo di valorizzare la cultura dell\u2019accoglienza e della condivisione attraverso il cibo. Per l\u2019occasione, i ristoranti aderenti proporranno piatti dedicati all\u2019uovo, esaltandone la ricchezza gastronomica e simbolica.\u00a0<em>\u201c<\/em>La Giornata della Ristorazione non \u00e8 solo un evento, ma un\u2019occasione per ribadire il ruolo centrale della ristorazione nella cultura e nella societ\u00e0\u201d, ha sottolineato\u00a0<strong>Laura Barbieri<\/strong>, Presidente di\u00a0<strong>Fipe Confcommercio Cosenza<\/strong>.\u00a0\u201cL\u2019uovo, scelto come simbolo di questa edizione, rappresenta perfettamente il legame tra tradizione e innovazione in cucina.\u201d<\/p>\n<p>Un altro argomento di grande rilievo \u00e8 stato il rapporto tra i giovani e l\u2019alimentazione. In un\u2019epoca di cambiamenti negli stili di vita e nelle abitudini alimentari, l\u2019educazione al cibo diventa un elemento fondamentale per garantire una maggiore consapevolezza e benessere nelle nuove generazioni.<\/p>\n<p><em>\u201c<\/em>Sosteniamo con convinzione questa iniziativa che non solo valorizza il settore della ristorazione, ma promuove anche un messaggio di consapevolezza e educazione alimentare tra le nuove generazioni\u201d, ha dichiarato\u00a0<strong>Massimiliano Battaglia<\/strong>, Assessore alle attivit\u00e0 produttive della citt\u00e0 di Cosenza.<\/p>\n<p>L\u2019educazione alimentare \u00e8 stata un altro punto chiave del dibattito. L\u2019IC Spirito Santo sar\u00e0 protagonista di un progetto dedicato ai pi\u00f9 piccoli, volto a sensibilizzarli sull\u2019importanza di una dieta equilibrata e sulla conoscenza degli alimenti.\u00a0\u201cEducare i bambini al cibo significa fornire loro strumenti di conoscenza e consapevolezza\u201d, ha spiegato\u00a0<strong>Maria Luisa Morrone<\/strong>, dirigente dell\u2019<strong>IC Spirito Santo<\/strong>.\u00a0\u201cGrazie a questo progetto, gli studenti avranno la possibilit\u00e0 di comprendere meglio ci\u00f2 che mangiano e fare scelte pi\u00f9 responsabili.\u201d<\/p>\n<p>Per \u00a0<strong>Davide Rampello<\/strong>, <em>\u201c<\/em>la ristorazione italiana \u00e8 un patrimonio culturale, un tessuto vivo che intreccia storia, tradizioni e territori. Ogni piatto racconta un paesaggio, ogni ristorante \u00e8 una porta aperta sulla nostra identit\u00e0. Con la Giornata della Ristorazione celebriamo non solo il valore dell\u2019ospitalit\u00e0, ma anche l\u2019impegno di migliaia di imprenditori e artigiani del gusto che ogni giorno custodiscono e innovano il nostro straordinario patrimonio enogastronomico. \u00c8 un\u2019occasione per riflettere sul ruolo centrale della ristorazione nella valorizzazione delle eccellenze locali e nella promozione di un turismo autentico e sostenibile.\u201d<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 E\u2019 stata presentata presso la sede di Confcommercio Cosenza la Giornata della Ristorazione edizione 2025, che il\u00a017 maggio\u00a0vedr\u00e0 ristoranti e locali di tutta Italia celebrare la cultura dell\u2019ospitalit\u00e0 e della condivisione attraverso il cibo. l\u2019iniziativa nazionale promossa da\u00a0Fipe-Confcommercio, ha visto la partecipazione di Davide Rampello direttore creativo della Rampello &amp; Partners e che [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":255386,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19,135],"class_list":["post-255384","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/255384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=255384"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/255384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/255386"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=255384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=255384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=255384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}