{"id":25541,"date":"2013-08-28T08:20:00","date_gmt":"2013-08-28T06:20:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=25541"},"modified":"2023-01-17T13:23:06","modified_gmt":"2023-01-17T12:23:06","slug":"10396-pollino-due-terremoti-in-poco-piu-di-un-ora-torna-la-paura","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10396-pollino-due-terremoti-in-poco-piu-di-un-ora-torna-la-paura\/","title":{"rendered":"Pollino: due terremoti in poco pi\u00f9 di un&#8217;ora, torna la paura"},"content":{"rendered":"<p>LAINO BORGO &#8211; Due scosse sismiche a distanza di un&#8217;ora registrate al confine tra Calabria e Basilicata.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">La prima di magnitudo 2.2 \u00e8 stata registrata alle 09.06 dalla Rete sismica dell\u2019Istituto nazionale di geofisica e vulcanologia sul Monte Alpi-Sirino. L\u2019evento \u00e8 stato localizzato ad una profondit\u00e0 di 20.7 chilometri. I centri pi\u00f9 vicini all\u2019epicentro sono Castelluccio Inferiore, Castelluccio Superiore, Lauria in provincia di Potenza; Laino Borgo, Laino Castello, in provincia di Cosenza. La seconda scossa di terremoto, dopo circa un\u2019ora dalla prima, di magnitudo 2.2, \u00e8 stata registrata alle 10.12 dalla Rete sismica dell\u2019Istituto nazionale di geofisica e vulcanologia nella stessa area della prima. L\u2019evento \u00e8 stato localizzato ad una profondit\u00e0 di 22.3 chilometri. Anche in questo caso i centri pi\u00f9 vicini all\u2019epicentro sono Castelluccio Inferiore e Castelluccio Superiore, in provincia di Potenza; Laino Borgo e Laino Castello, in provincia di Cosenza.<\/p>\n<p>&nbsp;<\/p>\n<p><br class=\"titolo_articolo titolo\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAINO BORGO &#8211; Due scosse sismiche a distanza di un&#8217;ora registrate al confine tra Calabria e Basilicata.<\/p>\n","protected":false},"author":22,"featured_media":25542,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-25541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=25541"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/25542"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=25541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=25541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=25541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}