{"id":25577,"date":"2013-08-29T11:17:56","date_gmt":"2013-08-29T09:17:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=25577"},"modified":"2023-01-17T13:23:08","modified_gmt":"2023-01-17T12:23:08","slug":"10414-bambino-nato-con-meta-cuore-salvato-dal-nuoto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10414-bambino-nato-con-meta-cuore-salvato-dal-nuoto\/","title":{"rendered":"Bambino nato con met\u00e0 cuore salvato dal nuoto"},"content":{"rendered":"<p><strong>Charlie Cobb<\/strong>, a causa di una rara cardiopatia congenita, poche ore dopo la nascita, \u00e8 stato sottoposto ad un delicato intervento chirurgico a cuore aperto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Prima dell\u2019intervento i chirurghi hanno avvertito i genitori che avrebbe potuto non farcela.<\/p>\n<p>Dopo la prima operazione il bimbo ha avuto un attacco di cuore, sottoposto successivamente ad altri <strong>due interventi<\/strong> \u00e8 stato ricoverato innumerevoli volte per combattere le infezioni.<br \/>Ma da quando la giovane mamma <strong>Louise Bushby<\/strong>, lo ha portato in piscina per la prima volta, il bimbo che aveva <strong>nove mesi<\/strong> ha cominciato a fare grandi progressi. \u201c<em>Sembra proprio migliorare a vista d\u2019occhio quando \u00e8 in acqua e i suoi progressi si sono visti fin dal primo giorno. Non sono un medico, ma io vedo che la piscina lo aiuta cos\u00ec tanto per il suo recupero che ci vado ogni settimana. Quando siamo in giro resta facilmente senza fiato \u2013 ma non in piscina. L\u2019acqua gli d\u00e0 il supporto necessario e lo rende pi\u00f9 forte. Non sono una cardiologa, ma l\u2019acqua gli ha fatto fare un enorme passo avanti nella giusta direzione. I suoi cardiologi non possono credere quanto bene gli stia facendo, e molto spesso, quando lo portiamo per le visite, le infermiere non credono che in realt\u00e0 ha la condizione che ha<\/em>\u201c.<\/p>\n<p>Mamma <strong>Louise <\/strong>e pap\u00e0 <strong>Dan Cobb<\/strong>, avevano scoperto alla ventesima settimana di gravidanza che il bimbo che la donna portava in grembo aveva la <strong>sindrome del cuore ipoplasico<\/strong> (<span style=\"text-decoration: underline;\">il ventricolo sinistro del cuore non pompa sangue<\/span>). <br \/>A quel punto i medici chiesero alla coppia di prendere una decisione: se continuare o meno la gravidanza. <br \/>Nonostante al piccolo fosse stata data solo un 50% di possibilit\u00e0 di sopravvivenza decisero di volerlo tenere lo stesso.<\/p>\n<p>Il piccolo <strong>Charlie<\/strong> \u00e8 stato sottoposto alla sua prima operazione di chirurgia a cuore aperto quando aveva un giorno di vita, e ha recuperato molto bene. <br \/>Un\u2019ora prima di essere dimesso, il piccolo ha avuto un arresto cardiaco mentre era in braccio a sua madre ed \u00e8 stato ricoverato in terapia intensiva. La mamma racconta: \u201c<em>I medici non pensavano che Charlie si risvegliasse dopo l\u2019arresto cardiaco ed \u00e8 stato ricoverato in terapia intensiva per tre settimane prima che ci permettessero di portarlo a casa. Lui avr\u00e0 sempre la met\u00e0 del cuore, ma pare stare cos\u00ec bene ora che ha 17 mesi, cammina e chiacchiera. E naturalmente va a nuoto<\/em>\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charlie Cobb, a causa di una rara cardiopatia congenita, poche ore dopo la nascita, \u00e8 stato sottoposto ad un delicato intervento chirurgico a cuore aperto.<\/p>\n","protected":false},"author":22,"featured_media":25578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,52],"tags":[],"class_list":["post-25577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=25577"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/25578"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=25577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=25577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=25577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}