{"id":255993,"date":"2025-04-08T13:30:12","date_gmt":"2025-04-08T11:30:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=255993"},"modified":"2025-04-08T13:52:17","modified_gmt":"2025-04-08T11:52:17","slug":"mare-pulito-in-calabria-task-force-contro-la-maladepurazione-con-luso-di-gps-battelli-droni-e-radar","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/mare-pulito-in-calabria-task-force-contro-la-maladepurazione-con-luso-di-gps-battelli-droni-e-radar\/","title":{"rendered":"Mare pulito in Calabria: task force contro la maladepurazione con l&#8217;uso di Gps, battelli, droni e radar"},"content":{"rendered":"<p>CATANZARO &#8211; \u201cTolleranza zero\u201d in tema di<strong> contrasto ai reati e agli illeciti ambientali e la mala depurazione. Una task force per il mare pulito in Calabria<\/strong> in vista della prossima stagione estiva.\u00a0Il presidente della Regione Calabria Roberto Occhiuto e l\u2019assessore all\u2019Ambiente, Giovanni Calabrese, hanno organizzato questa mattina, presso la Cittadella regionale, un in<strong>contro interistituzionale sul programma di interventi<\/strong> della Giunta, i<strong>n corso e per la prossima stagione estiva<\/strong>, relativi alla <strong>tutela del mare, al miglioramento delle acque di balneazione e della depurazione<\/strong>. L\u2019organizzazione delle attivit\u00e0 previste e in atto coinvolge diversi soggetti istituzionali: il Dipartimento Ambiente, l\u2019Ufficio unico del commissario della depurazione, Calabria Verde, Arpacal, i Comuni, la stazione Anton Dorhn, Sorical e Arrical.<\/p>\n<p><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/KByBZhCj8T8?si=Vw6RLAcfjzEEVKrL\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Hanno preso parte al tavolo odierno i prefetti della Calabria, <strong>i procuratori di Vibo Valentia, Lamezia Terme, e Paola, i comandanti della Legione dei carabinieri Calabria, del comando regionale della Guardia di Finanza, della Capitaneria di Porto di Gioia Tauro, il direttore generale di Arpacal e il direttore della stazione zoologica Anton Dohrn<\/strong>.<\/p>\n<h3>Mare pulito in Calabria: le attivit\u00e0 della Regione<\/h3>\n<p>Durante la riunione sono state presentate<strong> le attivit\u00e0 svolte dalla Regione gi\u00e0 da settembre 2024 in vista della stagione estiva 2025<\/strong>. Azioni coordinate e complesse tra cui il <strong>monitoraggio Gps degli autospurghi<\/strong>, il <strong>sopralluogo degli impianti di depurazione,<\/strong> l\u2019analisi delle segnalazioni prevenienti dalle associazioni ambientaliste, la pulizia dei corsi d\u2019acqua, gli interventi con bioattivatori sui torrenti, il confronto costante con i Comuni. Un lavoro che \u00e8 stato messo in campo fin dal 2022 e che ha consentito nel corso degli anni notevoli risultati tra cui u<strong>n incremento considerevole dello smaltimento dei fanghi<\/strong>, maggiore efficientamento degli impianti di depurazione, progressiva pulizia di alvei (294 solo nel 2025), campionamenti di analisi straordinarie e monitoraggio costiero esteso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-255996 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-droni.jpg\" alt=\"\" width=\"501\" height=\"310\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-droni.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-droni-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-droni-768x476.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-droni-678x420.jpg 678w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-droni-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-droni-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-droni-356x220.jpg 356w\" sizes=\"auto, (max-width: 501px) 100vw, 501px\" \/><\/p>\n<h3>Efficientamento degli impianti di depurazione<\/h3>\n<p>La Regione, solo per il 2025, ha gi\u00e0 messo in campo <strong>15 milioni di euro per l\u2019efficientamento degli <a href=\"https:\/\/quicosenza.it\/news\/provincia\/328203-impianti-depurazione-in-arrivo-16-milioni-per-tre-comuni-del-cosentino\" target=\"_blank\" rel=\"noopener\">impianti di depurazione<\/a> attraverso <a href=\"https:\/\/www.soricalspa.com\/\" target=\"_blank\" rel=\"noopener\">Sorical,<\/a><\/strong> oltre a <strong>121 milioni di euro provenienti da Por, Fsc, e fondi Pnrr per 51 interventi complessivi<\/strong>. Il programma di interventi si compone anche del supporto del monitoraggio innovativo con sonda Sar per l\u2019individuazione delle condotte abusive, un\u2019attivit\u00e0 ad alta tecnologia realizzata con droni a lungo raggio dotati di sonda radar e dai<a href=\"https:\/\/quicosenza.it\/news\/calabria\/tornano-in-azione-i-pulisci-mare-allopera-una-flotta-di-6-battelli-foto\" target=\"_blank\" rel=\"noopener\"><strong> battelli antinquinamento<\/strong><\/a> <strong>&#8220;Sistema Pelikan&#8221;,<\/strong> che, insieme a <strong>droni e row<\/strong>, e a una serie di altre azioni collegate, hanno fatto da deterrente contribuendo a diminuire gli sversamenti a mare durante i mesi di servizio dei battelli rispetto agli anni scorsi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-255997 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-enti.jpg\" alt=\"\" width=\"529\" height=\"335\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-enti.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-enti-300x190.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-enti-768x486.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-enti-664x420.jpg 664w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-enti-150x95.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Maladepurazione-enti-696x441.jpg 696w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/p>\n<p>Durante l\u2019incontro odierno \u00e8 stato ribadito <strong>l\u2019impegno della Regione Calabria contro la maladepurazione e per la salvaguardia ambientale<\/strong>, con una strategia di interventi finalizzati all<strong>\u2019ottimizzazione e al riefficientamento degli impianti di depurazione dei Comuni costieri<\/strong>, attraverso la sostituzione o la riparazione di pompe di sollevamento, lo smaltimento e il trattamento dei fanghi di depurazione e delle sabbie, il ripristino di parti elettromeccaniche dei depuratori, la fornitura e la posa in opera di apparecchiature elettromeccaniche, degli impianti di sollevamento, di serbatoi di stoccaggio e di reagenti dei sistemi depurativi.\u00a0Gli interventi &#8211; realizzati con risorse regionali <strong>&#8211; hanno coinvolto oltre 500 tra impianti di depurazione e stazioni di sollevamento<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; \u201cTolleranza zero\u201d in tema di contrasto ai reati e agli illeciti ambientali e la mala depurazione. Una task force per il mare pulito in Calabria in vista della prossima stagione estiva.\u00a0Il presidente della Regione Calabria Roberto Occhiuto e l\u2019assessore all\u2019Ambiente, Giovanni Calabrese, hanno organizzato questa mattina, presso la Cittadella regionale, un incontro interistituzionale [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":255994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-255993","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/255993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=255993"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/255993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/255994"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=255993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=255993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=255993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}