{"id":256074,"date":"2025-04-09T16:00:02","date_gmt":"2025-04-09T14:00:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=256074"},"modified":"2025-04-09T13:53:35","modified_gmt":"2025-04-09T11:53:35","slug":"dulbecco-concorso-per-tre-dirigenti-medici-in-chirurgia-pediatrica-prenderanno-servizio-il-1-maggio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/dulbecco-concorso-per-tre-dirigenti-medici-in-chirurgia-pediatrica-prenderanno-servizio-il-1-maggio\/","title":{"rendered":"Dulbecco: concorso per tre dirigenti medici in chirurgia pediatrica, prenderanno servizio il 1\u00b0 maggio"},"content":{"rendered":"<p>CATANZARO \u2013 \u00c8 stato espletato lo scorso <strong>2 aprile<\/strong> il <strong>concorso pubblico<\/strong> per l\u2019assunzione di tre dirigenti medici in chirurgia pediatrica presso l\u2019Azienda Ospedaliera Universitaria \u201cRenato Dulbecco\u201d di Catanzaro. Si tratta di un passo concreto e strategico verso il potenziamento della <strong>Struttura Complessa di Chirurgia Pediatrica<\/strong>, presidio fondamentale per la cura e l\u2019assistenza dei piccoli pazienti calabresi.<\/p>\n<p>L\u2019assunzione dei nuovi professionisti \u2013 che prenderanno servizio a partire dal 1\u00b0 maggio 2025 \u2013 rientra in un pi\u00f9 ampio progetto di sviluppo fortemente promosso dalla Direzione Generale dell\u2019Azienda ospedaliero-universitaria \u201cRenato Dulbecco\u201d, guidata dalla dottoressa Simona Carbone. Elemento cardine di questa visione \u00e8 la recente convenzione con l\u2019Istituto \u201cGiannina Gaslini\u201d di Genova, uno dei centri pediatrici di eccellenza a livello internazionale.<\/p>\n<p>Tale accordo, esclusivamente riferito all\u2019ambito della chirurgia pediatrica, \u00e8 finalizzato a rafforzare la qualit\u00e0 dell\u2019assistenza e della formazione professionale, attraverso: l<strong>o sviluppo di programmi formativi condivisi;<\/strong> la <strong>promozione della mobilit\u00e0 e dello scambio di personale<\/strong> <strong>medico e sanitario<\/strong>; <strong>la creazione di percorsi di aggiornamento continuo; l\u2019elaborazione di progetti di ricerca congiunti e protocolli assistenziali innovativi.<\/strong><\/p>\n<p>\u201cStiamo lavorando con determinazione \u2013 ha dichiarato la dottoressa Carbone \u2013 per rendere operativo il protocollo nel pi\u00f9 breve tempo possibile. Il nostro obiettivo \u00e8 garantire interventi di chirurgia pediatrica altamente qualificati, valorizzando le competenze interne e attivando sinergie virtuose con strutture di eccellenza come il Gaslini. Questa convenzione si inserisce in un pi\u00f9 ampio impegno sull\u2019area pediatrica, gi\u00e0 al centro dell\u2019attenzione regionale anche attraverso la collaborazione con l\u2019Ospedale Bambino Ges\u00f9:<strong> i due accordi operano su ambiti distinti e complementari\u201d.<\/strong><\/p>\n<p>Il dottor Giuseppe Stranieri, Direttore della Struttura Complessa di Chirurgia Pediatrica, sottolinea l\u2019importanza di questo investimento: \u201c\u00c8 un segnale chiaro di attenzione verso la sanit\u00e0 pediatrica regionale. Vogliamo offrire ai bambini calabresi servizi all\u2019altezza dei migliori standard nazionali, riducendo la necessit\u00e0 di cure fuori regione e rafforzando la fiducia dei cittadini nel nostro sistema sanitario\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO \u2013 \u00c8 stato espletato lo scorso 2 aprile il concorso pubblico per l\u2019assunzione di tre dirigenti medici in chirurgia pediatrica presso l\u2019Azienda Ospedaliera Universitaria \u201cRenato Dulbecco\u201d di Catanzaro. Si tratta di un passo concreto e strategico verso il potenziamento della Struttura Complessa di Chirurgia Pediatrica, presidio fondamentale per la cura e l\u2019assistenza dei piccoli [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":256075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-256074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/256074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=256074"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/256074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/256075"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=256074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=256074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=256074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}