{"id":256168,"date":"2025-04-10T12:21:20","date_gmt":"2025-04-10T10:21:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=256168"},"modified":"2025-04-10T12:22:09","modified_gmt":"2025-04-10T10:22:09","slug":"elezioni-a-rende-rossella-gallo-e-la-candidata-sindaca-del-movimento-5-stelle","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/elezioni-a-rende-rossella-gallo-e-la-candidata-sindaca-del-movimento-5-stelle\/","title":{"rendered":"Elezioni a Rende: Rossella Gallo \u00e8 la candidata sindaca del Movimento 5 Stelle"},"content":{"rendered":"<p>RENDE &#8211; &#8220;Si chiude oggi una lunga fase di interlocuzione con le altre forze politiche, condotta con spirito costruttivo, responsabilit\u00e0 e apertura. Un percorso che, purtroppo, non ha prodotto gli esiti auspicati. A pesare sono state scelte personalistiche, rigidit\u00e0 e la proposta di candidature imposte, lontane dal metodo partecipativo e condiviso che avevamo auspicato. La nostra posizione non nasce da chiusure pregiudiziali, ma dal rifiuto netto di logiche che sviliscono il senso stesso dell&#8217;impegno civico&#8221;. A sostenerlo il Gruppo Territoriale Rende in particolare Giuseppe Giorno, Coordinatore Provinciale Cosenza e la deputata e coordinatrice regionale del M5S Anna Laura Orrico.<\/p>\n<p>&#8220;Abbiamo lavorato per costruire un&#8217;alternativa vera, che fosse espressione di un&#8217;identit\u00e0 politica chiara, coerente e radicata nel campo progressista, in linea con ci\u00f2 che il Movimento 5 Stelle rappresenta in Europa e in Italia. Non possiamo n\u00e9 vogliamo annacquare i nostri valori per sostenere proposte che, pur proclamandosi civiche o fintamente scelte dal popolo, si rivelano funzionali ad apparati logori o alle ambizioni di pochi. <strong>Rende merita di pi\u00f9&#8221;.<\/strong><\/p>\n<p>&#8220;\u00c8 per questo che oggi, con <strong>orgoglio e senso di responsabilit\u00e0, rivendichiamo il nostro ruolo in citt\u00e0<\/strong>. Un ruolo che in queste elezioni ci vede in prima linea nel campo progressista. In un contesto politico frammentato e inquinato da alleanze trasversali, la nostra proposta \u00e8 chiara: rappresentiamo l&#8217;alternativa vera al centrodestra, che a Rende ha governato direttamente o indirettamente negli ultimi vent&#8217;anni, e ai personalismi trasversali che hanno lasciato dietro di s\u00e9 solo macerie politiche, disastri finanziari e commissariamenti per mafia&#8221;.<\/p>\n<h3>Rossella Gallo<\/h3>\n<p>&#8220;Giovane professionista, avvocata, cittadina attiva e consapevole, \u00e8 per noi la figura ideale per rappresentare una proposta <strong>politica nuova, coraggiosa, pulita<\/strong>. La sua candidatura incarna una rivoluzione autentica: un cambiamento profondo, capace di parlare alla citt\u00e0 con sincerit\u00e0, competenza e passione. Una proposta che si rivolge a tutti e tutte, senza distinzioni, nel segno del rispetto, della giustizia sociale e della partecipazione.<br \/>\nRende \u00e8 una citt\u00e0 che possiede cultura, grazie alla presenza dell&#8217;Universit\u00e0 della Calabria; produttivit\u00e0, grazie a due importanti aree industriali; storia e bellezza, grazie al suo straordinario centro storico. Ma \u00e8 anche una <strong>citt\u00e0 ferita da anni di cattiva amministrazione<\/strong>. Oggi, pi\u00f9 che mai, \u00e8 il momento di voltare pagina e iniziare a costruire quel futuro che ci \u00e8 stato negato&#8221;.<\/p>\n<p>&#8220;La nostra non \u00e8 una scelta di isolamento \u2013 come qualcuno ha voluto impropriamente descrivere evocando un Aventino \u2013 ma un atto di chiarezza politica. Scegliamo di rompere gli schemi che per oltre vent&#8217;anni hanno impedito alla citt\u00e0 di esprimere il proprio potenziale, imprigionandola in logiche di potere che nulla hanno a che fare con il bene comune. Il <strong>programma che accompagner\u00e0 la candidatura di Rossella Gallo \u00e8 incentrato su temi concreti e urgenti<\/strong>: trasparenza amministrativa, difesa dei diritti di tutti e tutte, consumo di suolo zero, verde pubblico e tutela ambientale, inclusione sociale reale. Intendiamo costruire un&#8217;amministrazione che ascolti, che pianifichi con visione e che agisca con coraggio. Un&#8217;amministrazione che metta al centro le persone, la dignit\u00e0 del lavoro, la qualit\u00e0 della vita. Il Movimento 5 Stelle si presenta a queste elezioni con una proposta credibile, pulita e radicalmente alternativa. Lo fa con l&#8217;entusiasmo di chi non ha nulla da difendere se non i valori in cui crede, e con la forza tranquilla di chi guarda al futuro con speranza, visione e determinazione&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; &#8220;Si chiude oggi una lunga fase di interlocuzione con le altre forze politiche, condotta con spirito costruttivo, responsabilit\u00e0 e apertura. Un percorso che, purtroppo, non ha prodotto gli esiti auspicati. A pesare sono state scelte personalistiche, rigidit\u00e0 e la proposta di candidature imposte, lontane dal metodo partecipativo e condiviso che avevamo auspicato. La [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":256169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-256168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/256168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=256168"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/256168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/256169"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=256168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=256168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=256168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}