{"id":256332,"date":"2025-04-11T20:14:24","date_gmt":"2025-04-11T18:14:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=256332"},"modified":"2025-04-11T20:14:24","modified_gmt":"2025-04-11T18:14:24","slug":"oliverio-chiede-audizione-in-commissione-ecomafie-il-paur-ultimo-baluardo-per-crotone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/oliverio-chiede-audizione-in-commissione-ecomafie-il-paur-ultimo-baluardo-per-crotone\/","title":{"rendered":"Oliverio chiede audizione in Commissione ecomafie: \u00abIl PAUR ultimo baluardo per Crotone\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; L&#8217;ex Presidente della Regione Calabria Mario Oliverio ha inoltrato richiesta di essere audito in Commissione parlamentare di inchiesta sulle ecomafie. Nelle scorse settimane la Commissione ha affrontato la problematica in merito alla <strong>Bonifica del sito industriale di Crotone.<\/strong> Durante l&#8217;ultima seduta \u00e8 stato audito il dg del Ministero dell&#8217;Ambiente, ing. Proietti.<\/p>\n<p>&#8220;Alla luce di quello che emerge da articoli di stampa &#8211; ha dichiarato Mario Oliverio &#8211; evinco che <strong>il presidente leghista della Commissione Bicamerale sulle ecomafie, ha chiesto pi\u00f9 volte chi fosse il presidente della Regione al tempo dell&#8217;adozione del Paur,<\/strong> <strong>l&#8217;ultimo baluardo di legalit\u00e0 in tema di difesa contro i veleni della bonifica dei rifiuti Eni a Crotone<\/strong>. Agevolo io il compito al presidente cos\u00ec &#8216;sensibile&#8217; alle sorti ambientali dei crotonesi alle prese con l&#8217;incubo Eni. Ho chiesto di essere audito dalla Commissione cos\u00ec conoscer\u00e0, non solo me di persona, ma &#8211; conclude Oliverio &#8211; le ragioni di ordine pubblico e di salvaguardia della salute dei cittadini che sono alla base del Paur, ultimo vincolo per impedire la catastrofe&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L&#8217;ex Presidente della Regione Calabria Mario Oliverio ha inoltrato richiesta di essere audito in Commissione parlamentare di inchiesta sulle ecomafie. Nelle scorse settimane la Commissione ha affrontato la problematica in merito alla Bonifica del sito industriale di Crotone. Durante l&#8217;ultima seduta \u00e8 stato audito il dg del Ministero dell&#8217;Ambiente, ing. Proietti. &#8220;Alla luce [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":155040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-256332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/256332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=256332"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/256332\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/155040"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=256332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=256332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=256332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}