{"id":257192,"date":"2025-04-25T16:00:31","date_gmt":"2025-04-25T14:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=257192"},"modified":"2025-04-25T13:50:33","modified_gmt":"2025-04-25T11:50:33","slug":"cosenza-ritmi-e-passioni-iberiche-il-duo-martina-biondi-e-pietro-locatto-al-teatro-rendano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-ritmi-e-passioni-iberiche-il-duo-martina-biondi-e-pietro-locatto-al-teatro-rendano\/","title":{"rendered":"Cosenza: ritmi e passioni iberiche, il duo Martina Biondi e Pietro Locatto al Teatro Rendano"},"content":{"rendered":"<p>COSENZA &#8211; L&#8217;Associazione Musicale Maurizio Quintieri, presenta il concerto del Duo Martina Biondi \u2013 Pietro Locatto, che si terr\u00e0 <strong>domani, sabato 26 aprile alle ore 19:00<\/strong> presso il prestigioso Teatro Alfonso Rendano di Cosenza. Questo evento rappresenta un&#8217;<strong>opportunit\u00e0 unica per immergersi nelle sonorit\u00e0 straordinarie della chitarra classica<\/strong>, con un repertorio interamente dedicato alla <strong>musica spagnola<\/strong>. La serata sar\u00e0 un viaggio attraverso le affascinanti atmosfere iberiche, con le opere di <strong>Alb\u00e9niz, Granados e de Falla,<\/strong> capaci di evocare colori, ritmi e passioni della tradizione musicale spagnola.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-257194 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Manifesto-26-Aprile-concerto.jpg\" alt=\"\" width=\"407\" height=\"252\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Manifesto-26-Aprile-concerto.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Manifesto-26-Aprile-concerto-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Manifesto-26-Aprile-concerto-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Manifesto-26-Aprile-concerto-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Manifesto-26-Aprile-concerto-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Manifesto-26-Aprile-concerto-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/Manifesto-26-Aprile-concerto-356x220.jpg 356w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/p>\n<h4>Martina Biondi<\/h4>\n<p>cosentina di nascita e di formazione, \u00e8 una delle violoncelliste italiane pi\u00f9 promettenti. Ha debuttato da solista a soli 17 anni e da allora \u00e8 stata protagonista di esibizioni in prestigiosi festival e teatri internazionali, tra cui la Berlin Philharmonie e Ravello Festival. Dopo un eccellente percorso accademico, si \u00e8 perfezionata con celebri maestri come Giovanni Sollima e Antonio Meneses. Vincitrice di numerosi premi internazionali, ha collaborato con grandi artisti ed \u00e8 stata ospite di trasmissioni televisive di rilievo.<\/p>\n<h4>Pietro Locatto<\/h4>\n<p>chitarrista raffinato e vincitore di prestigiosi concorsi internazionali, ha ricevuto borse di studio e riconoscimenti dall\u2019Accademia Musicale Chigiana di Siena e dall\u2019Associazione De Sono. Ha eseguito il Concierto de Aranjuez con l&#8217;Orchestra Toscanini di Parma ed \u00e8 stato invitato a festival in Europa, Australia e Messico. Particolarmente appassionato alla musica spagnola del \u2018900, ha inciso album dedicati a Torroba, Llobet, Asencio e Mompou.<br \/>\nIl Duo Evocaciones, che ha inciso un disco dedicato a questo repertorio, ha appena concluso una tourn\u00e8e in Giappone riscuotendo unanimi apprezzamenti di pubblico e di critica.<\/p>\n<p>Anche in questa speciale occasione, il pubblico e gli artisti condivideranno lo spazio del grande palcoscenico del Teatro Rendano, creando un\u2019atmosfera di intima connessione musicale e amplificando l\u2019emozione dell\u2019ascolto. Questa modalit\u00e0 innovativa di fruizione del concerto, che prevede la presenza di pubblico e musicisti sullo stesso palco, \u00e8 una novit\u00e0 introdotta nel 2025 dall&#8217;Associazione Musicale Maurizio Quintieri, pensata per rendere l\u2019esperienza ancora pi\u00f9 immersiva e coinvolgente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L&#8217;Associazione Musicale Maurizio Quintieri, presenta il concerto del Duo Martina Biondi \u2013 Pietro Locatto, che si terr\u00e0 domani, sabato 26 aprile alle ore 19:00 presso il prestigioso Teatro Alfonso Rendano di Cosenza. Questo evento rappresenta un&#8217;opportunit\u00e0 unica per immergersi nelle sonorit\u00e0 straordinarie della chitarra classica, con un repertorio interamente dedicato alla musica spagnola. [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":257193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-257192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/257192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=257192"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/257192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/257193"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=257192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=257192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=257192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}