{"id":257235,"date":"2025-04-23T11:40:30","date_gmt":"2025-04-23T09:40:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=257235"},"modified":"2025-04-23T12:44:08","modified_gmt":"2025-04-23T10:44:08","slug":"violento-incidente-stradale-due-feriti-trasportati-in-ospedale-in-eliambulanza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/violento-incidente-stradale-due-feriti-trasportati-in-ospedale-in-eliambulanza\/","title":{"rendered":"Violento incidente stradale, due feriti trasportati in ospedale in eliambulanza"},"content":{"rendered":"<p>CARFIZZI (KR) &#8211; Un incidente stradale ha visto coinvolte <strong>due autovetture<\/strong> sulla Strada Provinciale nel comune di <strong>Carfizzi<\/strong>, nel Crotonese. Sul posto \u00e8 intervenuta una squadra dei vigili fuoco che ha provveduto ad <strong>estrarre una persona ferita<\/strong>, rimasta incastrata <strong>all\u2019interno del veicolo<\/strong>. In totale sono due le persone ferite in modo grave che sono state affidate al personale sanitario del 118 per le cure del caso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-257240 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-04.jpg\" alt=\"\" width=\"475\" height=\"294\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-04.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-04-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-04-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-04-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-04-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-04-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-04-356x220.jpg 356w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><\/p>\n<p>Entrambi sono stati trasferiti in <strong>elisoccorso<\/strong> in ospedale. Il tratto della Provinciale interessato dal sinistro \u00e8 stato chiuso al transito in entrambi i sensi di marcia, sino al termine delle operazioni di soccorso. Sul posto anche i carabinieri cha hanno avviato gli accertamenti per stabilire la dinamica del sinistro. <strong>La Provinciale \u00e8 stata poi riaperta al traffico intorno alle 12.30.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-257239 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-03.jpg\" alt=\"\" width=\"512\" height=\"317\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-03.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-03-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-03-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-03-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-03-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-03-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-03-356x220.jpg 356w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-257238 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-02.jpg\" alt=\"\" width=\"507\" height=\"314\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/04\/incidente-auto-carfizzi-kr-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 507px) 100vw, 507px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CARFIZZI (KR) &#8211; Un incidente stradale ha visto coinvolte due autovetture sulla Strada Provinciale nel comune di Carfizzi, nel Crotonese. Sul posto \u00e8 intervenuta una squadra dei vigili fuoco che ha provveduto ad estrarre una persona ferita, rimasta incastrata all\u2019interno del veicolo. In totale sono due le persone ferite in modo grave che sono state [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":257237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-257235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/257235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=257235"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/257235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/257237"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=257235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=257235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=257235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}