{"id":257572,"date":"2025-05-01T15:00:50","date_gmt":"2025-05-01T13:00:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=257572"},"modified":"2025-05-01T13:57:50","modified_gmt":"2025-05-01T11:57:50","slug":"in-italia-e-povero-il-9-dei-lavoratori-full-time-difficolta-nellaffrontare-le-spese-minime-per-5-milioni-di-italiani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/in-italia-e-povero-il-9-dei-lavoratori-full-time-difficolta-nellaffrontare-le-spese-minime-per-5-milioni-di-italiani\/","title":{"rendered":"In Italia \u00e8 povero il 9% dei lavoratori full time, difficolt\u00e0 nell&#8217;affrontare le spese minime per 5 milioni di italiani"},"content":{"rendered":"<p>ROMA &#8211; Anche se si lavora a tempo pieno, il rischio di povert\u00e0 \u00e8 in crescita in Italia. Nel 2024 gli occupati con un reddito inferiore al 60% di quello medio nazionale al netto dei trasferimenti sociali sono il 9%, in aumento dall&#8217;8,7% registrato nel 2023. Una percentuale pi\u00f9 che doppia di quella della <strong>Germania<\/strong> (3,7%). \u00c8 quanto emerge dalle <strong>tabelle Eurostat<\/strong>\u00a0secondo le quali, invece, sono il 10,2% i lavoratori di <strong>almeno 18 anni<\/strong> occupati per almeno la met\u00e0 dell&#8217;anno (sia full time che part time) a rischio povert\u00e0, <strong>anche questi in aumento rispetto al 9,9% del 2023<\/strong>. In <strong>Spagna<\/strong> la percentuale dei lavoratori impegnati full time poveri \u00e8 del 9,6% mentre in Finlandia \u00e8 al 2,2%.<\/p>\n<h4>I dati sul part time<\/h4>\n<p>Per chi lavora part time la percentuale di chi risulta povero in Italia nel 2024 risulta in calo dal 16,9% al 15,7%. <strong>La povert\u00e0 lavorativa sale in Italia soprattutto per i lavoratori indipendenti,<\/strong> tra i quali il 17,2% ha redditi inferiori al 60% di quello mediano nazionale (era il 15,8% nel 2023) mentre per i dipendenti la quota sale all&#8217;8,4% dall&#8217;8,3% precedente. In Germania la quota degli occupati over 18 in una situazione di povert\u00e0 \u00e8 diminuita dal 6,6% al 6,5% mentre in Spagna \u00e8 diminuita dall&#8217;11,3% all&#8217;11,2%. Soffrono in <strong>Italia<\/strong> di questa condizione <strong>soprattutto i giovani<\/strong>: tra i <strong>16 e i 29 anni \u00e8 povero l&#8217;11,8% degli occupati<\/strong> mentre<strong> tra i 55 e i 64 anni \u00e8 il 9,3%.<\/strong><\/p>\n<h4>Il livello di istruzione<\/h4>\n<p>Nella povert\u00e0 lavorativa conta il <strong>livello di istruzione<\/strong>. Tra i lavoratori che hanno fatto la sola <strong>scuola dell&#8217;obbligo<\/strong> in Italia si registra un 18,2% di occupati poveri (era il 17,7% del 2023) mentre la <strong>percentuale crolla tra i lavoratori laureati<\/strong>, tra i quali solo il 4,5% risulta con un reddito inferiore al 60% di quello nazionale. Ma in questo caso si registra un importante aumento, visto che la percentuale era al 3,6% nel 2023. Si registra invece un lieve calo della povert\u00e0 tra gli occupati che hanno un diploma con il 9,1% in difficolt\u00e0 nel 2024 a fronte del 9,2% dell&#8217;anno precedente.<\/p>\n<h4>&#8220;Cinque milioni di italiani hanno difficolt\u00e0 sulle spese minime&#8221;<\/h4>\n<p>La <strong>deprivazione materiale in Italia nel 2024 \u00e8 scesa all&#8217;8,5%<\/strong> della popolazione dal 9,8% del 2023, al <strong>livello pi\u00f9 basso dall&#8217;inizio delle serie storiche nel 2015<\/strong>. Si tratta di circa cinque milioni di persone. L&#8217;indicatore si riferisce, spiega l&#8217;Eurostat, all&#8217;incapacit\u00e0 di permettersi una serie di beni, servizi o attivit\u00e0 sociali specifici che sono considerati dalla maggior parte delle persone essenziali per una qualit\u00e0 di vita adeguata. In pratica nel nostro paese ci sono circa cinque milioni di persone che non riescono ad affrontare cinque delle 13 spese contenute in questo indicatore quali avere una casa adeguatamente riscaldata, poter fare almeno una settimana di vacanza, far fronte a spese improvvise, poter fare un pasto con proteine almeno ogni due giorni, avere una connessione internet, avere almeno due paia di scarpe ecc. In Germania la deprivazione materiale riguarda l&#8217;11,4% della popolazione e in Spagna il 16%.<\/p>\n<p>La deprivazione materiale scende dall&#8217;8,4% al 7% per gli over 65 e diminuisce dall&#8217;11,1% al 10,5% tra gli under 18. Le persone in una situazione di deprivazione materiale &#8220;grave&#8221;, ovvero con difficolt\u00e0 su <strong>almeno sette spese su 13<\/strong>, sono circa 2,7 milioni, in calo al 4,6% della popolazione in Italia. La deprivazione materiale specifica per gli under 16 (poter mangiare quotidianamente proteine, verdure e frutta fresca, avere i libri, almeno due paia di scarpe, invitare amici ecc) \u00e8 in Italia all&#8217;11,7% con un calo rispetto al 13,5% del 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Anche se si lavora a tempo pieno, il rischio di povert\u00e0 \u00e8 in crescita in Italia. Nel 2024 gli occupati con un reddito inferiore al 60% di quello medio nazionale al netto dei trasferimenti sociali sono il 9%, in aumento dall&#8217;8,7% registrato nel 2023. Una percentuale pi\u00f9 che doppia di quella della Germania [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":257579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-257572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/257572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=257572"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/257572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/257579"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=257572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=257572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=257572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}