{"id":257887,"date":"2025-05-01T12:38:37","date_gmt":"2025-05-01T10:38:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=257887"},"modified":"2025-05-02T07:34:45","modified_gmt":"2025-05-02T05:34:45","slug":"tragedia-cosentino-auto-sbanda-e-finisce-contro-un-muro-muore-un-67enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tragedia-cosentino-auto-sbanda-e-finisce-contro-un-muro-muore-un-67enne\/","title":{"rendered":"Tragedia nel Cosentino, auto sbanda e finisce contro un muro. Muore un 67enne"},"content":{"rendered":"<p>MORMANNO (CS) &#8211; Un uomo di <strong>67 anni<\/strong>, originario del napoletano, ma <strong>residente a Scalea<\/strong> ha perso la vita sulla strada tra <strong>Campotenese e Mormanno, in contrada Campolongo<\/strong>. Il fatto \u00e8 accaduto ieri pomeriggio. Secondo quanto emerso l&#8217;uomo era alla guida di un&#8217;auto che, per cause in corso di accertamento, \u00e8<strong> sbandata finendo contro un muro<\/strong>. Il conducente sarebbe morto sul colpo. Sul posto sono giunti i vigili del fuoco di Castrovillari che hanno dovuto estrarre la vittima dalle lamiere e le forze dell&#8217;ordine per tentare di ricostruire quanto accaduto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MORMANNO (CS) &#8211; Un uomo di 67 anni, originario del napoletano, ma residente a Scalea ha perso la vita sulla strada tra Campotenese e Mormanno, in contrada Campolongo. Il fatto \u00e8 accaduto ieri pomeriggio. Secondo quanto emerso l&#8217;uomo era alla guida di un&#8217;auto che, per cause in corso di accertamento, \u00e8 sbandata finendo contro un [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":204271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-257887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/257887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=257887"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/257887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/204271"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=257887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=257887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=257887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}