{"id":258195,"date":"2025-05-06T10:22:05","date_gmt":"2025-05-06T08:22:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=258195"},"modified":"2025-05-06T10:30:18","modified_gmt":"2025-05-06T08:30:18","slug":"ventenne-ferito-a-colpi-di-pistola-ad-acri-un-arresto-per-tentato-omicidio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ventenne-ferito-a-colpi-di-pistola-ad-acri-un-arresto-per-tentato-omicidio\/","title":{"rendered":"Ventenne ferito a colpi di pistola ad Acri, un arresto per tentato omicidio"},"content":{"rendered":"<p>ACRI (CS) &#8211; I carabinieri di Rende hanno eseguito ieri, una misura cautelare in carcere emessa dal Giudice per le Indagini Preliminari presso il Tribunale di Cosenza, su richiesta della Procura di Cosenza, nei confronti di un <strong>soggetto residente ad Acri <\/strong>sulla base della ritenuta sussistenza dei gravi indizi in ordine al <a href=\"https:\/\/quicosenza.it\/news\/provincia\/acri-20enne-ferito-a-colpi-darma-da-fuoco-il-sindaco-chiede-lintervento-del-prefetto-di-cosenza\"><strong>tentato omicidio di un giovane ventenne<\/strong><\/a>, avvenuto nello stesso centro della provincia di Cosenza. I fatti risalgono alle prime ore del mattino del 22 dicembre del 2024.<\/p>\n<div style=\"width: 740px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-258195-1\" width=\"740\" height=\"419\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/05\/video-carabinieri.mp4?_=1\" \/><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/05\/video-carabinieri.mp4\">https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/05\/video-carabinieri.mp4<\/a><\/video><\/div>\n<p>Gli esiti investigativi, acquisiti a seguito delle accurate indagini svolte dai Carabinieri, hanno permesso di ricostruire la dinamica del fatto, nel senso che l\u2019autore, al culmine di un acceso <strong>diverbio con la vittima<\/strong>, esplodeva <strong>tre colpi di pistola all\u2019indirizzo della stessa<\/strong>, proprio nelle immediate vicinanze dell\u2019abitazione di quest\u2019ultima, cagionandogli importanti <strong>ferite d\u2019arma da fuoco ad una spalla e ad una gamba<\/strong>, e di individuare, sul piano della gravit\u00e0 indiziaria, l\u2019autore del grave fatto di sangue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACRI (CS) &#8211; I carabinieri di Rende hanno eseguito ieri, una misura cautelare in carcere emessa dal Giudice per le Indagini Preliminari presso il Tribunale di Cosenza, su richiesta della Procura di Cosenza, nei confronti di un soggetto residente ad Acri sulla base della ritenuta sussistenza dei gravi indizi in ordine al tentato omicidio di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":258201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19,135],"class_list":["post-258195","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-provincia","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/258195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=258195"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/258195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/258201"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=258195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=258195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=258195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}