{"id":258875,"date":"2025-05-12T20:00:42","date_gmt":"2025-05-12T18:00:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=258875"},"modified":"2025-05-12T19:09:31","modified_gmt":"2025-05-12T17:09:31","slug":"cellulari-a-scuola-valditara-propone-allue-il-divieto-in-classe-bisogna-intervenire","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cellulari-a-scuola-valditara-propone-allue-il-divieto-in-classe-bisogna-intervenire\/","title":{"rendered":"Cellulari a scuola, Valditara propone all&#8217;Ue il divieto in classe: \u00abBisogna intervenire\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Il Ministro dell&#8217;Istruzione e del Merito,<strong> Giuseppe Valditara<\/strong>, ha presentato oggi, nel corso della riunione del Consiglio dell&#8217;Unione europea dedicata all&#8217;Istruzione, <strong>la proposta per una raccomandazione europea che scoraggi l&#8217;uso degli smartphone in classe in tutte le scuole primarie e secondarie di primo grado dell&#8217;Unione<\/strong>.<\/p>\n<p>&#8220;I risultati degli studi scientifici dimostrano che l&#8217;abuso di dispositivi mobili durante l&#8217;infanzia e la preadolescenza incide negativamente sullo sviluppo cognitivo, causando perdita di concentrazione e memoria, riduzione delle competenze linguistiche e del pensiero critico. Oltre al <strong>calo delle performance scolastiche,<\/strong> l&#8217;uso eccessivo degli smartphone in et\u00e0 precoce \u00e8 riconosciuto come una delle principali cause di isolamento sociale. <strong>\u00c8 giunto il momento di intervenire<\/strong> con decisione per tutelare il benessere e l&#8217;apprendimento dei nostri giovani&#8221;, ha dichiarato il Ministro Valditara, aggiungendo: &#8220;Valuteremo se estendere il divieto anche alle superiori&#8221;. La proposta italiana si inserisce in un contesto europeo gi\u00e0 attivo su questo fronte, dove diversi Stati membri hanno adottato misure per limitare o vietare l&#8217;uso dei dispositivi mobili nelle scuole, in particolare per gli alunni pi\u00f9 piccoli.<\/p>\n<p>In Italia, il Ministero dell&#8217;Istruzione e del Merito ha gi\u00e0 avviato interventi concreti: &#8220;A partire da settembre 2024, \u00e8 stato disposto il divieto di utilizzo degli smartphone in classe per tutti gli alunni, dalla scuola dell&#8217;infanzia alla secondaria di primo grado. Rimane consentito l&#8217;uso dei dispositivi previsti nei piani didattici personalizzati per studenti con disabilit\u00e0 o disturbi specifici dell&#8217;apprendimento. Se vogliamo davvero bene ai nostri figli, dobbiamo garantirgli a scuola una pausa dai cellulari. Ora&#8221;, prosegue Valditara, &#8220;\u00e8 necessario un approccio coordinato a livello europeo anche sul tema dell&#8217;accesso ai social network per contrastare fenomeni come il cyberbullismo, la pedopornografia, gli atti di autolesionismo, e la violenza di genere&#8221;. La proposta italiana ha riscosso una ampia condivisione all&#8217;interno del Consiglio. Diversi Stati membri sono intervenuti per sostenere l&#8217;iniziativa italiana. Nessun intervento contrario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il Ministro dell&#8217;Istruzione e del Merito, Giuseppe Valditara, ha presentato oggi, nel corso della riunione del Consiglio dell&#8217;Unione europea dedicata all&#8217;Istruzione, la proposta per una raccomandazione europea che scoraggi l&#8217;uso degli smartphone in classe in tutte le scuole primarie e secondarie di primo grado dell&#8217;Unione. &#8220;I risultati degli studi scientifici dimostrano che l&#8217;abuso [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":258877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-258875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/258875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=258875"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/258875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/258877"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=258875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=258875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=258875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}