{"id":258882,"date":"2025-05-13T07:13:14","date_gmt":"2025-05-13T05:13:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=258882"},"modified":"2025-05-13T07:14:26","modified_gmt":"2025-05-13T05:14:26","slug":"scavano-e-inquinano-il-fiume-blitz-tra-crotone-e-cosenza-arrestati-in-flagrante-tre-operai","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/scavano-e-inquinano-il-fiume-blitz-tra-crotone-e-cosenza-arrestati-in-flagrante-tre-operai\/","title":{"rendered":"Scavano e inquinano il fiume, blitz tra Crotone e Cosenza: arrestati in flagrante tre operai"},"content":{"rendered":"<p>COSENZA &#8211; Continuano le attivit\u00e0 di controllo del territorio dei Carabinieri nell\u2019ambito della <strong>campagna \u201cFiume sicuro 2025\u201d,<\/strong> pianificata dal Comando Carabinieri per la Tutela Forestale e dei Parchi al fine di prevenire e reprimere gli illeciti ambientali. A tal riguardo, nei giorni scorsi, i Carabinieri del Nucleo Forestale di Cir\u00f2 hanno <strong>sorpreso tre persone mentre eseguivano lavori di estrazione abusiva<\/strong> con mezzi meccanici di materiale inerte dall\u2019alveo del fiume Nic\u00e0, tra le province di Crotone e Cosenza e precisamente a <strong>ridosso del confine tra i comuni di Crucoli (KR) e Terravecchia (CS).<\/strong><\/p>\n<p>I militari, durante l\u2019attivit\u00e0 di controllo, hanno notato la presenza di mezzi meccanici fermi sulla superficie golenale dell\u2019asta fluviale, dove erano evidenti i segni di un cantiere di movimento terra e, insospettiti, si sono appostati a distanza. L\u2019intuizione \u00e8 stata confermata poco dopo, quando sono giunte sul posto tre persone che, ignare di essere osservate, hanno ripreso ad eseguire i<strong>l prelievo di massa inerte<\/strong> con l\u2019ausilio dei veicoli a motore. Prontamente i militari sono intervenuti identificando i soggetti che, alla richiesta senza esito di esibire la necessaria documentazione autorizzatoria, sono stati tratti in arresto per<strong> furto aggravato in flagranza ai danni dello Stato,<\/strong> trattandosi di sottrazione abusiva di beni demaniali destinati alla pubblica utilit\u00e0, sotto le immediate direttive dalla Procura della Repubblica presso il Tribunale di Castrovillari.<\/p>\n<p>Dai controlli \u00e8 emerso inoltre che<strong> gli operai erano intenti a livellare la buca scavata, per una estensione e profondit\u00e0 di svariati metri<\/strong>, <strong>attraverso il reinterro di terre da scavo frammiste ad altri rifiuti provenienti da attivit\u00e0 di demolizione (quali laterizi e calcinacci, calcestruzzo, traversine ferroviarie, ecc.)<\/strong>. A seguito di tale attivit\u00e0 \u00e8 scattato anche il <strong>sequestro dei veicoli utilizzati<\/strong> per la commissione delle attivit\u00e0 illecite. Ne \u00e8 seguito il giudizio per direttissima per <strong>G.M., trentacinquenne di Crosia (CS), V.F., cinquantunenne, e A.G., cinquantottenne, entrambi di Cariati (CS),<\/strong> riconosciuti colpevoli e condannati alla reclusione per periodi tra i 6 e gli 8 mesi, con pena patteggiata e sospesa, oltre che all\u2019imposizione di una multa.<\/p>\n<p>Le ulteriori condotte contestate dai militari hanno portato al <strong>deferimento<\/strong> all\u2019Autorit\u00e0 Giudiziaria oltre che delle tre persone arrestate, anche del<strong> titolare della ditta crotonese<\/strong> di cui gli stessi risultano dipendenti, attivo nella gestione di un impianto di recupero inerti non lontano dalla zona dello scavo. Gli stessi dovranno difendersi anche dalle a<strong>ccuse di invasione di terreni demaniali<\/strong> in area vincolata, gestione illecita di rifiuti nell\u2019esercizio di attivit\u00e0 d\u2019impresa, <strong>deterioramento di beni paesaggistici,<\/strong> modifica dello stato dei luoghi ed ulteriori profili di responsabilit\u00e0 in campo ambientale in fase di verifica.<\/p>\n<h3><strong>La campagna \u201cFiume sicuro 2025\u201d <\/strong><\/h3>\n<p>La campagna denominata \u201cFiume sicuro 2025\u201d si inserisce nel programma di contrasto ai fenomeni di dissesto idrogeologico sul territorio italiano, caratterizzato da una tormentata orografia e da sedimenti geologicamente instabili che lo predispongono. La destabilizzazione delle condizioni naturali di molti torrenti e aste fluviali, dovuta spesso a condotte illecite, ha contribuito alla alterazione dei fenomeni naturali di erosione e sedimentazione collegati, che hanno portato negli ultimi anni alla perdita di ingenti risorse economiche nonch\u00e9, in occasione di eventi di maggiore intensit\u00e0, di numerose vite umane.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Continuano le attivit\u00e0 di controllo del territorio dei Carabinieri nell\u2019ambito della campagna \u201cFiume sicuro 2025\u201d, pianificata dal Comando Carabinieri per la Tutela Forestale e dei Parchi al fine di prevenire e reprimere gli illeciti ambientali. A tal riguardo, nei giorni scorsi, i Carabinieri del Nucleo Forestale di Cir\u00f2 hanno sorpreso tre persone mentre [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":258883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,28],"tags":[19],"class_list":["post-258882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/258882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=258882"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/258882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/258883"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=258882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=258882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=258882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}