{"id":259048,"date":"2025-05-14T19:19:24","date_gmt":"2025-05-14T17:19:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=259048"},"modified":"2025-05-14T19:19:24","modified_gmt":"2025-05-14T17:19:24","slug":"cosenza-su-via-popilia-chiude-il-centro-anziani-cipparrone-un-colpo-al-cuore-per-il-quartiere","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-su-via-popilia-chiude-il-centro-anziani-cipparrone-un-colpo-al-cuore-per-il-quartiere\/","title":{"rendered":"Cosenza, su via Popilia chiude il centro anziani. Cipparrone: \u00abUn colpo al cuore per il quartiere\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;So che a qualcuno dar\u00e0 fastidio parlare di tutto ci\u00f2 per\u00f2 da ex amministratore prima e da cittadino dopo duole il cuore sapere dai tantissimi amici assidui frequentatori del <strong>centro anziani di via Popilia<\/strong> della<strong> chiusura forzata del centro<\/strong>&#8220;. A scriverlo l&#8217;ex consigliere comunale di Cosenza <strong>Giovanni Cipparrone.<\/strong><\/p>\n<p>&#8220;Ora non sto qui a giudicare chi ha ragione oppure chi ha torto, io sono per far amministrare chi da sempre lo ha vissuto ed \u00e8 del luogo, proprio perch\u00e9 in citt\u00e0 ci sono vari centri nei vari quartieri e farlo gestire a chi ci abita a via Popilia non \u00e8 sbagliato.<br \/>\nEssere arrivati a tutto ci\u00f2 non fa onore a nessuno e sicuramente c\u2019\u00e8 chi gi\u00e0 si sta prodigando a risolvere tutto ci\u00f2, ecco perch\u00e9 <strong>invito a chi di competenza a far riaprire al pi\u00f9 presto quello che per tantissime persone \u00e8 un vero e proprio posto di sana aggregazione ludica.<\/strong><\/p>\n<p>Avevamo fatto un lavoro certosino con la commissione approvando un regolamento che disciplinava la fruizione del centro e le attivit\u00e0 che si dovevano svolgere l\u00ec dentro.<br \/>\nDa presidente di circoscrizione feci costruire una balera esterna, intitolata al giovane carabiniere Di Lauro, per far aggregare anche nel periodo estivo, quando il centro era chiuso, pi\u00f9 persone possibile, compito pi\u00f9 che riuscito visto che le serate danzanti estive ancora oggi sono ben frequentate, ci\u00f2 significa che la mia intuizione era pi\u00f9 che giusta.<br \/>\n<strong>Un mio augurio che il centro possa riaprire al pi\u00f9 presto possibile<\/strong> e che i tantissimi fruitori possono ritornare a trascorrere ore liete e serene nel posto che desiderano da sempre frequentare&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;So che a qualcuno dar\u00e0 fastidio parlare di tutto ci\u00f2 per\u00f2 da ex amministratore prima e da cittadino dopo duole il cuore sapere dai tantissimi amici assidui frequentatori del centro anziani di via Popilia della chiusura forzata del centro&#8220;. A scriverlo l&#8217;ex consigliere comunale di Cosenza Giovanni Cipparrone. &#8220;Ora non sto qui a [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":259049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-259048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=259048"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/259049"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=259048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=259048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=259048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}