{"id":259066,"date":"2025-05-15T08:55:50","date_gmt":"2025-05-15T06:55:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=259066"},"modified":"2025-05-15T08:55:38","modified_gmt":"2025-05-15T06:55:38","slug":"giovane-morto-a-villa-degli-oleandri-gli-infermieri-di-turno-e-la-terapia-telefonica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/giovane-morto-a-villa-degli-oleandri-gli-infermieri-di-turno-e-la-terapia-telefonica\/","title":{"rendered":"Giovane morto a Villa degli Oleandri, gli infermieri di turno e la terapia telefonica"},"content":{"rendered":"<p>PAOLA (CS) \u2013 Gianmatteo Broccolo \u00e8 morto a 36 anni nella clinica Villa degli Oleandri. Il suo decesso \u00e8 stato attribuito ad insufficienza neurologica e depressione respiratoria acuta da assunzione di psicofarmaci. Uno stato indotto dall\u2019assunzione di ossicodone e benzodiazepine. <a href=\"https:\/\/quicosenza.it\/news\/provincia\/villa-degli-oleandri-cosa-hanno-in-comune-le-morti-di-iaccino-e-broccolo-i-familiari-chiedono-giustizia\">Il 36enne cosentino<\/a> si era allontanato dalla struttura il<strong> 6 gennaio 2021<\/strong>. Qualche giorno dopo, la <strong>notte tra il 9 e il 10 gennaio<\/strong>, era stato riaccompagnato nella casa di cura in ambulanza da Cetraro, scortato dai carabinieri che lo avevano rintracciato sulla costa tirrenica cosentina e trasportato in ospedale. Ufficialmente <strong>il suo cuore ha cessato di battere a distanza di meno di 12 ore dal suo rientro.<\/strong> Sul suo letto \u00e8 stata trovata, \u00e8 scritto negli atti, una compressa di <em>\u00abcolore rosa\u00a0con scritto da un lato \u201cOC\u201d e dall\u2019altro \u201c20\u201d di cui si sconosce la tipologia del farmaco\u00bb.<\/em><\/p>\n<p><strong>La morte di Broccolo a Villa degli Oleandri<\/strong><\/p>\n<p>Il padre era nel cortile della clinica e chiedeva di salutarlo, di consegnargli il telefono e dei dolci alle 12:30, proprio nei minuti a cavallo della tragedia. Gli dissero per\u00f2 che suo figlio riposava. <strong>L\u2019autopsia ha segnalato la presenza nel suo stomaco di 5 pillole di ossicodone<\/strong> appena ingerite, in fase di iniziale assorbimento, ma anche macchie ematiche nelle narici, sanguinamenti gastrici e nel cervello, sparsi focolai emorragici, edema polmonare e celebrale. I farmaci che aveva in tasca invece non contenevano ossicodone. <strong>Per far chiarezza sulla morte di Gianmatteo Broccolo<\/strong>, oltre a un procedimento in corso presso il Tribunale di Cosenza, la Procura di Paola ha avviato indagini che hanno portato il <strong>dottor Emilio Ruggiero a processo. Internista, medico di base ad Amantea,<\/strong> \u00e8 accusato di omicidio colposo in quanto ritenuto responsabile di aver aiutato Broccolo nel procurarsi psicofarmaci e oppiacei nei giorni in cui era evaso da Villa degli Oleandri.<\/p>\n<h4><strong>Gli infermieri di turno <\/strong><\/h4>\n<p>Quale terapia sia stata somministrata a Broccolo tra il 9 e il 10 gennaio non \u00e8 stato del tutto chiarito da sanitari che lo hanno avuto in carico nelle ore tra l\u2019arrivo in clinica e la sua morte. L\u2019infermiere che era di turno quando \u00e8 stato dichiarato l\u2019avvenuto decesso di Gianmatteo Broccolo, \u00e8 stato ascoltato ieri nel corso del procedimento a carico di Ruggiero. Nell\u2019aula Beccaria del Tribunale di Paola, <strong>Mabruokj Mongi<\/strong> ha risposto alle domande della pm Maria Porcelli, innanzi al collegio giudicante presieduto da Salvatore Carpino con a latere i giudici Sara Cominato e Anna Iadicicco. L\u2019uomo ha reso dichiarazioni ritenute non conformi con quanto dichiarato nell\u2019immediatezza dei fatti ai carabinieri, quando rifer\u00ec di aver somministrato tutta la terapia al paziente (elencandola nei dettagli) il quale gli avrebbe anche chiesto un caff\u00e8. Ieri ha invece detto di ricordare che il ragazzo \u00aballe 7:00 quando sono arrivato \u2013 ha affermato in aula \u2013 non si era ancora svegliato. Ha dormito tutta la mattina, non ci ho mai parlato.<strong> Non gli ho dato nessun farmaco.<\/strong> Quando ho portato i dolci del padre ho visto che non rispondeva. Lo abbiamo provato a rianimare, poi \u00e8 stata chiamata la guardia medica e il 118. Nel giubbotto e nel pantalone farmaci abbiamo in seguito trovato delle medicine che noi non usiamo\u00bb.<\/p>\n<h4><strong>L\u2019arrivo in clinica dopo la fuga<\/strong><\/h4>\n<p>L\u2019infermiere di turno che ha invece accolto Broccolo quando \u00e8 rientrato, con un\u2019ambulanza da Cetraro scortato dai carabinieri, a Villa degli Oleandri ricorda di aver somministrato la terapia: 500 mg di Depachin, 300 mg di Seroquel, 30 gocce di Azepam, 35 gocce di Aldol e 10 gocce di Talofen. \u00ab<strong>Erano i farmaci che prendeva abitualmente<\/strong>, \u2013 ha spiegato Veltri \u2013 <strong>il dottor Crispino senza visitarlo mi ha detto per telefono di dargli la solita terapia.<\/strong> E cos\u00ec ho fatto, con l\u2019aiuto del 118 e dei carabinieri. Non ho controllato n\u00e9 la pressione n\u00e9 altri parametri n\u00e9 se avesse assunto altre medicine o se ne avesse con s\u00e9 perch\u00e9 pensavo fosse gi\u00e0 stato perquisito dai carabinieri\u00bb.<\/p>\n<p>L\u2019uomo \u00e8 stato quindi incalzato dal legale della difesa che ha sottolineato l\u2019illogicit\u00e0 di non avere controllato gli indumenti di un paziente ristretto in clinica per ordine di un giudice a causa di un\u2019inchiesta (Ricettopoli) che ruota sul consumo di psicofarmaci e oppiacei. \u00c8 stata inoltre sollevata la gravit\u00e0 dell\u2019aver fatto ingerire delle medicine particolarmente impattanti senza misurare neanche la pressione. <strong>\u00abHo fatto solo quello che ha detto il dottore Crispino\u00bb<\/strong> si \u00e8 giustificato l\u2019infermiere innanzi ai giudici. Intanto <strong>stanno per scadere i 90 giorni entro i quali dovrebbe essere consegnato l\u2019esito dell\u2019autopsia di <a href=\"https:\/\/quicosenza.it\/news\/provincia\/villa-degli-oleandri-cosa-hanno-in-comune-le-morti-di-iaccino-e-broccolo-i-familiari-chiedono-giustizia\">Salvatore Iaccino<\/a>,<\/strong> il 48enne morto lo scorso febbraio a Villa degli Oleandri in circostanze ancora da chiarire cui decesso ha portato all\u2019iscrizione nel registro degli indagati 1 medico, 2 operatori socio-sanitari e 1 infermiere.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAOLA (CS) \u2013 Gianmatteo Broccolo \u00e8 morto a 36 anni nella clinica Villa degli Oleandri. Il suo decesso \u00e8 stato attribuito ad insufficienza neurologica e depressione respiratoria acuta da assunzione di psicofarmaci. Uno stato indotto dall\u2019assunzione di ossicodone e benzodiazepine. Il 36enne cosentino si era allontanato dalla struttura il 6 gennaio 2021. Qualche giorno dopo, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":259067,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-259066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=259066"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/259067"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=259066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=259066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=259066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}