{"id":259319,"date":"2025-05-19T10:05:55","date_gmt":"2025-05-19T08:05:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=259319"},"modified":"2025-05-19T10:07:01","modified_gmt":"2025-05-19T08:07:01","slug":"referendum-dell8-e-9-giugno-sui-temi-del-lavoro-e-della-cittadinanza-incontro-pubblico-a-rende","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/referendum-dell8-e-9-giugno-sui-temi-del-lavoro-e-della-cittadinanza-incontro-pubblico-a-rende\/","title":{"rendered":"&#8220;Referendum dell&#8217;8 e 9 giugno sui temi del Lavoro e della Cittadinanza&#8221;, incontro pubblico a Rende"},"content":{"rendered":"<p>RENDE &#8211; Il circolo Auser di Rende organizza per domani, marted\u00ec 20 maggio alle ore 17:00, presso la sede in viale dei Giardini, un incontro pubblico sul tema \u201c<a href=\"https:\/\/quicosenza.it\/news\/calabria\/referendum-abrogativi-2025-ecco-tutte-le-schede-e-i-quesiti-per-il-voto-dell8-e-9-giugno\">Referendum dell&#8217;8 e 9 giugno<\/a> sui temi del Lavoro e della Cittadinanza\u201d. L&#8217;iniziativa nasce dal bisogno di difendere e implementare la democrazia <strong>contrastando l&#8217;astensionismo<\/strong> perch\u00e9 siamo certi che la democrazia si difende praticandola.<\/p>\n<p>&#8220;I <strong>quesiti referendari<\/strong> &#8211; sottolinea l&#8217;Auser di Rende &#8211; pongono all&#8217;attenzione dell&#8217;elettorato questioni che riguardano le attuali condizioni del lavoro &#8220;povero&#8221;, quello di migliaia di lavoratori, soprattutto giovani, ai quali non viene garantito un lavoro tutelato, dignitoso, stabile e sicuro&#8221;.<\/p>\n<p>&#8220;Dire s\u00ec a ciascuno di questi quesiti serve a:<\/p>\n<p>&#8211; contrastare il licenziamenti senza giusta causa;<br \/>\n&#8211; rimuovere i limiti al risarcimento per ingiusta causa;<br \/>\n&#8211; limitare l&#8217;uso dei contratti a termine;<br \/>\n&#8211; rendere le ditte appaltatrici responsabili degli infortuni sul lavoro&#8221;.<\/p>\n<p>&#8220;Infine il quinto referendum per consentire ai migranti che hanno scelto di vivere e lavorare in Italia di poter accedere alla cittadinanza dopo cinque anni e non dieci di permanenza nei nostri territori. Il circolo <strong>Auser di Rende che promuove, tra l&#8217;altro, la cittadinanza attiva e consapevole degli anziani e dei pensionati<\/strong>, invita tutti quelli che hanno a cuore il futuro del nostro Paese di andare a votare per raggiungere il quorum. Votare S\u00ec \u00e8 un atto di generosit\u00e0, di responsabilit\u00e0, di realismo politico nei confronti delle nuove generazioni, dei nostri figli, dei nostri nipoti, esposti, quanto mai prima, all&#8217;insicurezza e all&#8217;instabilit\u00e0&#8221;.<\/p>\n<p>Di tutto questo parleranno: <strong>Elena Hoo<\/strong> (Presidente Auser Rende), <strong>Franco D&#8217;Orrico<\/strong> (Sindacato Pensionati CGIL Cosenza), <strong>Daniel Greco<\/strong> (SLC CGIL Cosenza), <strong>Simone Celebre<\/strong> (FILLEA CGIL Cosenza) e <strong>Veronica Moyolema Tiban<\/strong>, cittadina equadoregna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Il circolo Auser di Rende organizza per domani, marted\u00ec 20 maggio alle ore 17:00, presso la sede in viale dei Giardini, un incontro pubblico sul tema \u201cReferendum dell&#8217;8 e 9 giugno sui temi del Lavoro e della Cittadinanza\u201d. L&#8217;iniziativa nasce dal bisogno di difendere e implementare la democrazia contrastando l&#8217;astensionismo perch\u00e9 siamo certi [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":259323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-259319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=259319"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/259323"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=259319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=259319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=259319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}