{"id":259372,"date":"2025-05-19T16:17:37","date_gmt":"2025-05-19T14:17:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=259372"},"modified":"2025-05-19T16:17:37","modified_gmt":"2025-05-19T14:17:37","slug":"strade-invase-dal-verde-spadafora-chiede-interventi-urgenti-per-le-frazioni-di-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/strade-invase-dal-verde-spadafora-chiede-interventi-urgenti-per-le-frazioni-di-cosenza\/","title":{"rendered":"\u00abStrade invase dal verde\u00bb, Spadafora chiede interventi urgenti per le frazioni di Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Il consigliere comunale Francesco Spadafora, da sempre attento alle problematiche che affliggono le frazioni della citt\u00e0 e non solo, con spirito costruttivo e senza polemica alcuna, si rivolge all\u2019amministrazione comunale in carica affinch\u00e9 possano essere celermente avviati<strong> interventi specifici e mirati per eliminare la vegetazione infestante come erbacce, rovi, arbusti e cespugli, insistenti ai margini delle strade<\/strong> che collegano le zone pi\u00f9 decentrate alla citt\u00e0&#8221;. Lo dichiara in una nota <strong>Francesco Spadafora<\/strong>, Consigliere Comunale &#8211; Presidente Gruppo \u201cFDI\u201d.<\/p>\n<p>\u201cL\u2019attivit\u00e0 di manutenzione che dovr\u00e0 essere messa in atto al pi\u00f9 presto possibile si rende particolarmente necessaria per garantire la<strong> sicurezza stradale e il decoro delle nostre bellissime frazioni,<\/strong> che non sempre, purtroppo, godono di un\u2019adeguata attenzione da parte di coloro che oggi si ritrovano ad amministrare l\u2019ente comunale\u201d.<\/p>\n<p>\u201cL\u2019obiettivo che mi spinge a rivolgermi pubblicamente all\u2019amministrazione comunale non ha lo scopo della polemica pretestuosa, che poco interessa ai cittadini, ma bens\u00ec quello di sollecitare chi di competenza perch\u00e9 sia messo in atto un piano di intervento mirato, preceduto da una attenta e scrupolosa programmazione, al fine di minimizzare i disagi alla circolazione stradale e diminuire i pericoli alle persone che con l\u2019approssimarsi delle belle giornate e della stagione estiva passeggiano lungo la maggior parte delle strade che insistono nelle frazioni\u201d.<\/p>\n<p>\u201cPer queste ragioni, nella qualit\u00e0 di consigliere comunale, <strong>presenter\u00f2 ufficiale richiesta d\u2019intervento al sindaco, Franz Caruso<\/strong>, e all\u2019ufficio competente per rendere le strade sicure e ben curate, chiedendo priorit\u00e0 per i tratti stradali maggiormente trafficati e soprattutto che le operazioni riguardino ogni singola strada e area della citt\u00e0\u201d, dichiara il consigliere bruzio Francesco Spadafora.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Il consigliere comunale Francesco Spadafora, da sempre attento alle problematiche che affliggono le frazioni della citt\u00e0 e non solo, con spirito costruttivo e senza polemica alcuna, si rivolge all\u2019amministrazione comunale in carica affinch\u00e9 possano essere celermente avviati interventi specifici e mirati per eliminare la vegetazione infestante come erbacce, rovi, arbusti e cespugli, insistenti [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":259373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-259372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=259372"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/259373"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=259372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=259372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=259372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}