{"id":259430,"date":"2025-05-20T15:00:30","date_gmt":"2025-05-20T13:00:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=259430"},"modified":"2025-05-20T14:26:33","modified_gmt":"2025-05-20T12:26:33","slug":"non-era-caduto-ma-pestato-brutalmente-da-un-conoscente-armato-di-accetta-arrestato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/non-era-caduto-ma-pestato-brutalmente-da-un-conoscente-armato-di-accetta-arrestato\/","title":{"rendered":"Non era caduto, ma pestato brutalmente da un conoscente armato di accetta: arrestato"},"content":{"rendered":"<p>SERRA SAN BRUNO (VV) &#8211; I carabinieri di Serra San Bruno hanno dato esecuzione ad un\u2019ordinanza di <strong>custodia cautelare in carcere<\/strong>, emessa dalla Procura della Repubblica di Vibo Valentia, guidata dal Procuratore Camillo Falvo, nei confronti di un<strong> uomo ritenuto responsabile di un violento episodio di tentato omicidio<\/strong>.<\/p>\n<p>Le indagini dei militari hanno consentito di far luce su un <strong>grave episodio di cronaca avvenuto il 5 gennaio 2024 <\/strong>quando, i carabinieri, erano intervenuti presso la guardia medica di Soriano Calabro dove si era presentato un uomo ferito e in gravi condizioni che<strong> aveva riportato un evidente trauma cranico<\/strong>. In un primo momento le lesioni erano state ricondotte a <strong>una caduta accidentale<\/strong>. Tuttavia, <strong>gi\u00e0 durante le prime concitate fasi dell\u2019intervento, il personale sanitario era stato aggredito dagli accompagnatori del ferito<\/strong>, che si erano poi allontanati rapidamente per dirigersi verso l\u2019ospedale di Vibo Valentia.<\/p>\n<h3>Gravi ferite e il ricovero al Pugliese-Ciaccio<\/h3>\n<p>Una volta giunto al nosocomio vibonese,<strong> i medici avevano riscontrato un quadro clinico ben pi\u00f9 complesso e grave<\/strong>: la vittima presentava un trauma cranico con frattura scomposta dell\u2019osso frontale, ferite da taglio al torace, la frattura della clavicola e segni evidenti di un politrauma. <strong>La situazione era talmente grave da richiedere un trasferimento d\u2019urgenza all\u2019ospedale \u201cPugliese\u201d di Catanzaro<\/strong>, dove l\u2019uomo era rimasto ricoverato in prognosi riservata fino al 16 gennaio. Subito dopo l\u2019accaduto i carabinieri avevano avviato un\u2019articolata attivit\u00e0 investigativa sotto il coordinamento del sostituto procuratore titolare del fascicolo.<\/p>\n<h3>Aggressione per futili motivi legati a dissidi personali<\/h3>\n<p>Gli approfondimenti hanno portato alla luce la realt\u00e0 dei fatti:<strong> le prime dichiarazioni rese dalla vittima non corrispondevano alla verit\u00e0<\/strong>. Gli inquirenti hanno infatti accertato che l\u2019uomo non era caduto, ma era stato brutalmente aggredito a Soriano Calabro da un conoscente, armato di accetta. <strong>Alla base dell\u2019aggressione vi sarebbero stati futili motivi legati a dissidi personali<\/strong>. L\u2019operazione condotta dai Carabinieri conferma ancora una volta l\u2019efficacia del lavoro congiunto tra le forze dell\u2019ordine e la Procura della Repubblica di Vibo Valentia, impegnate con determinazione nella lotta ai reati contro la persona e nella tutela dell\u2019ordine pubblico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SERRA SAN BRUNO (VV) &#8211; I carabinieri di Serra San Bruno hanno dato esecuzione ad un\u2019ordinanza di custodia cautelare in carcere, emessa dalla Procura della Repubblica di Vibo Valentia, guidata dal Procuratore Camillo Falvo, nei confronti di un uomo ritenuto responsabile di un violento episodio di tentato omicidio. Le indagini dei militari hanno consentito di [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":259432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-259430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=259430"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/259432"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=259430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=259430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=259430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}