{"id":259834,"date":"2025-05-24T15:40:34","date_gmt":"2025-05-24T13:40:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=259834"},"modified":"2026-01-07T13:02:56","modified_gmt":"2026-01-07T12:02:56","slug":"litigano-per-un-parcheggio-condominiale-e-accoltella-il-vicino-di-casa-arrestato-un-21enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/litigano-per-un-parcheggio-condominiale-e-accoltella-il-vicino-di-casa-arrestato-un-21enne\/","title":{"rendered":"Litigano per un parcheggio condominiale e accoltella il vicino di casa: arrestato un 21enne"},"content":{"rendered":"<p>LAMEZIA TERME (CZ) &#8211; Un giovane h<strong>a accoltellato un vicino di casa al culmine di una lite condominiale per futili motivi di vicinato connessi ad un parcheggio<\/strong>. Con l\u2019accusa di tentato omicidio <strong>un 21enne \u00e8 stato arrestato dai carabinieri<\/strong> della Compagnia di Lamezia Terme per tentato omicidio. <strong>La vittima, un 26enne, si trova adesso ricoverato in prognosi riservata nell&#8217;ospedale lametino per due profonde ferite alla schiena<\/strong>.<\/p>\n<h3>La violenta lite e l&#8217;accoltellamento<\/h3>\n<p>I fatti risalgono alla serata del 22 maggio scorso. I militari del Nucleo operativo e radiomobile e della Stazione di Lamezia Terme Sambiase sono intervenuti <strong>in un condominio per una violenta lite tra residenti segnalata al 112 NUE<\/strong>. Le indagini, secondo l&#8217;accusa, hanno permesso di individuare in pochissimo tempo il responsabile dell&#8217;aggressione, ricostruendo la dinamica dei fatti.<\/p>\n<h3>Due fendenti alla schiena di un 26enne con un coltello da cucina<\/h3>\n<p>Il 21enne <strong>avrebbe sferrato due fendenti alla schiena della vittima utilizzando un coltello da cucina<\/strong> c<strong>on lama di 25 centimetri<\/strong> che \u00e8 stata trovata nell&#8217;immediatezza e sequestrata per gli accertamenti. Gli investigatori hanno anche <strong>acquisito e analizzato i filmati degli impianti videosorveglianza<\/strong> presenti nella zona e ascoltato alcuni testimoni, che hanno consentito di identificare subito l&#8217;autore che si \u00e8 costituito poco dopo nella caserma dei carabinieri di Sambiase. Stamani il gup di Lamezia Terme<strong> ha convalidato l&#8217;arresto e disposto la traduzione in carcere<\/strong> dell&#8217;indagato su richiesta della Procura della Repubblica che coordina le indagini.<\/p>\n<p>Questa mattina, il gip ha convalidato l\u2019arresto ma <strong>ha disposto i domiciliari con braccialetto elettronico<\/strong>. Il giovane, difeso dall\u2019avvocato Domenico Villella, ha risposto alle domande del gip e spiegato le sue motivazioni e si \u00e8 mostrato collaborativo indicato subito l\u2019arma utilizzata e fornendola ai fornita ai Carabinieri. Il 26enne ferito si trova ricoverato in prognosi riservata a Catanzaro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA TERME (CZ) &#8211; Un giovane ha accoltellato un vicino di casa al culmine di una lite condominiale per futili motivi di vicinato connessi ad un parcheggio. Con l\u2019accusa di tentato omicidio un 21enne \u00e8 stato arrestato dai carabinieri della Compagnia di Lamezia Terme per tentato omicidio. La vittima, un 26enne, si trova adesso ricoverato [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":172044,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-259834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=259834"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/172044"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=259834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=259834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=259834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}