{"id":259942,"date":"2025-05-26T13:58:21","date_gmt":"2025-05-26T11:58:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=259942"},"modified":"2025-05-26T14:55:30","modified_gmt":"2025-05-26T12:55:30","slug":"schede-e-timbro-spariti-a-scalea-erano-in-possesso-della-presidente-del-seggio-interrogata-dai-carabinieri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/schede-e-timbro-spariti-a-scalea-erano-in-possesso-della-presidente-del-seggio-interrogata-dai-carabinieri\/","title":{"rendered":"Schede e timbro spariti a Scalea: erano in possesso della presidente del seggio. Interrogata dai carabinieri"},"content":{"rendered":"<p>SCALEA (CS) &#8211; Le <strong><a href=\"https:\/\/quicosenza.it\/news\/provincia\/rende-denunciato-per-aver-fotografato-la-scheda-a-scalea-schede-e-timbro-scomparsi-poi-ritrovati\" target=\"_blank\" rel=\"noopener\">due schede elettorali ed un timbro spariti <\/a>sabato sera dal seggio numero 7 a Scalea (Cosenza)<\/strong> e poi ritrovati<strong> erano in possesso della presidente del seggio stesso<\/strong> che poi ha proseguito regolarmente nel suo ruolo. <strong>La vicenda, su cui stanno indagando i carabinieri, potrebbe avere adesso ripercussioni sull&#8217;esito del voto<\/strong>. La lista Scalea Oltre ha reso noto di aver informato della vicenda la Prefettura di Cosenza, il commissario prefettizio di Scalea e la Corte d&#8217;appello di Catanzaro.<\/p>\n<p>In qualit\u00e0 di candidato a sindaco &#8211; ha sostenuto <strong>Giacomo Perrotta,<\/strong> capolista di Scalea Oltre e sindaco uscente sfiduciato a pochi mesi dalla conclusione del mandato &#8211; prima dell&#8217;inizio dello spoglio, chieder\u00f2 ai presidenti dei seggi di verificare durante le operazioni di assegnazione dei voti ogni timbro presente su ogni singola scheda e di verbalizzare eventuali anomalie&#8221;. Non risultano, invece, segnalazioni alle autorit\u00e0 da parte degli altri candidati sindaci e delle loro liste.<\/p>\n<p><strong>Mario Russo<\/strong>, gi\u00e0 in passato pi\u00f9 volte primo cittadino di Scalea, e capolista di Scalea Rinasce ha sostenuto che non c&#8217;\u00e8 nulla da segnalare alle autorit\u00e0. &#8220;Sulla vicenda sono stati <strong>avviati accertamenti da parte delle forze dell&#8217;ordine<\/strong> e la presidente del seggio \u00e8 stata lasciata al suo posto, cosa che non sarebbe successa se fossero state riscontrate irregolarit\u00e0&#8221; ha aggiunto.<\/p>\n<p>&#8220;Segnalare non servirebbe a nulla&#8221; ha detto <strong>Angelo Paravati,<\/strong> candidato sindaco per Scalea Futura, aggiungendo: &#8220;Se si \u00e8 lasciata al proprio posto la persona che avrebbe commesso questo gesto e se le autorit\u00e0 preposte a vigilare dicono che va bene cos\u00ec, resta bene poco da fare&#8221;. <strong>Gennaro Licursi<\/strong>, capolista di Uniti per Scalea, infine, ha affermato che &#8220;appena saputo dell&#8217;accaduto mi sono messo in contatto con il comandante dei carabinieri il quale mi ha rassicurato che erano e sono in corso le indagini&#8221;.<\/p>\n<h4>Interrogata la presidente di seggio<\/h4>\n<p>La presidente del seggio dove sono state segnalate irregolarit\u00e0, si \u00e8 allontanata dal seggio ed \u00e8 stata <strong>accompagnata dai carabinieri fino alla locale Stazione dell&#8217;Arma<\/strong>. L&#8217;episodio \u00e8 avvenuto <strong>intorno alle ore 13.00,<\/strong> mentre erano in corso le votazioni. I carabinieri stanno indagando dopo che la presidente era stata trovata in possesso di due schede e di un timbro nel seggio, ospitato in un edificio delle scuole materne cittadine.<br \/>\nDa quanto si \u00e8 appreso, si tratta di un&#8217;attivit\u00e0 svolta dall&#8217;Arma nell&#8217;ambito delle indagini su quanto avvenuto nelle scorse ore nel seggio,<strong> al termine delle quali la donna torner\u00e0 al suo posto.\u00a0\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SCALEA (CS) &#8211; Le due schede elettorali ed un timbro spariti sabato sera dal seggio numero 7 a Scalea (Cosenza) e poi ritrovati erano in possesso della presidente del seggio stesso che poi ha proseguito regolarmente nel suo ruolo. La vicenda, su cui stanno indagando i carabinieri, potrebbe avere adesso ripercussioni sull&#8217;esito del voto. La [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":259943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-259942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=259942"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/259942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/259943"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=259942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=259942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=259942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}