{"id":26011,"date":"2013-09-18T05:56:45","date_gmt":"2013-09-18T03:56:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26011"},"modified":"2023-01-17T13:23:33","modified_gmt":"2023-01-17T12:23:33","slug":"10638-minaccia-di-lanciarsi-da-un-viadotto-dell-a3-all-altezza-di-altilia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10638-minaccia-di-lanciarsi-da-un-viadotto-dell-a3-all-altezza-di-altilia\/","title":{"rendered":"Minaccia di lanciarsi da un viadotto dell&#8217;A3 all&#8217;altezza di Altilia"},"content":{"rendered":"<p>COSENZA &#8211; Meditava l&#8217;estremo gesto dal momento in cui aveva imboccato l&#8217;autostrada, a Salerno.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Un quarantenne campano \u00e8 stato bloccato sull&#8217;A3 mentre affacciato al parapetto di un cavalcavia minacciava di lanciarsi nel vuoto. L&#8217;uomo pare abbia fermato l&#8217;auto sulla quale viaggiava parcheggiando al lato della carreggiata nel tratto di strada che divide Rogliano da Altilia. Da l\u00ec si sarebbe avvicinato al cavalcavia fissando il vuoto, quei cinquanta metri che lo separavano dalla morte. E l\u00ec \u00e8 rimasto per circa due ore, dalle 17 alle 19. Due ore nel corso delle quali gli agenti della Questura, il personale dell&#8217;Anas, i sanitari del 118 e i vigili del fuoco hanno implorato l&#8217;uomo per evitare il peggio. Il quarantenne alla fine di una lunga trattativa ha desistito dai propri intenti omicidi e si \u00e8 consegnato alle forze dell&#8217;ordine. Ad intervenire nel confronto con il campano anche uno psichiatra che viaggiava sull&#8217;autostrada il quale ha prestato soccorso inducendo l&#8217;uomo a scendere dalla balaustra. L&#8217;uomo \u00e8 stato immediatamente trasportato presso l&#8217;ospedale dell&#8217;Annunziata per le cure del caso.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Meditava l&#8217;estremo gesto dal momento in cui aveva imboccato l&#8217;autostrada, a Salerno.<\/p>\n","protected":false},"author":22,"featured_media":26012,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-26011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26011"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26012"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}