{"id":26037,"date":"2013-09-19T06:28:18","date_gmt":"2013-09-19T04:28:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26037"},"modified":"2023-01-17T13:23:35","modified_gmt":"2023-01-17T12:23:35","slug":"10651-invasioni-stasera-bregovic-infuoca-i-due-fiumi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10651-invasioni-stasera-bregovic-infuoca-i-due-fiumi\/","title":{"rendered":"Invasioni, stasera Bregovic infuoca i &#8216;due fiumi&#8217;"},"content":{"rendered":"<p>COSENZA &#8211; In Piazza XV Marzo, il concerto di punta della manifestazione.<\/p>\n<p>  <!--more-->  <\/p>\n<div class=\"campoOggetto128\" style=\"text-align: justify;\">E\u2019 senz\u2019altro l\u2019evento di punta di tutta la Festa delle Invasioni ed \u00e8 per questo che la sua vigilia \u00e8 carica di attese. Ma lo \u00e8 anche per un altro motivo, perch\u00e9 il grande musicista e compositore bosniaco <strong>Goran Bregovic manca da Cosenza da dieci anni, dalla notte di San Silvestro del 31 dicembre 2003, quando a Piazza dei Bruzi tenne un memorabile concerto per salutare l\u2019arrivo del 2004. Alla testa della sua supercollaudata \u201cWedding and the Funeral Band\u201d, Bregovic porter\u00e0 oggi, gioved\u00ec 19 settembre, alle ore 22,00, in Piazza XV Marzo<\/strong>, il suo fortunato tour, dal titolo \u201cChampagne for Gypsies\u201d, diretta filiazione del suo disco pi\u00f9 recente, pubblicato nell\u2019autunno del 2012. L\u2019originalit\u00e0 di Champagne for Gypsies \u00e8 costituita dalle numerosissime collaborazioni tra Goran Bregovic ed altri noti musicisti internazionali gitani. Il disco, come il tour, nasce dal desiderio del compositore balcanico di invitare i pi\u00f9 importanti rappresentanti musicali di etnia gitana dopo gli scandali e le sommosse nelle comunit\u00e0 gitane nell\u2019Europa occidentale negli anni scorsi. Tra le tante collaborazioni, il duetto con il famosissimo ensemble musicale zingaro The Gipsy Kings, che ha costituito il singolo di lancio dell\u2019album, dal titolo \u201cBalkaneros\u201d. Nel concerto di Piazza XV marzo a Cosenza per la Festa delle Invasioni, Bregovic sar\u00e0 affiancato da una band gitana di fiati composta da Muharem Red\u017eepi-Goc (grancassa tradizionale e voce), Bokan Stankovic (prima tromba), Dalibor Lukic (seconda tromba), Stojan Dimov (sax e clarinetto), Aleksandar Rajkovic (primo trombone e glockenspiel) e Milos Mihajlovic (secondo trombone). Sul palco di Piazza XV Marzo anche due voci bulgare, quelle di Ludmila Radkova Trajkova e Daniela Radkova Aleksandrova. <strong>La musica di \u201cChampagne for Gypsies\u201d, trasposta dal disco al tour di Goran Bregovic, nata dalla reazione alle violenze contro i gitani che avvengono in Europa e dalla voglia di mostrare la bellezza della loro musica,<\/strong> \u00e8, per ammissione dello stesso Bregovic, concepita \u201cper ballare e divertirsi nel filo della mia musica onesta, fuori dagli stereotipi e dalla pressioni dell\u2019industria discografica\u201d. Dagli esordi nei club di Sarajevo, dove il rock era di casa, alla fuga in Francia, Goran Bregovic ha mescolato, nelle sue composizioni (famose le colonne sonore scritte per i film di Emir Kusturica, dal \u201cTempo dei gitani\u201d ad \u201cUnderground\u201d, ad \u201cArizona Dream\u201d, che gli sono valse il passaporto per sfondare in Europa) il folk balcanico con la raffinata tecnologia. Lo spettacolo dei suoi concerti non nasce da effetti speciali, ma dai musicisti presenti sul palco, siano essi quelli dell\u2019austera Orchestra di Belgrado, sia la &#8220;Wedding &amp; Funerals Band&#8221;, la fanfara di ottoni che aggiorna la tradizione dei complessi ottomani e rom, siano, ora, i componenti della band gitana di fiati che lo accompagneranno a Cosenza. Intanto, anche per il concerto di Goran Bregovic <strong>l\u2019Amaco ha predisposto un servizio navetta con partenza da Piazza Europa ed arrivo ai Tredici canali e viceversa ogni 25 minuti a partire dalle 20:25 sino alle 02:00<\/strong>.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; In Piazza XV Marzo, il concerto di punta della manifestazione.<\/p>\n","protected":false},"author":22,"featured_media":26038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-26037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26037"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26038"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}